{"id":62451,"date":"2025-10-30T11:08:31","date_gmt":"2025-10-30T16:08:31","guid":{"rendered":"https:\/\/nazarene.org\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/"},"modified":"2025-10-31T13:37:01","modified_gmt":"2025-10-31T18:37:01","slug":"conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/","title":{"rendered":"Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mais de 700 nazarenos se reuniram para a AME.25, a Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul em Cali, na Col\u00f4mbia, de 22 a 24 de outubro. A confer\u00eancia regional reuniu pastores, l\u00edderes e leigos das regi\u00f5es Am\u00e9rica do Sul, Mesoam\u00e9rica e EUA\/Canad\u00e1 sob o tema: &#8220;Amar, Ministrar e Evangelizar como Jesus&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organizada pela Regi\u00e3o Am\u00e9rica do Sul e sediada pela Igreja do Nazareno Casa de Ora\u00e7\u00e3o em Cali, a confer\u00eancia mission\u00e1ria quadrienal da regi\u00e3o foi apoiada por mais de 100 volunt\u00e1rios que serviram com excel\u00eancia, hospitalidade e alegria, tornando cada momento uma experi\u00eancia inesquec\u00edvel de comunh\u00e3o e adora\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tr\u00eas temas principais nortearam a confer\u00eancia: amar como Jesus, ministrar como Jesus e evangelizar como Jesus. Os organizadores programaram momentos de adora\u00e7\u00e3o, ensino e comunh\u00e3o para renovar a vis\u00e3o e o compromisso da igreja em refletir Cristo na vida e no minist\u00e9rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os Superintendentes Gerais <a href=\"https:\/\/nazarene.org\/pt-br\/profiles\/dr-carla-d-sunberg\/\">Carla Sunberg<\/a> e <a href=\"https:\/\/nazarene.org\/pt-br\/profiles\/dr-t-scott-daniels\/\">Scott Daniels<\/a>, juntamente com o diretor regional e outros pastores s\u00eaniores e l\u00edderes de minist\u00e9rio, lideraram os principais serm\u00f5es. Entre os distintos facilitadores e palestrantes do workshop estavam Jim Ritchie, diretor de Miss\u00f5es Globais, e Sam Barber, diretor global de Discipulado Nazareno Internacional<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo dos tr\u00eas dias, centenas de pastores e l\u00edderes vieram ao altar, respondendo com compromisso e dedica\u00e7\u00e3o ao chamado de Deus para suas vidas. Um esp\u00edrito de adora\u00e7\u00e3o, renova\u00e7\u00e3o espiritual e unidade entre as na\u00e7\u00f5es preencheu o encontro, inaugurando uma nova era para a Am\u00e9rica do Sul. O evento marcou o in\u00edcio de um avivamento que sem d\u00favida moldar\u00e1 os pr\u00f3ximos anos, sob o tema &#8220;Seja como Jesus&#8221;. Este tema guiar\u00e1 a Meta 2030, que busca alcan\u00e7ar 500.000 nazarenos na Am\u00e9rica do Sul, estabelecer 3.600 congrega\u00e7\u00f5es ativas e garantir que 100% das igrejas participem de doa\u00e7\u00f5es ao Fundo Mundial de Evangeliza\u00e7\u00e3o (FEM).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A noite final foi transmitida ao vivo em toda a Am\u00e9rica do Sul, atraindo centenas de pessoas para a celebra\u00e7\u00e3o. Em sua mensagem de encerramento, Carla Sunberg citou Phineas F. Bresee, fundador da Igreja do Nazareno, encorajando todas as igrejas, pastores e l\u00edderes a serem uma chama sagrada em todos os cantos do continente, levando o amor e a esperan\u00e7a de Cristo para todas as pessoas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AME.25 A Confer\u00eancia Regional impactou profundamente a vida da Igreja do Nazareno na Am\u00e9rica do Sul, lembrando a todos que o chamado permanece o mesmo: amar, servir e evangelizar como Jesus, at\u00e9 que o poder do evangelho transforme toda a regi\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<a href=\"https:\/\/www.samnaz.org\/ame-25-marca-un-nuevo-tiempo-para-la-iglesia-del-nazareno-en-america-del-sur\/\">Igreja do Nazareno Regi\u00e3o Am\u00e9rica do Sul<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais de 700 nazarenos se reuniram para a AME.25, a Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul em Cali, na Col\u00f4mbia, de 22 a 24 de outubro. A confer\u00eancia regional reuniu pastores, l\u00edderes e leigos das regi\u00f5es Am\u00e9rica do Sul, Mesoam\u00e9rica e EUA\/Canad\u00e1 sob o tema: &#8220;Amar, Ministrar e Evangelizar como Jesus&#8221;. Organizada pela Regi\u00e3o Am\u00e9rica [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":62452,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[2881],"news-tag":[],"class_list":["post-62451","news","type-news","status-publish","has-post-thumbnail","hentry","news-region-taxonomy-america-do-sul"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus - Church of the Nazarene<\/title>\n<meta name=\"description\" content=\"Mais de 700 nazarenos se reuniram para a AME.25, a Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul em Cali, na Col\u00f4mbia, de 22 a 24 de outubro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus\" \/>\n<meta property=\"og:description\" content=\"Mais de 700 nazarenos se reuniram para a AME.25, a Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul em Cali, na Col\u00f4mbia, de 22 a 24 de outubro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T18:37:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/AME-25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\\\/\",\"name\":\"Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AME-25.jpg\",\"datePublished\":\"2025-10-30T16:08:31+00:00\",\"dateModified\":\"2025-10-31T18:37:01+00:00\",\"description\":\"Mais de 700 nazarenos se reuniram para a AME.25, a Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul em Cali, na Col\u00f4mbia, de 22 a 24 de outubro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AME-25.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/AME-25.jpg\",\"width\":1500,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus - Church of the Nazarene","description":"Mais de 700 nazarenos se reuniram para a AME.25, a Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul em Cali, na Col\u00f4mbia, de 22 a 24 de outubro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/","og_locale":"pt_BR","og_type":"article","og_title":"Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus","og_description":"Mais de 700 nazarenos se reuniram para a AME.25, a Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul em Cali, na Col\u00f4mbia, de 22 a 24 de outubro.","og_url":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","article_modified_time":"2025-10-31T18:37:01+00:00","og_image":[{"width":1500,"height":800,"url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/AME-25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/","url":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/","name":"Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/AME-25.jpg","datePublished":"2025-10-30T16:08:31+00:00","dateModified":"2025-10-31T18:37:01+00:00","description":"Mais de 700 nazarenos se reuniram para a AME.25, a Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul em Cali, na Col\u00f4mbia, de 22 a 24 de outubro.","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/AME-25.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/AME-25.jpg","width":1500,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/conferencia-da-regiao-america-do-sul-inspira-nazarenos-a-refletir-jesus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"Confer\u00eancia da Regi\u00e3o Am\u00e9rica do Sul inspira nazarenos a refletir Jesus"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/62451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":3,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/62451\/revisions"}],"predecessor-version":[{"id":62477,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/62451\/revisions\/62477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media\/62452"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=62451"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=62451"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=62451"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=62451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}