{"id":62278,"date":"2025-10-23T14:30:03","date_gmt":"2025-10-23T19:30:03","guid":{"rendered":"https:\/\/nazarene.org\/news\/bandeiras-das-nacoes-taiwan\/"},"modified":"2025-10-27T11:14:59","modified_gmt":"2025-10-27T16:14:59","slug":"bandeiras-das-nacoes-taiwan","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/","title":{"rendered":"Bandeiras das Na\u00e7\u00f5es: Taiwan"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Desde 1\u00ba de setembro de 2009, o Centro Global de Minist\u00e9rio (CGM) da Igreja do Nazareno orgulhosamente hasteia todas as semanas a bandeira de uma das muitas na\u00e7\u00f5es em que a denomina\u00e7\u00e3o est\u00e1 presente ministerialmente. Os l\u00edderes foram convidados a enviar uma bandeira nacional para ser hasteada no CGM ao lado da bandeira dos Estados Unidos*. As bandeiras nacionais s\u00e3o trocadas semanalmente, e as fotos delas hasteadas s\u00e3o enviadas aos l\u00edderes da igreja daquele pa\u00eds.  <\/p>\n\n<p class=\"wp-block-paragraph\">Essa semana:<strong> Taiwan<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">A Igreja do Nazareno entrou oficialmente em Taiwan em 1956.<\/p>\n\n<p class=\"wp-block-paragraph\">Taiwan tinha uma popula\u00e7\u00e3o de 23.595.274 habitantes em 2024. Nesse mesmo ano, Taiwan reportou 46 Igrejas do Nazareno, 43 das quais tinham sido oficialmente organizadas. Taiwan tem um total de 2.952 membros.  <\/p>\n\n<p class=\"wp-block-paragraph\">Taiwan tem um distrito Fase 3. Faz parte da <a href=\"http:\/\/www.asiapacificnazarene.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Regi\u00e3o \u00c1sia-Pac\u00edfico.<\/a> <\/p>\n\n<p class=\"wp-block-paragraph\"><em>* = A bandeira em destaque da semana \u00e9 hasteada no meio dos tr\u00eas mastros, em conformidade com os protocolos do governo dos EUA. Ela \u00e9 hasteada \u00e0 esquerda da bandeira dos Estados Unidos, pa\u00eds anfitri\u00e3o do CGM, que \u00e9 hasteada acima da bandeira do estado anfitri\u00e3o, Kansas. A bandeira crist\u00e3 \u00e9 hasteada no terceiro mastro.  <\/em><\/p>\n\n<p class=\"wp-block-paragraph\"><em>O <a href=\"https:\/\/nazarene.org\/pt-br\/centro-de-ministerio-global\/\">Centro Global de Minist\u00e9rio<\/a> \u00e9 o centro de miss\u00e3o e servi\u00e7o da Igreja do Nazareno.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde 1\u00ba de setembro de 2009, o Centro Global de Minist\u00e9rio (CGM) da Igreja do Nazareno orgulhosamente hasteia todas as semanas a bandeira de uma das muitas na\u00e7\u00f5es em que a denomina\u00e7\u00e3o est\u00e1 presente ministerialmente. Os l\u00edderes foram convidados a enviar uma bandeira nacional para ser hasteada no CGM ao lado da bandeira dos Estados [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":62277,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[2879],"news-tag":[1385,2234],"class_list":["post-62278","news","type-news","status-publish","has-post-thumbnail","hentry","news-region-taxonomy-asia-pacifico","news-tag-bandeiras","news-tag-taiwan-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bandeiras das Na\u00e7\u00f5es: Taiwan - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bandeiras das Na\u00e7\u00f5es: Taiwan\" \/>\n<meta property=\"og:description\" content=\"Desde 1\u00ba de setembro de 2009, o Centro Global de Minist\u00e9rio (CGM) da Igreja do Nazareno orgulhosamente hasteia todas as semanas a bandeira de uma das muitas na\u00e7\u00f5es em que a denomina\u00e7\u00e3o est\u00e1 presente ministerialmente. Os l\u00edderes foram convidados a enviar uma bandeira nacional para ser hasteada no CGM ao lado da bandeira dos Estados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T16:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/Taiwan.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/bandeiras-das-nacoes-taiwan\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/bandeiras-das-nacoes-taiwan\\\/\",\"name\":\"Bandeiras das Na\u00e7\u00f5es: Taiwan - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/bandeiras-das-nacoes-taiwan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/bandeiras-das-nacoes-taiwan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Taiwan.jpg\",\"datePublished\":\"2025-10-23T19:30:03+00:00\",\"dateModified\":\"2025-10-27T16:14:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/bandeiras-das-nacoes-taiwan\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/bandeiras-das-nacoes-taiwan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/bandeiras-das-nacoes-taiwan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Taiwan.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Taiwan.jpg\",\"width\":1500,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/bandeiras-das-nacoes-taiwan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bandeiras das Na\u00e7\u00f5es: Taiwan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bandeiras das Na\u00e7\u00f5es: Taiwan - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/","og_locale":"pt_BR","og_type":"article","og_title":"Bandeiras das Na\u00e7\u00f5es: Taiwan","og_description":"Desde 1\u00ba de setembro de 2009, o Centro Global de Minist\u00e9rio (CGM) da Igreja do Nazareno orgulhosamente hasteia todas as semanas a bandeira de uma das muitas na\u00e7\u00f5es em que a denomina\u00e7\u00e3o est\u00e1 presente ministerialmente. Os l\u00edderes foram convidados a enviar uma bandeira nacional para ser hasteada no CGM ao lado da bandeira dos Estados [&hellip;]","og_url":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","article_modified_time":"2025-10-27T16:14:59+00:00","og_image":[{"width":1500,"height":800,"url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/Taiwan.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/","url":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/","name":"Bandeiras das Na\u00e7\u00f5es: Taiwan - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/Taiwan.jpg","datePublished":"2025-10-23T19:30:03+00:00","dateModified":"2025-10-27T16:14:59+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/Taiwan.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/10\/Taiwan.jpg","width":1500,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/bandeiras-das-nacoes-taiwan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"Bandeiras das Na\u00e7\u00f5es: Taiwan"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/62278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":3,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/62278\/revisions"}],"predecessor-version":[{"id":62281,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/62278\/revisions\/62281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media\/62277"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=62278"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=62278"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=62278"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=62278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}