{"id":55097,"date":"2020-06-05T00:00:00","date_gmt":"2020-06-05T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/"},"modified":"2020-06-05T00:00:00","modified_gmt":"2020-06-05T05:00:00","slug":"distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/","title":{"rendered":"Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas"},"content":{"rendered":"<p>O Distrito de Vanuatu enviou recentemente sua primeira equipe para a ilha norte de Espiritu Santo para come\u00e7ar a estabelecer a presen\u00e7a do Nazareno l\u00e1.&nbsp;<\/p>\n<p>A equipe participou de um servi\u00e7o de comissionamento em meados de maio. Durante o servi\u00e7o, uma pastora testemunhou que ela estava orando por muitos anos que Deus ajudaria a trazer a mensagem de santidade para sua fam\u00edlia em Santo.&nbsp;<\/p>\n<p>Deus respondeu minhas ora\u00e7\u00f5es&#8221;, ela disse.&nbsp;<\/p>\n<p>Quando a equipe chegou na primeira aldeia, eles come\u00e7aram a ganhar a confian\u00e7a dos residentes distribuindo peixes, roupas, placas, copos e colheres. Eles tamb\u00e9m distribu\u00edram B\u00edblias e livros para as crian\u00e7as. O chefe da aldeia aceitou seus presentes, dando sua b\u00ean\u00e7\u00e3o para a equipe para evangelizar em toda a aldeia.&nbsp;<\/p>\n<p>Cada noite, a equipe realizou um servi\u00e7o de adora\u00e7\u00e3o. Em 23 de maio, 21 pessoas aceitaram Cristo como seu Senhor e Salvador. Na noite seguinte, a equipe realizou um grande servi\u00e7o de adora\u00e7\u00e3o onde outras 15 pessoas comprometeram suas vidas a Cristo.<\/p>\n<p>Esta tem sido nossas ora\u00e7\u00f5es por um longo tempo, para trazer a Igreja do Nazareno para as ilhas do norte, e Deus est\u00e1 respondendo nossa ora\u00e7\u00e3o&#8221;, disse Peter.<\/p>\n<p>Um novo crente ofereceu sua propriedade como um local para um abrigo de igreja. Mais tarde, um segundo homem pediu \u00e0 equipe para construir o abrigo no centro da aldeia. A equipe estava feliz em mudar locais e construiu a estrutura com a ajuda de v\u00e1rios homens da aldeia.<\/p>\n<p>Duas outras equipes tamb\u00e9m foram comissionadas no servi\u00e7o como parte do projeto do distrito para alcan\u00e7ar novas \u00e1reas. A segunda equipe viajar\u00e1 para duas outras ilhas do norte, Malekula e Ambrym, e a terceira equipe seguir\u00e1.&nbsp;<\/p>\n<p><em>Nome retido por raz\u00f5es de seguran\u00e7a<\/em><\/p>\n<p><a href=\"asiapacificnazarene.org\" target=\"_blank\">Igreja do Nazareno \u00c1sia-Pac\u00edfico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Distrito de Vanuatu enviou recentemente sua primeira equipe para a ilha norte de Espiritu Santo para come\u00e7ar a estabelecer a presen\u00e7a do Nazareno l\u00e1. Como resultado, quase 40 pessoas aceitaram Cristo.<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[926,1541],"class_list":["post-55097","news","type-news","status-publish","hentry","news-tag-asia-pacifico-pt-br","news-tag-vanuatu-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas\" \/>\n<meta property=\"og:description\" content=\"O Distrito de Vanuatu enviou recentemente sua primeira equipe para a ilha norte de Espiritu Santo para come\u00e7ar a estabelecer a presen\u00e7a do Nazareno l\u00e1. Como resultado, quase 40 pessoas aceitaram Cristo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\\\/\",\"name\":\"Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"datePublished\":\"2020-06-05T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/","og_locale":"pt_BR","og_type":"article","og_title":"Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas","og_description":"O Distrito de Vanuatu enviou recentemente sua primeira equipe para a ilha norte de Espiritu Santo para come\u00e7ar a estabelecer a presen\u00e7a do Nazareno l\u00e1. Como resultado, quase 40 pessoas aceitaram Cristo.","og_url":"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/","url":"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/","name":"Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"datePublished":"2020-06-05T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-de-vanuatu-comeca-trabalho-em-ilhas-nao-alcancadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"Distrito de Vanuatu come\u00e7a trabalho em ilhas n\u00e3o alcan\u00e7adas"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/55097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/55097\/revisions"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=55097"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=55097"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=55097"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=55097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}