{"id":54872,"date":"2019-11-14T00:00:00","date_gmt":"2019-11-14T06:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/"},"modified":"2019-11-14T00:00:00","modified_gmt":"2019-11-14T06:00:00","slug":"primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/","title":{"rendered":"Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/www.nazarene.orghttps:\/\/nazarene.org\/wp-content\/uploads\/NCN%20News\/USACanada\/Massachusetts\/ECHS.png\" width=\"750\"><\/p>\n<p>A primeira <a href=\"https:\/\/sites.google.com\/northst.org\/holinesssummit\/home\" target=\"_blank\">C\u00fapula de Santidade da Costa Leste<\/a> foi realizada 1 de junho na Segunda Igreja Dorchester do Nazareno em Boston, Massachusetts, onde a Superintendente Geral Carla Sunberg e o Superintendente do Distrito de Nova York Sam Vassall eram os palestrantes plen\u00e1rios.<\/p>\n<p>A miss\u00e3o da c\u00fapula era discutir que santidade tem a dizer sobre como o povo de Deus entra, interage e falar sobre quest\u00f5es de Palavra-se com carne.<\/p>\n<p>O evento foi organizado pelo L\u00edder Dorchester Segunda Igreja Pastor Victor Price com a ajuda de um comit\u00ea de dire\u00e7\u00e3o composto de v\u00e1rios l\u00edderes Nazarenos do distrito de Nova Inglaterra e Metro de Nova York, incluindo Robert Benjamin, Cliff Hersey, Eustace MacDonald, Kyung Lyul Yu, Jeremy Scott e Mat Thomas.<\/p>\n<p>A C\u00fapula de Santidade come\u00e7ou com Sunberg falando sobre &#8220;Santidade no Contexto da Igreja&#8221;, e oficinas seguiram no final da manh\u00e3 e in\u00edcio da tarde.<\/p>\n<p>L\u00edderes de oficina envolveram participantes em t\u00f3picos como imigra\u00e7\u00e3o, harmonia racial, justi\u00e7a restaurativa e sexualidade humana da estrutura do compromisso de santidade do Nazareno.<\/p>\n<p>Sam Vassall fechou a c\u00fapula falando sobre &#8220;Santidade no Contexto de Comunidade&#8221;.<\/p>\n<p>O evento foi bem recebido, e o comit\u00ea de dire\u00e7\u00e3o planeja continuar organizando discuss\u00f5es similares de quest\u00e3o \u00fanica em andamento em todo o resto do ano. Eles tamb\u00e9m est\u00e3o discutindo como reestruturar esta c\u00fapula em particular como um evento anual ou bianual.<\/p>\n<p><a href=\"https:\/\/www.nednaz.com\/\" target=\"_blank\">Nova Inglaterra District<\/a>&nbsp;via <a href=\"mailto:news@nazarene.org?subject=NCN%20News%20submissions\">NCN News envios<\/a><\/p>\n<p><em>Hist\u00f3rias para compartilhar? Envie um e-mail para <a href=\"mailto:news@nazarene.org\">news@nazarene.org<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/www.nazarene.org\/sites\/default\/files\/NCN%20News\/USACanada\/Mas&lt;\/div&gt;\"><\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[762,2208],"class_list":["post-54872","news","type-news","status-publish","hentry","news-tag-eua-canada","news-tag-massachusetts-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nazarene.orghttps:\/\/nazarene.org\/wp-content\/uploads\/NCN%20News\/USACanada\/Massachusetts\/ECHS.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\\\/\",\"name\":\"Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nazarene.orghttps:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/NCN%20News\\\/USACanada\\\/Massachusetts\\\/ECHS.png\",\"datePublished\":\"2019-11-14T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nazarene.orghttps:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/NCN%20News\\\/USACanada\\\/Massachusetts\\\/ECHS.png\",\"contentUrl\":\"https:\\\/\\\/www.nazarene.orghttps:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/NCN%20News\\\/USACanada\\\/Massachusetts\\\/ECHS.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/","og_locale":"pt_BR","og_type":"article","og_title":"Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts","og_url":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","og_image":[{"url":"https:\/\/www.nazarene.orghttps:\/\/nazarene.org\/wp-content\/uploads\/NCN%20News\/USACanada\/Massachusetts\/ECHS.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/","url":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/","name":"Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nazarene.orghttps:\/\/nazarene.org\/wp-content\/uploads\/NCN%20News\/USACanada\/Massachusetts\/ECHS.png","datePublished":"2019-11-14T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/#primaryimage","url":"https:\/\/www.nazarene.orghttps:\/\/nazarene.org\/wp-content\/uploads\/NCN%20News\/USACanada\/Massachusetts\/ECHS.png","contentUrl":"https:\/\/www.nazarene.orghttps:\/\/nazarene.org\/wp-content\/uploads\/NCN%20News\/USACanada\/Massachusetts\/ECHS.png"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/primeira-cupula-de-santidade-da-costa-leste-realizada-em-massachusetts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"Primeira C\u00fapula de Santidade da Costa Leste realizada em Massachusetts"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/54872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/54872\/revisions"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=54872"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=54872"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=54872"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=54872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}