{"id":54311,"date":"2019-07-10T00:00:00","date_gmt":"2019-07-10T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/"},"modified":"2019-07-10T00:00:00","modified_gmt":"2019-07-10T05:00:00","slug":"distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/","title":{"rendered":"Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Nicaragua\/NicaraguaFood.jpg\" width=\"750\"><\/p>\n<p>O Distrito Central da Nicar\u00e1gua doou suprimentos para mais de 125 fam\u00edlias em Ventarron e Monte Fresco, Nicar\u00e1gua, que est\u00e3o experimentando escassez de alimentos. Superintendente de Distrito Maria Antonia Ponce e outros volunt\u00e1rios entregaram a comida e roupas &nbsp;20 de junho.<\/p>\n<p>Bloqueios <a href=\"http:\/\/www.nazarene.org\/article\/nicaragua-district-office-closes-amid-nearby-protests\" target=\"_blank\">causados por protestos<\/a> atrav\u00e9s do pa\u00eds est\u00e3o impedindo deliver&nbsp;i v\u00e1rias comunidades no pa\u00eds, levando \u00e0s atuais escassez de alimentos.<\/p>\n<p>Durante a entrega, o caminh\u00e3o que eles estavam usando, mas Ponce disse que eles eram capazes de encontrar outro motorista de caminh\u00e3o que estava disposto a levar a equipe para seu destino.<\/p>\n<p>A entrega era uma \u00f3tima exibi\u00e7\u00e3o de trabalho em equipe [na qual] as pessoas participaram de muitas maneiras diferentes&#8221;, disse Ponce. Alguns alimentos doados, outros dividiram as doa\u00e7\u00f5es em pacotes, e outros entregaram as doa\u00e7\u00f5es. Queremos expressar nossa profunda gratid\u00e3o para todas as igrejas que organizaram e realizaram campanhas de comida, e somos gratos por nossos Minist\u00e9rios Nazarenos Compassivos regionais por sua amizade e ajuda nesses tempos dif\u00edceis para todos n\u00f3s.<\/p>\n<p>Embora a Nicar\u00e1gua esteja experimentando situa\u00e7\u00f5es sociais e econ\u00f4micas dif\u00edceis, Ponce e o resto do distrito continuam a estender a m\u00e3o para suas comunidades.<\/p>\n<p>Vendo a alegria nas crian\u00e7as e o amor dos pais faz tudo a pena&#8221;, disse Ponce.<\/p>\n<p>Ora\u00e7\u00e3o cont\u00ednua \u00e9 solicitada para Nicar\u00e1gua.&nbsp;<\/p>\n<p><a href=\"http:\/\/www.mesoamericaregion.org\/en\/\">Igreja do Nazareno Mesoam\u00e9rica<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" alt=\"\" height=\"400\" src=\"\/sites\/default\/files\/migrated_images\/NCN%20News\/Mesoamerica\/Nicaragua&lt;\/div&gt;\"><\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[1389,1752],"class_list":["post-54311","news","type-news","status-publish","hentry","news-tag-mesoamerica-pt-br","news-tag-nicaragua-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Nicaragua\/NicaraguaFood.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\\\/\",\"name\":\"Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Mesoamerica\\\/Nicaragua\\\/NicaraguaFood.jpg\",\"datePublished\":\"2019-07-10T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Mesoamerica\\\/Nicaragua\\\/NicaraguaFood.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Mesoamerica\\\/Nicaragua\\\/NicaraguaFood.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade","og_url":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","og_image":[{"url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Nicaragua\/NicaraguaFood.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/","url":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/","name":"Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Nicaragua\/NicaraguaFood.jpg","datePublished":"2019-07-10T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Nicaragua\/NicaraguaFood.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Nicaragua\/NicaraguaFood.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/distrito-central-da-nicaragua-doa-comida-para-comunidades-em-necessidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"Distrito Central da Nicar\u00e1gua doa comida para comunidades em necessidade"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/54311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/54311\/revisions"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=54311"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=54311"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=54311"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=54311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}