{"id":52585,"date":"2019-07-10T00:00:00","date_gmt":"2019-07-10T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/"},"modified":"2019-07-10T00:00:00","modified_gmt":"2019-07-10T05:00:00","slug":"igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/","title":{"rendered":"Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville"},"content":{"rendered":"<div style=\"text-align:center\">\n<figure class=\"image\" style=\"display:inline-block\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"600\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/USACanada\/Virginia\/CullenSouthsideNazarene.jpg\" width=\"1125\"><figcaption>Tenente H. Jay Cullen<\/figcaption><\/figure>\n<\/div>\n<p>Nazareno Pastor Wynne Lankford acredita que sua igreja n\u00e3o \u00e9 apenas um lugar de adora\u00e7\u00e3o, mas tamb\u00e9m um centro para a comunidade.<\/p>\n<p>As portas da <a href=\"http:\/\/southsidechurchva.org\/\" target=\"_blank\">Igreja Southside do Nazareno<\/a> est\u00e3o abertas para uma variedade de eventos comunit\u00e1rios, muitas vezes incluindo servi\u00e7os memoriais para primeiros socorristas que exigem um grande local. No s\u00e1bado 19 de agosto, Southside novamente sediar\u00e1 um servi\u00e7o memorial, desta vez para Trooper do Estado de Virg\u00ednia H. Jay Cullen.<\/p>\n<p>Cullen, 48, e colega Trooper Berke Bates, 40, foram mortos 12 de agosto quando o helic\u00f3ptero que eles estavam pilotando caiu no Condado de Albermarle nas proximidades. Os dois membros da Pol\u00edcia Estadual de Virg\u00ednia estavam ajudando com seguran\u00e7a p\u00fablica do ar durante o altamente controverso rali &#8220;Unir o Direito&#8221; em Charlottesville.<\/p>\n<p>Heather Heyer, 32, tamb\u00e9m foi morto e 19 outros feridos depois que um homem de Ohio dirigiu em um grupo de manifestantes com seu ve\u00edculo durante o rali, que ocorreu um pouco mais de uma hora de dist\u00e2ncia da Igreja Southside.<\/p>\n<p>Cullen, que era o comandante da Unidade de Avia\u00e7\u00e3o de Pol\u00edcia Estadual, viveu no Condado de Chesterfield com sua esposa, Karen, e dois filhos. Sua fam\u00edlia participa de uma igreja Metodista Unida local, mas uma instala\u00e7\u00e3o maior era necess\u00e1ria para seu servi\u00e7o memorial e Igreja Southside do Nazareno \u00e9 uma das maiores instala\u00e7\u00f5es na \u00e1rea.<\/p>\n<p>Pastor Lankford, que serve como um dos capel\u00e3es do Departamento de Pol\u00edcia do Condado de Chesterfield, ofereceu sua igreja.<\/p>\n<p>O edif\u00edcio normalmente assenta cerca de 1.000 no audit\u00f3rio, mas com assentos de transbordamento pode acomodar 1.400-1.500 pessoas. Espera-se que os amigos de Cullen, fam\u00edlia, apoiadores, l\u00edderes estaduais e comunit\u00e1rios, e representantes de departamentos de pol\u00edcia em todo os EUA estejam em participa\u00e7\u00e3o. A pol\u00edcia estadual est\u00e1 trabalhando com Southside em log\u00edstica para o servi\u00e7o.<\/p>\n<div style=\"text-align:center\">\n<figure class=\"image\" style=\"display:inline-block\"><img decoding=\"async\" alt=\"\" height=\"280\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/USACanada\/Virginia\/516e06862010f.image.jpg\" width=\"760\"><figcaption>Igreja Southside do Nazareno (foto Times-Dispatch)<\/figcaption><\/figure>\n<\/div>\n<p>Estamos abrindo nossas portas e nossa equipe est\u00e1 se tornando a equipe estendida da Pol\u00edcia Estadual de Virg\u00ednia&#8221;, disse Lankford. Nosso cora\u00e7\u00e3o aqui \u00e9 ser um centro comunit\u00e1rio e abrir nossas portas para a comunidade. Qualquer oportunidade que temos, abriremos nossas portas &#8211; amplamente abertas. Podemos permitir que as pessoas venham e ministrem para eles e se importe com eles. Estamos aqui para servir a comunidade local.<\/p>\n<p>Southside Nazarenos ajudar\u00e3o no s\u00e1bado com assentos de transbordamento, estacionamento estendido e fluxo de estacionamento, bem como fornecer transporte para e da igreja, participantes de cumprimento, guich\u00ea e mais.<\/p>\n<p>Lankford disse que ele disse a sua congrega\u00e7\u00e3o que se eles tinham um relacionamento com a fam\u00edlia Cullen para vir para o servi\u00e7o. Se eles n\u00e3o conheciam a fam\u00edlia, &#8220;venha e servir&#8221;. Outros s\u00e3o incentivados a apoiar a fam\u00edlia e comunidade assistindo <a href=\"http:\/\/southside.churchonline.org\/\" target=\"_blank\">ao servi\u00e7o on-line<\/a> (fluxo abre em 9:45 AM EST, com servi\u00e7o funer\u00e1rio come\u00e7ando em 10).<\/p>\n<p>Lankford chamou a morte de Tenente Cullen uma &#8220;perda significativa para a fam\u00edlia de pol\u00edcia e para o condado &#8211; ele \u00e9 parte desta comunidade&#8221;.<\/p>\n<p>Como Virginianos tentam se recuperar da viol\u00eancia de Charlottesville, Lankford disse que o sentimento em sua parte de Virg\u00ednia \u00e9 &#8220;tenso&#8221; com uma &#8220;divis\u00e3o racial&#8221;.<\/p>\n<p>Em resposta, o pastor pedir\u00e1 a sua congrega\u00e7\u00e3o e comunidade no domingo para pausar e falar sobre &#8220;reconcilia\u00e7\u00e3o atrav\u00e9s de amor e justi\u00e7a&#8221;.<\/p>\n<p>O que podemos fazer para ser parte da solu\u00e7\u00e3o? ele perguntou. N\u00e3o seja parte do desenho de linha. Diminuir e ser o Corpo de Cristo, porque as pessoas ao nosso redor est\u00e3o procurando algu\u00e9m para fornecer um toque amoroso e n\u00e3o um tom irritado de ret\u00f3rica.<\/p>\n<p>Pare o drama e seja parte da solu\u00e7\u00e3o.<\/p>\n<p>Come\u00e7a com uma porta aberta.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Relacionado:<\/strong> A seguinte adi\u00e7\u00e3o \u00e0 declara\u00e7\u00e3o do Nazareno sobre discrimina\u00e7\u00e3o em seu <em>Manual<\/em> foi adotada na Assembleia Geral de 2017 em junho. A declara\u00e7\u00e3o foi patrocinada pelos distritos de Kansas City e Virg\u00ednia da Regi\u00e3o EUA \/ Canad\u00e1. (Baixar <a href=\"http:\/\/ga2017.comhttps:\/\/nazarene.org\/wp-content\/uploads\/resolutions\/english\/christian_action\/CA-704a.pdf\" target=\"_blank\">PDF<\/a>)<\/p>\n<p>RESOLVED que esse par\u00e1grafo 903.2 do <em>Manual<\/em> ser\u00e1 alterado como a seguir:<\/p>\n<p>903.2. Discrimina\u00e7\u00e3o<\/p>\n<p>A Igreja do Nazareno reitera sua posi\u00e7\u00e3o hist\u00f3rica de compaix\u00e3o crist\u00e3 para pessoas de todas as ra\u00e7as. Acreditamos que Deus \u00e9 o Criador de todas as pessoas, e que de um sangue s\u00e3o todas as pessoas criadas.<\/p>\n<p>Acreditamos que cada indiv\u00edduo, independentemente de ra\u00e7a, cor, g\u00eanero ou credo, deve ter igualdade antes da lei, incluindo o direito de voto, acesso igual a oportunidades educacionais, a todas as instala\u00e7\u00f5es p\u00fablicas, e \u00e0 oportunidade igualit\u00e1ria, de acordo com a capacidade de algu\u00e9m, para ganhar uma vida livre de qualquer emprego ou discrimina\u00e7\u00e3o econ\u00f4mica.<\/p>\n<p>Instamos nossas igrejas em todos os lugares a continuar e fortalecer programas de educa\u00e7\u00e3o para promover compreens\u00e3o racial e harmonia. Tamb\u00e9m sentimos que a admoesta\u00e7\u00e3o escritur\u00edstica de Hebreus 12:14 deve guiar as a\u00e7\u00f5es de nosso povo. Instamos que cada membro da Igreja do Nazareno examine humildemente suas atitudes pessoais e a\u00e7\u00f5es para outros, como um primeiro passo para alcan\u00e7ar o objetivo crist\u00e3o de participa\u00e7\u00e3o plena por todos na vida da igreja e toda a comunidade.<\/p>\n<p>Reenfatizamos nossa cren\u00e7a que santidade de cora\u00e7\u00e3o e vida \u00e9 a base para vida correta. Acreditamos que a caridade crist\u00e3 entre grupos raciais ou de g\u00eanero vir\u00e1 quando os cora\u00e7\u00f5es de pessoas foram mudados por submiss\u00e3o completa a Jesus Cristo, e que a ess\u00eancia do verdadeiro cristianismo consiste em amar a Deus com o cora\u00e7\u00e3o, alma, mente e for\u00e7a, e o vizinho de algu\u00e9m como si mesmo.<\/p>\n<p>Portanto, renunciamos a qualquer forma de indiferen\u00e7a racial e \u00e9tnica, exclus\u00e3o, subjuga\u00e7\u00e3o ou opress\u00e3o como um pecado grave contra Deus e nossos companheiros seres humanos. Lamentamos o legado de todas as formas de racismo em todo o mundo, e buscamos confrontar esse legado atrav\u00e9s de arrependimento, reconcilia\u00e7\u00e3o e justi\u00e7a b\u00edblica. Buscamos nos arrepender de todo comportamento no qual fomos abertamente ou encobertamente c\u00famplices com o pecado de racismo, passado e presente; e em confiss\u00e3o e lamento buscamos perd\u00e3o e reconcilia\u00e7\u00e3o.<\/p>\n<p>Al\u00e9m disso, reconhecemos que n\u00e3o h\u00e1 reconcilia\u00e7\u00e3o al\u00e9m da luta humana para estar contra e superar todo preconceito pessoal, institucional e estrutural respons\u00e1vel por humilha\u00e7\u00e3o racial e \u00e9tnica e opress\u00e3o. Chamamos Nazarenos em todos os lugares para identificar e buscar remover atos e estruturas de preconceito, para facilitar ocasi\u00f5es para buscar perd\u00e3o e reconcilia\u00e7\u00e3o, e tomar a\u00e7\u00e3o para empoderar aqueles que foram marginalizados. (2017)<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"text-align:center\">\n<figure class=\"image\" style=\"display:inline-block\"><img alt=\"\" heig=\"\"><\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[762,2274,1864],"class_list":["post-52585","news","type-news","status-publish","hentry","news-tag-eua-canada","news-tag-iniciativa-atual","news-tag-virginia-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/USACanada\/Virginia\/CullenSouthsideNazarene.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\\\/\",\"name\":\"Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/USACanada\\\/Virginia\\\/CullenSouthsideNazarene.jpg\",\"datePublished\":\"2019-07-10T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/USACanada\\\/Virginia\\\/CullenSouthsideNazarene.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/USACanada\\\/Virginia\\\/CullenSouthsideNazarene.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/","og_locale":"pt_BR","og_type":"article","og_title":"Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville","og_url":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","og_image":[{"url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/USACanada\/Virginia\/CullenSouthsideNazarene.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/","url":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/","name":"Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/USACanada\/Virginia\/CullenSouthsideNazarene.jpg","datePublished":"2019-07-10T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/USACanada\/Virginia\/CullenSouthsideNazarene.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/USACanada\/Virginia\/CullenSouthsideNazarene.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-virginia-abre-portas-para-uma-comunidade-ferida-tem-como-objetivo-ser-parte-de-uma-solucao-depois-de-charlottesville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"Igreja Virg\u00ednia abre portas para uma comunidade ferida, tem como objetivo ser parte de uma solu\u00e7\u00e3o depois de Charlottesville"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/52585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/52585\/revisions"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=52585"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=52585"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=52585"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=52585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}