{"id":51326,"date":"2019-12-17T00:00:00","date_gmt":"2019-12-17T06:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/"},"modified":"2019-12-17T00:00:00","modified_gmt":"2019-12-17T06:00:00","slug":"apnts-dedica-novo-centro-de-missao-de-vida","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/","title":{"rendered":"APNTS dedica Novo Centro de Miss\u00e3o de Vida"},"content":{"rendered":"<p>O Presidente do Semin\u00e1rio Floyd T. Cunningham se juntou a parceiros coreanos da Igreja SangAmDong do Nazareno e Igreja Metodista Onnuri em 17 de junho para dedicar o Centro de Miss\u00e3o Nova Vida no campus do Semin\u00e1rio Teol\u00f3gico Nazareno \u00c1sia-Pac\u00edfico. &nbsp;<\/p>\n<p>Juntar aos pastores coreanos eram membros de suas respectivas igrejas, bem como amigos, corpo docente, estudantes e equipe de&nbsp;<a href=\"http:\/\/www.apnts.org\/\" target=\"_blank\">APNTS<\/a>.&nbsp;<\/p>\n<p>A dedica\u00e7\u00e3o veio apenas algumas semanas antes da conclus\u00e3o real do projeto de edif\u00edcio, mas forneceu um tempo significativo para doadores e parceiros para realizar uma turn\u00ea na instala\u00e7\u00e3o na qual eles colocaram seu apoio generoso. &nbsp;<\/p>\n<p>A cerim\u00f4nia especial foi planejada para coincidir com a presen\u00e7a de Shin Min-Gyoo e Jeong Myeong Muk, que ensinou os cursos de m\u00f3dulo de ver\u00e3o do semin\u00e1rio.&nbsp;<\/p>\n<p>A cerim\u00f4nia incluiu hinos e liturgia de dedica\u00e7\u00e3o, m\u00fasica especial de estudantes APNTS, e uma mensagem de dedica\u00e7\u00e3o especial do Dr. Jeong da Igreja Metodista Onnuri.&nbsp;<\/p>\n<p>Ap\u00f3s a apresenta\u00e7\u00e3o simb\u00f3lica das chaves da instala\u00e7\u00e3o para Cunningham pelo arquiteto APNTS Eric Sanchez, um corte de fita oficial foi feito na frente no novo edif\u00edcio.&nbsp; O Professor APNTS Kwon Dong Hwan ent\u00e3o liderou parceiros APNTS em uma turn\u00ea guiada das novas instala\u00e7\u00f5es. &nbsp;<\/p>\n<p>O prop\u00f3sito inicial do centro era fornecer habita\u00e7\u00e3o para equipes de Trabalho e Testemunha e mission\u00e1rios que v\u00eam para APNTS e as Filipinas.&nbsp; Embora este prop\u00f3sito certamente seja realizado, esta instala\u00e7\u00e3o tamb\u00e9m fornecer\u00e1 habita\u00e7\u00e3o para outros grupos que v\u00eam para APNTS para cursos de curto prazo, semin\u00e1rios, oficinas em miss\u00f5es, ingl\u00eas e o novo programa de desenvolvimento infantil hol\u00edstico.&nbsp;<\/p>\n<p>Esta instala\u00e7\u00e3o crescer\u00e1 rapidamente em utilidade como o semin\u00e1rio desenvolve outras instala\u00e7\u00f5es, incluindo o Centro Cobb de Worship e a Sala Horizon no Centro Nielson para Evangelismo e Educa\u00e7\u00e3o, que \u00e9 adjacente ao novo centro. &nbsp;<\/p>\n<p>O primeiro andar do centro apresenta acomoda\u00e7\u00f5es semelhantes a hotel com amenidades e servi\u00e7os completos.&nbsp; O segundo n\u00edvel fornece acomoda\u00e7\u00f5es de dormit\u00f3rio, que ser\u00e3o ideais para grupos que visitam o campus, enquanto o terceiro andar incluir\u00e1 dois apartamentos para membros de corpo docente visitantes, completos com uma cozinha e espa\u00e7os de jantar internos e externos.&nbsp;<\/p>\n<p>A nova instala\u00e7\u00e3o fornecer\u00e1 um grande recurso para minist\u00e9rio para APNTS e sua \u00e1rea circundante.&nbsp; A escola estende sua gratid\u00e3o mais profunda para as igrejas SangAmDong e Onnuri para seu apoio generoso e parceria cont\u00ednua.&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Presidente do Semin\u00e1rio Floyd T. Cunningham se juntou a parceiros coreanos da Igreja SangAmDong do Nazareno e Igreja Metodista Onnuri em 17 de junho para dedicar o Centro de Miss\u00e3o Nova Vida no campus do Semin\u00e1rio Teol\u00f3gico Nazareno \u00c1sia-Pac\u00edfico. &nbsp; Juntar aos pastores coreanos eram membros de suas respectivas igrejas, bem como amigos, corpo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25037,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[754,820,1778],"class_list":["post-51326","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-asia-pacifico","news-tag-filipinas-pt-br","news-tag-nts-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>APNTS dedica Novo Centro de Miss\u00e3o de Vida - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"APNTS dedica Novo Centro de Miss\u00e3o de Vida\" \/>\n<meta property=\"og:description\" content=\"O Presidente do Semin\u00e1rio Floyd T. Cunningham se juntou a parceiros coreanos da Igreja SangAmDong do Nazareno e Igreja Metodista Onnuri em 17 de junho para dedicar o Centro de Miss\u00e3o Nova Vida no campus do Semin\u00e1rio Teol\u00f3gico Nazareno \u00c1sia-Pac\u00edfico. &nbsp; Juntar aos pastores coreanos eram membros de suas respectivas igrejas, bem como amigos, corpo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/apnts-dedica-novo-centro-de-missao-de-vida\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/apnts-dedica-novo-centro-de-missao-de-vida\\\/\",\"name\":\"APNTS dedica Novo Centro de Miss\u00e3o de Vida - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/apnts-dedica-novo-centro-de-missao-de-vida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/apnts-dedica-novo-centro-de-missao-de-vida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/APNTS_new_building_dedication_1.jpg\",\"datePublished\":\"2019-12-17T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/apnts-dedica-novo-centro-de-missao-de-vida\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/apnts-dedica-novo-centro-de-missao-de-vida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/apnts-dedica-novo-centro-de-missao-de-vida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/APNTS_new_building_dedication_1.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/APNTS_new_building_dedication_1.jpg\",\"width\":480,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/apnts-dedica-novo-centro-de-missao-de-vida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"APNTS dedica Novo Centro de Miss\u00e3o de Vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"APNTS dedica Novo Centro de Miss\u00e3o de Vida - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/","og_locale":"pt_BR","og_type":"article","og_title":"APNTS dedica Novo Centro de Miss\u00e3o de Vida","og_description":"O Presidente do Semin\u00e1rio Floyd T. Cunningham se juntou a parceiros coreanos da Igreja SangAmDong do Nazareno e Igreja Metodista Onnuri em 17 de junho para dedicar o Centro de Miss\u00e3o Nova Vida no campus do Semin\u00e1rio Teol\u00f3gico Nazareno \u00c1sia-Pac\u00edfico. &nbsp; Juntar aos pastores coreanos eram membros de suas respectivas igrejas, bem como amigos, corpo [&hellip;]","og_url":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/","url":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/","name":"APNTS dedica Novo Centro de Miss\u00e3o de Vida - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/APNTS_new_building_dedication_1.jpg","datePublished":"2019-12-17T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/APNTS_new_building_dedication_1.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/APNTS_new_building_dedication_1.jpg","width":480,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/apnts-dedica-novo-centro-de-missao-de-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"APNTS dedica Novo Centro de Miss\u00e3o de Vida"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/51326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/51326\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media\/25037"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=51326"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=51326"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=51326"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=51326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}