{"id":50287,"date":"2020-05-22T00:00:00","date_gmt":"2020-05-22T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/"},"modified":"2020-05-22T00:00:00","modified_gmt":"2020-05-22T05:00:00","slug":"igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/","title":{"rendered":"Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19"},"content":{"rendered":"<p>Quando Winter Haven Primeira Igreja da equipe pastoral do Nazareno e conselho de igreja ouviram sobre a estadia em ordens de casa, eles eram r\u00e1pidos para servi\u00e7os de adora\u00e7\u00e3o de transi\u00e7\u00e3o e li\u00e7\u00f5es de escola dominical on-line. A decis\u00e3o mais dif\u00edcil era o que fazer com Sua Miss\u00e3o, um minist\u00e9rio para os residentes marginalizados de Winter Haven, Fl\u00f3rida.&nbsp;<\/p>\n<p>Sua Miss\u00e3o tem corrido por duas d\u00e9cadas, ministrando para fam\u00edlias de rua e de baixa renda alimentando-as refei\u00e7\u00f5es e realizando um servi\u00e7o de adora\u00e7\u00e3o e estudo b\u00edblico duas vezes uma semana. Uma ordem de abrigo em lugar n\u00e3o era vi\u00e1vel para muitos daqueles que participam de Sua Miss\u00e3o.&nbsp;<\/p>\n<p>Para muitas dessas pessoas sem abrigo permanente, a ordem para autoquarentena tinha pouco significado&#8221;, disse Wes Eby, o presidente local de Miss\u00f5es Nazarenas Internacionais. Onde eles comeriam? Como eles obteriam lavanderia feita? Ou tomar um chuveiro?<\/p>\n<p>O minist\u00e9rio decidiu realizar servi\u00e7os t\u00e3o pr\u00f3ximos do normal quanto poss\u00edvel enquanto observava as recomenda\u00e7\u00f5es do CDC, o governador e funcion\u00e1rios do governo local. Eles moveram os servi\u00e7os de fora, se distanciaram fisicamente das cadeiras e tomaram as precau\u00e7\u00f5es de servi\u00e7o de comida necess\u00e1rias.&nbsp;<\/p>\n<p>A igreja era capaz de formar parcerias com um n\u00famero de organiza\u00e7\u00f5es e outras igrejas para aumentar os servi\u00e7os do minist\u00e9rio durante um tempo no qual seus destinat\u00e1rios &nbsp;s\u00e3o &nbsp;particularmente afetados.&nbsp;Sua Miss\u00e3o come\u00e7ou a servir refei\u00e7\u00f5es diariamente no campus atrav\u00e9s de doa\u00e7\u00f5es de comida aumentadas para a igreja. Eles at\u00e9 trouxeram um reboque port\u00e1til no site para fornecer servi\u00e7os de chuveiro e lavanderia.<\/p>\n<p>A igreja foi agradavelmente surpresa por como Seus destinat\u00e1rios de Miss\u00f5es est\u00e3o fazendo sua parte para ajudar outros. Uma mulher que vive em seu carro deu doa\u00e7\u00f5es em dinheiro duas vezes de gratid\u00e3o pelo que ela foi dado.<\/p>\n<p>T\u00e3o s\u00e9rio e devastador quanto COVID-19 \u00e9, trouxe novas pessoas para a igreja, almas que precisam da mensagem de evangelho de esperan\u00e7a, e forjou novas parcerias na comunidade para servir os marginalizados&#8221;, disse Pastor Tom Whitesides. Verdadeiramente, Deus deu graciosamente a Winter Haven Nazarene as novas oportunidades para ministrar para o &#8216;menor desses&#8217; em Seu nome.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sua Miss\u00e3o, um minist\u00e9rio para fam\u00edlias de rua e de baixa renda em Winter Haven, Fl\u00f3rida, intensificou seus servi\u00e7os durante a pandemia COVID-19, incluindo oferecer servi\u00e7os de chuveiro e lavanderia. <\/p>\n","protected":false},"author":1,"featured_media":25945,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[2342,1959,2115],"class_list":["post-50287","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-coronavirus-pt-br","news-tag-florida-pt-br","news-tag-regiao-eua-canada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19 - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19\" \/>\n<meta property=\"og:description\" content=\"Sua Miss\u00e3o, um minist\u00e9rio para fam\u00edlias de rua e de baixa renda em Winter Haven, Fl\u00f3rida, intensificou seus servi\u00e7os durante a pandemia COVID-19, incluindo oferecer servi\u00e7os de chuveiro e lavanderia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\\\/\",\"name\":\"Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19 - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Winter-Haven.jpg\",\"datePublished\":\"2020-05-22T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Winter-Haven.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Winter-Haven.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19 - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/","og_locale":"pt_BR","og_type":"article","og_title":"Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19","og_description":"Sua Miss\u00e3o, um minist\u00e9rio para fam\u00edlias de rua e de baixa renda em Winter Haven, Fl\u00f3rida, intensificou seus servi\u00e7os durante a pandemia COVID-19, incluindo oferecer servi\u00e7os de chuveiro e lavanderia.","og_url":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/","url":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/","name":"Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19 - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Winter-Haven.jpg","datePublished":"2020-05-22T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Winter-Haven.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Winter-Haven.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-da-florida-continua-a-alcancar-marginalizada-durante-pandemia-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"Igreja da Fl\u00f3rida continua a alcan\u00e7ar marginalizada durante pandemia COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/50287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/50287\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media\/25945"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=50287"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=50287"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=50287"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=50287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}