{"id":46144,"date":"2022-05-19T00:00:00","date_gmt":"2022-05-19T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/"},"modified":"2022-05-19T00:00:00","modified_gmt":"2022-05-19T05:00:00","slug":"igreja-filipinas-do-nazareno-celebra-75o-aniversario","status":"publish","type":"news","link":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/","title":{"rendered":"Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio"},"content":{"rendered":"<p>A Igreja do Nazareno nas Filipinas celebrou seu 75\u00ba Anivers\u00e1rio de Jubileu de Diamante este ano. Uma celebra\u00e7\u00e3o de adora\u00e7\u00e3o foi realizada no Centro de Conven\u00e7\u00f5es Internacional Filipino em 8 de maio de 22 e foi participada por mais de 3.000 Nazarenos, tanto fisicamente e on-line de Luzon, Visayas e Mindanao.&nbsp;<\/p>\n<p>O programa de tr\u00eas partes, com tema &#8220;Rise Up e Go Filipinas!&#8221; come\u00e7ou com uma celebra\u00e7\u00e3o de adora\u00e7\u00e3o seguida pela honra de igrejas pioneiras e membros no pa\u00eds. A celebra\u00e7\u00e3o culminou com um servi\u00e7o de ordena\u00e7\u00e3o para 17 &nbsp;ministros.<\/p>\n<p>A celebra\u00e7\u00e3o de adora\u00e7\u00e3o foi aberta por louvor e m\u00fasicas de a\u00e7\u00e3o de gra\u00e7as lideradas pelos jovens talentosos do Distrito Metro Manila. Nova Esperan\u00e7a do Nazareno e crian\u00e7as de seis centros de desenvolvimento infantil diferentes deram apresenta\u00e7\u00f5es culturais. A m\u00fasica tema, &#8220;Tumayo Humayo Pilipinas&#8221;, foi cantada por Rommel Bonus e Hannah Morales junto com um grupo de jovens pastores do Distrito Metro Manila.<\/p>\n<p>Mark Louw, diretor regional \u00c1sia-Pac\u00edfico, compartilhou a mensagem de anivers\u00e1rio e desafiou a igreja das Filipinas a participar da Grande Comiss\u00e3o, para se levantar e &#8220;ir fazer disc\u00edpulos de todas as na\u00e7\u00f5es&#8221;.<\/p>\n<p>Embora celebremos o trabalho da igreja e seus servos nesses \u00faltimos 75 anos, tamb\u00e9m precisamos confessar que n\u00e3o alcan\u00e7amos nosso potencial total&#8221;, disse Louw. \u00c0s vezes, perdemos oportunidades de impactar, e \u00e0s vezes permitimos conforto e um desejo de calma para anular a necessidade de pecado ser confrontado em amor e problemas para serem lidados.<\/p>\n<p>Louw fechou o servi\u00e7o de celebra\u00e7\u00e3o com uma ora\u00e7\u00e3o para as pessoas da igreja das Filipinas, que eles ser\u00e3o as m\u00e3os de Deus no trabalho em sua na\u00e7\u00e3o e para Deus para preench\u00ea-los, form\u00e1-los e envi\u00e1-los para cumprir a Grande Comiss\u00e3o.<\/p>\n<p>A segunda parte da celebra\u00e7\u00e3o se concentrou em honrar as pessoas que foram pioneiras no trabalho nas Filipinas. Estes s\u00e3o os homens e mulheres que comprometeram suas vidas para espalhar o evangelho, plantando igrejas e fazendo disc\u00edpulos. Axa Jane Encarnacion, filha do ministro fundador nas Filipinas, Marciano Encarnacion, deu uma <a href=\"https:\/\/youtu.be\/GwJkMem9iwg\" target=\"_blank\">mensagem de v\u00eddeo inspiradora<\/a>.&nbsp;<\/p>\n<p>Arnel Piliin, coordenador de estrat\u00e9gia de campo Filipinas-Micronesia, tamb\u00e9m apresentou a vis\u00e3o e metas para a Igreja Filipina do Nazareno. Ele desafiou os membros, pastores e superintendentes de distrito para trabalhar juntos para alcan\u00e7ar o objetivo de plantio 587 novas igrejas e receber 74.000 novos membros at\u00e9 2030. Ele enfatizou que isso &nbsp;pode ser alcan\u00e7ado apenas atrav\u00e9s do poder do Esp\u00edrito Santo e por todos trabalhando juntos &#8211; cada pessoa discipulando outra, cada igreja local plantando uma igreja, e cada distrito patrocinando um novo distrito.<br \/>\nA parte final da celebra\u00e7\u00e3o era o servi\u00e7o de ordena\u00e7\u00e3o liderado por David Graves, superintendente geral jurisdiccional para a Regi\u00e3o \u00c1sia-Pac\u00edfico. Graves ordenou 17 pastores durante a celebra\u00e7\u00e3o de Jubileu, e outros 9 pastores em Cebu City em 10 de maio de 2022.<\/p>\n<p>Graves deu uma mensagem inspiradora e desafiadora para os ordenandos e todos que participaram da celebra\u00e7\u00e3o.&nbsp;<\/p>\n<p>Acho que \u00e9 bom para n\u00f3s ocasionalmente apenas parar e olhar para tr\u00e1s no passado&#8221;, disse Graves. De fato, eu acho que \u00e9 realmente bom para n\u00f3s parar uma vez em um tempo e olhar para tr\u00e1s para o passado e ver como Deus tem sido fiel para n\u00f3s.<br \/>\nA celebra\u00e7\u00e3o de Jubileu n\u00e3o \u00e9 apenas um evento de um dia. Os organizadores esperam que continue a fazer um impacto como a igreja arrecada fundos para o Projeto Diamond &#8211; a constru\u00e7\u00e3o de uma casa de aposentadoria para pastores filipinos e um centro de treinamento de miss\u00e3o.<br \/>\nO campo tamb\u00e9m lan\u00e7ou um livro, <i>Fogo Santo: A Hist\u00f3ria de Jubileu de Diamante da Igreja do Nazareno nas Filipinas,<\/i> de autor por Jason Hallig, Floyd T. Cunningham e Ernesto Rulloda. Rendimentos da venda de livros ir\u00e3o para o Projeto Diamond.<\/p>\n<p><a href=\"https:\/\/www.asiapacificnazarene.org\" target=\"_blank\">&nbsp;Igreja do Nazareno \u00c1sia-Pac\u00edfico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Igreja do Nazareno nas Filipinas celebrou seu 75\u00ba Anivers\u00e1rio de Jubileu de Diamante com uma celebra\u00e7\u00e3o de adora\u00e7\u00e3o participada por mais de 3.000 Nazarenos.<\/p>\n","protected":false},"author":1,"featured_media":28429,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[754,820],"class_list":["post-46144","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-asia-pacifico","news-tag-filipinas-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio\" \/>\n<meta property=\"og:description\" content=\"A Igreja do Nazareno nas Filipinas celebrou seu 75\u00ba Anivers\u00e1rio de Jubileu de Diamante com uma celebra\u00e7\u00e3o de adora\u00e7\u00e3o participada por mais de 3.000 Nazarenos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\\\/\",\"name\":\"Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Philippines-75th.png\",\"datePublished\":\"2022-05-19T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Philippines-75th.png\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Philippines-75th.png\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/","og_locale":"pt_BR","og_type":"article","og_title":"Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio","og_description":"A Igreja do Nazareno nas Filipinas celebrou seu 75\u00ba Anivers\u00e1rio de Jubileu de Diamante com uma celebra\u00e7\u00e3o de adora\u00e7\u00e3o participada por mais de 3.000 Nazarenos.","og_url":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/","url":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/","name":"Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Philippines-75th.png","datePublished":"2022-05-19T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Philippines-75th.png","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Philippines-75th.png","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/news\/igreja-filipinas-do-nazareno-celebra-75o-aniversario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/pt-br\/news\/"},{"@type":"ListItem","position":3,"name":"Igreja Filipinas do Nazareno celebra 75\u00ba Anivers\u00e1rio"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/46144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news\/46144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media\/28429"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=46144"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-categories?post=46144"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-region-taxonomy?post=46144"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/news-tag?post=46144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}