{"id":41498,"date":"2025-03-11T16:21:03","date_gmt":"2025-03-11T21:21:03","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/mantendo-em-passo-com-jesus\/"},"modified":"2025-03-11T16:21:03","modified_gmt":"2025-03-11T21:21:03","slug":"mantendo-em-passo-com-jesus","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/","title":{"rendered":"Mantendo Em Passo com Jesus"},"content":{"rendered":"<p style=\"margin-bottom:11px\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\"><span style=\"font-family:Calibri,sans-serif\">Nunca vivi em uma fazenda &#8211; nunca ordenhei uma vaca, nunca arei um campo, nunca esperei para a colheita. Sou um menino de cidade. Isso me coloca em uma desvantagem, \u00e0s vezes, quando eu li as par\u00e1bolas e ilustra\u00e7\u00f5es de Jesus no Novo Testamento. Muitas de suas imagens em prega\u00e7\u00e3o vieram de um contexto de agricultura &#8211; Israel antigo era uma sociedade agr\u00e1ria. As pessoas n\u00e3o apenas entenderam, mas viveram suas vidas em torno das temporadas de plantio e colheita. Uma dessas imagens de agricultura no Novo Testamento \u00e9 Jesus como nosso &#8220;Yokefellow&#8221;. Em Mateus 11:28-30, Jesus disse, &#8220;Venha a mim, todos voc\u00eas que est\u00e3o cansados e sobrecarregados, e eu lhe darei descanso. Tome meu jugo sobre voc\u00ea e aprenda de mim, porque eu sou gentil e humilde em cora\u00e7\u00e3o, e voc\u00ea encontrar\u00e1 descanso para suas almas. Para meu jugo \u00e9 f\u00e1cil e meu fardo \u00e9 leve. Ainda hoje, agricultores em diferentes partes do mundo usam bois para arar seus campos. Quando os agricultores t\u00eam um novo boi, eles colocar\u00e3o o ox jovem e n\u00e3o treinado em um jugo com um boi experiente e bem treinado. O jovem box aprende a ser um animal de projeto simplesmente mantendo em passo com o boi mais antigo. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\"><span style=\"font-family:Calibri,sans-serif\">Recentemente, eu estava refletindo sobre o desafio de evangelismo da igreja em 2020 e al\u00e9m. Honestamente, evangelismo parece t\u00e3o dif\u00edcil hoje. Muitos no mundo parecem n\u00e3o interessados em um relacionamento comprometido com um Deus soberano. At\u00e9 muitos crist\u00e3os se afastam quando falamos sobre evangelismo e alcan\u00e7ar o perdido. Pastores muitas vezes se sentem cansados e oprimidos quando eles pensam em compartilhar a mensagem do Evangelho e ajudar sua igreja a crescer. O que as palavras de Jesus em Mateus 11 nos ensinam sobre fazer disc\u00edpulos? Uma li\u00e7\u00e3o importante para aprender \u00e9 que buscar o perdido \u00e9 a miss\u00e3o de Jesus. Somos para ser jugados a Jesus, n\u00e3o da outra maneira. N\u00e3o estamos destinados a sair para o mundo e pedir a Jesus para nos seguir. Jesus, eu tenho que crescer esta igreja&#8221;, diz o pastor ansioso. Por favor, venha junto com mim e me aben\u00e7oe. Ser jugo a Jesus parece muito diferente do que isso. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\"><span style=\"font-family:Calibri,sans-serif\">O descanso que Jesus oferece quando seus disc\u00edpulos s\u00e3o jugados com ele como eles come\u00e7am cada novo dia. Reconhecemos que aprendemos de Jesus. O seguimos. Vamos onde ele vai. Jesus nos lidera. Evangelismo, ent\u00e3o, assume uma nova dimens\u00e3o. \u00c9 evangelismo liderado pelo Esp\u00edrito de Deus. Ele nos traz em conversas com as pessoas certas no tempo certo. Vivendo em passo com o Esp\u00edrito de Cristo, nos encontramos no meio do que a gra\u00e7a salvadora de Cristo est\u00e1 fazendo neste mundo. Jesus nos convida ao longo de sua jornada com algu\u00e9m que precisa dele. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\"><span style=\"font-family:Calibri,sans-serif\">Somos chamados para viver momento a momento em sintonia com Jesus, jugo a ele, ouvindo sua voz. Quando fazemos isso, evangelismo traz paz em lugar de ansiedade porque estamos caminhando com o Pr\u00edncipe da Paz. \u00c9 um lugar de excita\u00e7\u00e3o porque estamos caminhando com o Um que faz todas as coisas novas. \u00c9 um lugar de liberta\u00e7\u00e3o porque estamos caminhando com o Deus Todo-Poderoso. \u00c9 um lugar de bondade porque estamos caminhando com o Aquele que \u00e9 chamado Maravilhoso! A pr\u00f3xima vez que voc\u00ea sente medo em torno da atividade de evangelismo, lembre-se de tomar seu jugo. Aprenda com ele. Encontre descanso. V\u00e1 onde ele vai, e seja frut\u00edfero como voc\u00ea mant\u00e9m em passo com Jesus!<\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":21790,"menu_order":0,"template":"","ndi-journey-tags":[1283,1365],"class_list":["post-41498","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-evangelismo","ndi-journey-tags-passo-com-jesus"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mantendo Em Passo com Jesus - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mantendo Em Passo com Jesus\" \/>\n<meta property=\"og:description\" content=\"Nunca vivi em uma fazenda &#8211; nunca ordenhei uma vaca, nunca arei um campo, nunca esperei para a colheita. Sou um menino de cidade. Isso me coloca em uma desvantagem, \u00e0s vezes, quando eu li as par\u00e1bolas e ilustra\u00e7\u00f5es de Jesus no Novo Testamento. Muitas de suas imagens em prega\u00e7\u00e3o vieram de um contexto de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/mantendo-em-passo-com-jesus\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/mantendo-em-passo-com-jesus\\\/\",\"name\":\"Mantendo Em Passo com Jesus - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/mantendo-em-passo-com-jesus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/mantendo-em-passo-com-jesus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Keeping-in-step-with-Jesus-cow-in-asia-scaled.jpg\",\"datePublished\":\"2025-03-11T21:21:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/mantendo-em-passo-com-jesus\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/mantendo-em-passo-com-jesus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/mantendo-em-passo-com-jesus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Keeping-in-step-with-Jesus-cow-in-asia-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Keeping-in-step-with-Jesus-cow-in-asia-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Two white oxen pulling wooden cart in Myanmar village\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/mantendo-em-passo-com-jesus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mantendo Em Passo com Jesus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mantendo Em Passo com Jesus - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/","og_locale":"pt_BR","og_type":"article","og_title":"Mantendo Em Passo com Jesus","og_description":"Nunca vivi em uma fazenda &#8211; nunca ordenhei uma vaca, nunca arei um campo, nunca esperei para a colheita. Sou um menino de cidade. Isso me coloca em uma desvantagem, \u00e0s vezes, quando eu li as par\u00e1bolas e ilustra\u00e7\u00f5es de Jesus no Novo Testamento. Muitas de suas imagens em prega\u00e7\u00e3o vieram de um contexto de [&hellip;]","og_url":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/","url":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/","name":"Mantendo Em Passo com Jesus - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Keeping-in-step-with-Jesus-cow-in-asia-scaled.jpg","datePublished":"2025-03-11T21:21:03+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Keeping-in-step-with-Jesus-cow-in-asia-scaled.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Keeping-in-step-with-Jesus-cow-in-asia-scaled.jpg","width":2560,"height":1707,"caption":"Two white oxen pulling wooden cart in Myanmar village"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/mantendo-em-passo-com-jesus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"Mantendo Em Passo com Jesus"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey\/41498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey\/41498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media\/21790"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=41498"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey-tags?post=41498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}