{"id":41316,"date":"2024-06-26T15:12:26","date_gmt":"2024-06-26T20:12:26","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/"},"modified":"2024-06-26T15:12:26","modified_gmt":"2024-06-26T20:12:26","slug":"fazer-acampamentos-de-verao-importantes","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/","title":{"rendered":"Fazer Acampamentos de Ver\u00e3o Importantes"},"content":{"rendered":"<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\"><b>Por que nossas igrejas devem priorizar acampamentos de ver\u00e3o? <\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">Sei de experi\u00eancia pessoal que acampamentos de ver\u00e3o s\u00e3o transformadores. Na idade de 10, Deus se encontrou comigo em um acampamento de meninos e meninas no leste de Michigan. Uma quarta-feira \u00e0 noite, abri minha vida para a dire\u00e7\u00e3o de Deus como respondi ao convite para receber Cristo como meu Salvador pessoal. Nesse mesmo acampamento, tamb\u00e9m disse &#8220;Sim&#8221; para seu convite para servir como um ministro em sua igreja.&nbsp; <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\"><b>Como podemos fazer acampamentos de ver\u00e3o uma prioridade?<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\"><i>Publique datas de acampamento e pre\u00e7os cedo<\/i>. Cronogramas de ver\u00e3o podem preencher rapidamente com muitas atividades para nossas crian\u00e7as e juventude. Eles t\u00eam que competir com f\u00e9rias familiares, esportes e atividades escolares extracurriculares. A maioria dos distritos planeja bem \u00e0 frente e pode fornecer detalhes para igrejas locais. Muitas crian\u00e7as e juventude precisam de assist\u00eancia financeira, ent\u00e3o arrecada\u00e7\u00e3o de fundos e bolsas de estudo s\u00e3o necess\u00e1rias.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\"><i>Fa\u00e7a acampamentos um aspecto vital de sua programa\u00e7\u00e3o<\/i>. Cronogramas de igrejas locais tamb\u00e9m podem se encher durante o ver\u00e3o. Ent\u00e3o \u00e9 importante colocar datas de acampamento no calend\u00e1rio da igreja para evitar conflitos. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\"><i>Compartilhar experi\u00eancias de acampamento<\/i>. D\u00ea oportunidades para aqueles que j\u00e1 desfrutaram de acampamento para compartilhar suas experi\u00eancias. Envolver toda a igreja em fornecer bolsas de estudo de acampamento.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\"><i>Acompanhar as crian\u00e7as e juventude<\/i>. N\u00e3o apenas trabalhadores de acampamento e conselheiros s\u00e3o necess\u00e1rios, nossos trabalhadores locais de crian\u00e7as e juventude t\u00eam uma oportunidade maravilhosa para mais constru\u00e7\u00e3o de relacionamento. O crescimento espiritual que ocorre durante o acampamento \u00e9 vital, e \u00e9 importante para nossos criadores de discipulado adultos experiment\u00e1-lo com nossos filhos e juventude.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\"><i>Use acompanhamento estrat\u00e9gico depois de acampamentos<\/i>. Sucesso requer planejamento, seguir e acompanhamento.&nbsp; Se voc\u00ea estava com seus filhos e juventude em acampamento, voc\u00ea saber\u00e1 o que eles experimentaram, e voc\u00ea ser\u00e1 capaz de confirmar e construir nessas experi\u00eancias. Uma vez que as emo\u00e7\u00f5es de acampamento diminuem, eles precisam ser firmemente estabelecidos em seus grupos de discipulado onde eles podem crescer juntos.&nbsp; <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">Por favor, <b>compartilhe suas experi\u00eancias de acampamento<\/b>. Envie-os para dstanton@nazarene.org<\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":22680,"menu_order":0,"template":"","ndi-journey-tags":[1193],"class_list":["post-41316","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-acampamentos-de-verao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fazer Acampamentos de Ver\u00e3o Importantes - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fazer Acampamentos de Ver\u00e3o Importantes\" \/>\n<meta property=\"og:description\" content=\"Por que nossas igrejas devem priorizar acampamentos de ver\u00e3o? Sei de experi\u00eancia pessoal que acampamentos de ver\u00e3o s\u00e3o transformadores. Na idade de 10, Deus se encontrou comigo em um acampamento de meninos e meninas no leste de Michigan. Uma quarta-feira \u00e0 noite, abri minha vida para a dire\u00e7\u00e3o de Deus como respondi ao convite para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/fazer-acampamentos-de-verao-importantes\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/fazer-acampamentos-de-verao-importantes\\\/\",\"name\":\"Fazer Acampamentos de Ver\u00e3o Importantes - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/fazer-acampamentos-de-verao-importantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/fazer-acampamentos-de-verao-importantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/shot-of-a-group-of-friends-holding-a-sign-in-a-out-2023-11-27-04-57-30-utc.jpg\",\"datePublished\":\"2024-06-26T20:12:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/fazer-acampamentos-de-verao-importantes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/fazer-acampamentos-de-verao-importantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/fazer-acampamentos-de-verao-importantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/shot-of-a-group-of-friends-holding-a-sign-in-a-out-2023-11-27-04-57-30-utc.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/shot-of-a-group-of-friends-holding-a-sign-in-a-out-2023-11-27-04-57-30-utc.jpg\",\"width\":7740,\"height\":5296,\"caption\":\"Shot of a group of friends holding a sign in a outside in a park.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/fazer-acampamentos-de-verao-importantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fazer Acampamentos de Ver\u00e3o Importantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fazer Acampamentos de Ver\u00e3o Importantes - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/","og_locale":"pt_BR","og_type":"article","og_title":"Fazer Acampamentos de Ver\u00e3o Importantes","og_description":"Por que nossas igrejas devem priorizar acampamentos de ver\u00e3o? Sei de experi\u00eancia pessoal que acampamentos de ver\u00e3o s\u00e3o transformadores. Na idade de 10, Deus se encontrou comigo em um acampamento de meninos e meninas no leste de Michigan. Uma quarta-feira \u00e0 noite, abri minha vida para a dire\u00e7\u00e3o de Deus como respondi ao convite para [&hellip;]","og_url":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/","url":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/","name":"Fazer Acampamentos de Ver\u00e3o Importantes - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/shot-of-a-group-of-friends-holding-a-sign-in-a-out-2023-11-27-04-57-30-utc.jpg","datePublished":"2024-06-26T20:12:26+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/shot-of-a-group-of-friends-holding-a-sign-in-a-out-2023-11-27-04-57-30-utc.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/shot-of-a-group-of-friends-holding-a-sign-in-a-out-2023-11-27-04-57-30-utc.jpg","width":7740,"height":5296,"caption":"Shot of a group of friends holding a sign in a outside in a park."},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/fazer-acampamentos-de-verao-importantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"Fazer Acampamentos de Ver\u00e3o Importantes"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey\/41316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey\/41316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media\/22680"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=41316"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey-tags?post=41316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}