{"id":41105,"date":"2023-09-13T14:37:20","date_gmt":"2023-09-13T19:37:20","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/procurando-um-novo-programa-vbs\/"},"modified":"2025-06-13T00:18:53","modified_gmt":"2025-06-13T05:18:53","slug":"procurando-um-novo-programa-vbs","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/","title":{"rendered":"Procurando um Novo Programa VBS?"},"content":{"rendered":"<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\">Todos os anos, igrejas Nazarenas s\u00e3o bombardeadas por numerosos programas VBS de outras denomina\u00e7\u00f5es e empresas, enquanto n\u00e3o percebem que Nazarenos t\u00eam um curr\u00edculo VBS criado por Nazarenos. Ent\u00e3o, antes de voc\u00ea comprar um recurso VBS que n\u00e3o reflete a teologia Wesleyan-Holiness, investigue um criado especialmente para seus filhos. E \u00e9 um download gratuito!&nbsp; <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\"><b>Aqui est\u00e3o as ofertas VBS de NDI para os pr\u00f3ximos dois anos!<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\"><b>2024 VBS &#8211; Aventura de Rafting de Rio<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\">N\u00e3o perca o 2024 VBS:&nbsp;Aventura <i>de Rafting de Rio<\/i>! Cada parada na aventura nos atrair\u00e1 para mais perto de Deus e seu amor. Crian\u00e7as aprender\u00e3o que Deus nos enche com seu amor, Deus nos transforma com seu amor, Deus nos salva com seu amor, e Deus nos quer para compartilhar seu amor. Em uma viagem que espelha o crescimento da igreja no livro de Atos, as crian\u00e7as viajar\u00e3o no rio com Bobby (um cientista) e Sammy (um guia de rio). Bobby e Sammy visitam pessoas ao longo do rio cujo trabalho \u00e1rduo n\u00e3o produz nenhuma colheita. Os campos, tabelas e est\u00f4magos das pessoas est\u00e3o vazios. Felizmente, um criador fez uma semente milagrosa que cresce 100 vezes mais r\u00e1pido do que sementes regulares, e a fruta \u00e9 100 vezes mais nutritiva e mais saborosa do que fruta regular. Bobby e Sammy compartilhar\u00e3o as sementes de milagre em todas as paradas em sua jornada! Como crian\u00e7as veem comunidades transformadas pela semente de milagre, suas pr\u00f3prias vidas ser\u00e3o transformadas pelo milagre do amor de Deus.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\"><b>2025 &#8211; Starlight Airlines<\/b><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\">Em nosso 2025 VBS, passageiros no <i>Starlight Airlines<\/i> quebrar\u00e3o a &#8220;barreira de tempo&#8221;, viajando em per\u00edodos de tempo do Antigo Testamento para uma experi\u00eancia de perto com destaques do livro de G\u00eanesis. Capit\u00e3o Gen inventou este avi\u00e3o especial e pilotos cada voo. Ao longo do caminho, os atendentes de voo dirigir\u00e3o a jornada enquanto um &#8220;atendente de luz&#8221;, Star, ajudar\u00e1 as crian\u00e7as a descobrir verdades fundacionais das hist\u00f3rias de cria\u00e7\u00e3o, Noah, Abra\u00e3o e Joseph. Crian\u00e7as aprender\u00e3o que Deus nos fez, Deus nos salva, Deus nos chama, e Deus nos envia. Prepare-se para uma jornada para o passado que tem o poder de mudar o futuro &#8211; e a eternidade &#8211; daqueles em sua pr\u00f3pria comunidade.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\"><i>River Rafting Adventure<\/i> e <i>Starlight Airlines <\/i>s\u00e3o experi\u00eancias VBS de quatro dias, com um quinto dia opcional, para levar o amor de Deus para a comunidade atrav\u00e9s de um projeto de miss\u00e3o. Uma celebra\u00e7\u00e3o de fechamento tamb\u00e9m \u00e9 inclu\u00edda para dar \u00e0s crian\u00e7as uma oportunidade de compartilhar o que elas aprenderam com suas fam\u00edlias e permitir a oportunidade de convidar pais e outros convidados para come\u00e7ar um relacionamento com Deus. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\">Outro benef\u00edcio adicionado \u00e9 que ambos esses programas VBS est\u00e3o vinculados \u00e0s Escrituras nossos filhos est\u00e3o estudando no <a href=\"https:\/\/www.thefoundrypublishing.com\/children-s-bible-quizzing.html\" style=\"color:#0563c1; text-decoration:underline\">Quizzing B\u00edblico Infantil<\/a>. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:11pt\"><span style=\"line-height:107%\">N\u00e3o perca essas aventuras!<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\">&nbsp;<\/p>\n","protected":false},"featured_media":22946,"menu_order":0,"template":"","ndi-journey-tags":[1055],"class_list":["post-41105","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-vbs-pt-br"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Procurando um Novo Programa VBS? - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Procurando um Novo Programa VBS?\" \/>\n<meta property=\"og:description\" content=\"Todos os anos, igrejas Nazarenas s\u00e3o bombardeadas por numerosos programas VBS de outras denomina\u00e7\u00f5es e empresas, enquanto n\u00e3o percebem que Nazarenos t\u00eam um curr\u00edculo VBS criado por Nazarenos. Ent\u00e3o, antes de voc\u00ea comprar um recurso VBS que n\u00e3o reflete a teologia Wesleyan-Holiness, investigue um criado especialmente para seus filhos. E \u00e9 um download gratuito!&nbsp; Aqui [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-13T05:18:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/2023\/09\/erika-giraud-4EFeD-VTgu4-unsplash-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/procurando-um-novo-programa-vbs\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/procurando-um-novo-programa-vbs\\\/\",\"name\":\"Procurando um Novo Programa VBS? - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/procurando-um-novo-programa-vbs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/procurando-um-novo-programa-vbs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/erika-giraud-4EFeD-VTgu4-unsplash-1-scaled.jpg\",\"datePublished\":\"2023-09-13T19:37:20+00:00\",\"dateModified\":\"2025-06-13T05:18:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/procurando-um-novo-programa-vbs\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/procurando-um-novo-programa-vbs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/procurando-um-novo-programa-vbs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/erika-giraud-4EFeD-VTgu4-unsplash-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/erika-giraud-4EFeD-VTgu4-unsplash-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/procurando-um-novo-programa-vbs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Procurando um Novo Programa VBS?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Procurando um Novo Programa VBS? - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/","og_locale":"pt_BR","og_type":"article","og_title":"Procurando um Novo Programa VBS?","og_description":"Todos os anos, igrejas Nazarenas s\u00e3o bombardeadas por numerosos programas VBS de outras denomina\u00e7\u00f5es e empresas, enquanto n\u00e3o percebem que Nazarenos t\u00eam um curr\u00edculo VBS criado por Nazarenos. Ent\u00e3o, antes de voc\u00ea comprar um recurso VBS que n\u00e3o reflete a teologia Wesleyan-Holiness, investigue um criado especialmente para seus filhos. E \u00e9 um download gratuito!&nbsp; Aqui [&hellip;]","og_url":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","article_modified_time":"2025-06-13T05:18:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/nazarene.org\/wp-content\/uploads\/2023\/09\/erika-giraud-4EFeD-VTgu4-unsplash-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/","url":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/","name":"Procurando um Novo Programa VBS? - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2023\/09\/erika-giraud-4EFeD-VTgu4-unsplash-1-scaled.jpg","datePublished":"2023-09-13T19:37:20+00:00","dateModified":"2025-06-13T05:18:53+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2023\/09\/erika-giraud-4EFeD-VTgu4-unsplash-1-scaled.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2023\/09\/erika-giraud-4EFeD-VTgu4-unsplash-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/procurando-um-novo-programa-vbs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/pt-br\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"Procurando um Novo Programa VBS?"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey\/41105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey\/41105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media\/22946"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/media?parent=41105"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey-tags?post=41105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}