{"id":1367,"count":1,"description":"","link":"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/","name":"Ideias de Escola Dominical","slug":"ideias-de-escola-dominical","taxonomy":"ndi-journey-tags","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ideias de Escola Dominical Archives - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ideias de Escola Dominical Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey-tags\\\/ideias-de-escola-dominical\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey-tags\\\/ideias-de-escola-dominical\\\/\",\"name\":\"Ideias de Escola Dominical Archives - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey-tags\\\/ideias-de-escola-dominical\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/ndi-journey-tags\\\/ideias-de-escola-dominical\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ideias de Escola Dominical\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ideias de Escola Dominical Archives - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/","og_locale":"pt_BR","og_type":"article","og_title":"Ideias de Escola Dominical Archives","og_url":"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/","og_site_name":"Church of the Nazarene","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/","url":"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/","name":"Ideias de Escola Dominical Archives - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/pt-br\/#website"},"breadcrumb":{"@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/pt-br\/ndi-journey-tags\/ideias-de-escola-dominical\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Ideias de Escola Dominical"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/pt-br\/#website","url":"https:\/\/nazarene.org\/pt-br\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/pt-br\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey-tags\/1367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey-tags"}],"about":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/taxonomies\/ndi-journey-tags"}],"wp:post_type":[{"href":"https:\/\/nazarene.org\/pt-br\/wp-json\/wp\/v2\/ndi-journey?ndi-journey-tags=1367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}