{"id":37765,"date":"2025-02-20T10:43:01","date_gmt":"2025-02-20T16:43:01","guid":{"rendered":"https:\/\/nazarene.org\/mission-mondiale-diffusee\/"},"modified":"2026-02-25T21:33:01","modified_gmt":"2026-02-26T03:33:01","slug":"mission-mondiale-diffusee","status":"publish","type":"page","link":"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/","title":{"rendered":"Mission mondiale diffus\u00e9e"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"37765\" class=\"elementor elementor-37765 elementor-15343\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52ceb4e e-flex e-con-boxed e-con e-parent\" data-id=\"52ceb4e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2a6fe42 e-flex e-con-boxed e-con e-child\" data-id=\"2a6fe42\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ac3707a e-con-full e-flex e-con e-child\" data-id=\"ac3707a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77c0c43 elementor-widget elementor-widget-heading\" data-id=\"77c0c43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mission mondiale diffus\u00e9e<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbb9faf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cbb9faf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e913f4 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"1e913f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des milliers de vies sont transform\u00e9es par le travail du Saint-Esprit et les programmes missionnaires mondiaux (WMB). WMB a commenc\u00e9 en tant que Ligue radio nazar\u00e9enne en 1944 et s&rsquo;est \u00e9largie pour devenir un r\u00e9seau mondial de programmes contextualis\u00e9s pour les auditeurs et les t\u00e9l\u00e9spectateurs du monde entier.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d3f1e4 e-flex e-con-boxed e-con e-parent\" data-id=\"4d3f1e4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-83e2c1c e-flex e-con-boxed e-con e-child\" data-id=\"83e2c1c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9899a8b e-flex e-con-boxed e-con e-parent\" data-id=\"9899a8b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8db91c1 e-con-full e-flex e-con e-child\" data-id=\"8db91c1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c6c6e9 elementor-widget elementor-widget-heading\" data-id=\"5c6c6e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Liens rapides<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c07c2c2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c07c2c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4bc38da e-con-full e-flex e-con e-child\" data-id=\"4bc38da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<a class=\"elementor-element elementor-element-f128f2f e-con-full e-transform e-flex e-con e-child\" data-id=\"f128f2f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/give.nazarene.org\/donate\/world-mission-broadcast\" target=\"_blank\">\n\t\t<div class=\"elementor-element elementor-element-3f05af0 e-con-full e-flex e-con e-child\" data-id=\"3f05af0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e89ed4 elementor-widget elementor-widget-heading\" data-id=\"6e89ed4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Donner en ligne<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-715d684 e-con-full e-flex e-con e-child\" data-id=\"715d684\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87a08f3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"87a08f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-571a414 e-con-full e-transform e-flex e-con e-child\" data-id=\"571a414\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/nazarene.org\/wmb-promotional-resources\" target=\"_blank\">\n\t\t<div class=\"elementor-element elementor-element-fac1f85 e-con-full e-flex e-con e-child\" data-id=\"fac1f85\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c40b22d elementor-widget elementor-widget-heading\" data-id=\"c40b22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ressources promotionnelles WMB<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20c6463 e-con-full e-flex e-con e-child\" data-id=\"20c6463\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9bbcb0f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9bbcb0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-f84a0e8 e-con-full e-transform e-flex e-con e-child\" data-id=\"f84a0e8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/nazarene.org\/fr\/prendre-en-charge-wmb\/\" target=\"_blank\">\n\t\t<div class=\"elementor-element elementor-element-3ff022b e-con-full e-flex e-con e-child\" data-id=\"3ff022b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e1e1784 elementor-widget elementor-widget-heading\" data-id=\"e1e1784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prendre en charge WMB<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-612a717 e-con-full e-flex e-con e-child\" data-id=\"612a717\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5877a7b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5877a7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-f27969e e-con-full e-transform elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-mobile e-flex e-con e-child\" data-id=\"f27969e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;_transform_scale_effect_hover_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:1.02,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scale_effect_hover_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" href=\"https:\/\/resources.nazarene.org\/index.php\/s\/FAqp9gDAMoZ6LNH\" target=\"_blank\">\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b6d646 e-con-full e-flex e-con e-parent\" data-id=\"4b6d646\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-50f4918 e-flex e-con-boxed e-con e-child\" data-id=\"50f4918\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-09132e5 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"09132e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Maintenant plus que jamais, nous nous accrochons aux connexions tout autour de nous, renfor\u00e7ant notre sens de la communaut\u00e9. Gr\u00e2ce \u00e0 la technologie d&rsquo;aujourd&rsquo;hui, nous sommes capables de nous connecter \u00e0 d&rsquo;autres personnes du monde entier et de diffuser pour le mieux. Maintenant plus que jamais, il est temps de se recentrer et de partager le message d&rsquo;espoir en J\u00e9sus.<\/p><p>Mission mondiale Broadcast souhaite cr\u00e9er un lieu o\u00f9 les gens du monde entier peuvent se connecter les uns aux autres \u00e0 un moment o\u00f9 cela est n\u00e9cessaire plus que jamais. Nous d\u00e9passons les fronti\u00e8res et les obstacles pour partager la lumi\u00e8re de J\u00e9sus dans les coins sombres de notre monde.<\/p><p>Maintenant plus que jamais, il est important d&rsquo;\u00e9quiper nos minist\u00e8res de partenariat des outils dont ils ont besoin pour continuer \u00e0 se connecter aux autres malgr\u00e9 cette p\u00e9riode d&rsquo;incertitude.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b45eedc e-con-full e-flex e-con e-parent\" data-id=\"b45eedc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-f6f0705 e-con-full e-flex e-con e-child\" data-id=\"f6f0705\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16222ef e-con-full e-flex e-con e-child\" data-id=\"16222ef\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fe1fb62 e-con-full e-flex e-con e-child\" data-id=\"fe1fb62\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ae18d1c elementor-widget elementor-widget-text-editor\" data-id=\"ae18d1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Plantation d&rsquo;\u00e9glises pendant une pand\u00e9mie &#8211; Papouasie-Nouvelle-Guin\u00e9e<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c5970 elementor-widget elementor-widget-text-editor\" data-id=\"73c5970\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les partenaires de Mission mondiale Broadcast en Papouasie-Nouvelle-Guin\u00e9e ont \u00e9tabli leur minist\u00e8re radio en 2002 dans l&rsquo;objectif d&rsquo;\u00e9vang\u00e9liser et de faire du disciple. Ils ont trois programmes qu&rsquo;ils produisent :<br><br> \u00ab Cry of women \u00bb : vise \u00e0 atteindre les femmes qui subissent de la violence, des abus et la polygamie par le biais de sketches dramatis\u00e9es.<br><br>\u00ab Commencer une bonne vie \u00bb : vise \u00e0 atteindre les jeunes de la nation pour leur apporter espoir et encouragement par la Parole de Dieu.<br><br>\u00ab Le Christ aime tous les enfants \u00bb : vise \u00e0 atteindre les enfants de 7 \u00e0 13 ans par des histoires bibliques dramatis\u00e9es et des t\u00e9moignages de vie r\u00e9elle d&rsquo;enfants alors qu&rsquo;ils apprennent \u00e0 conna\u00eetre J\u00e9sus comme leur Sauveur et ami.<br><br>Cette ann\u00e9e, le minist\u00e8re c\u00e9l\u00e8bre une \u00e9glise qu&rsquo;il a pu planter et ses 27 nouveaux membres. Ils se r\u00e9jouissent \u00e9galement qu&rsquo;une autre \u00e9glise ait pu \u00eatre plant\u00e9e par un homme d&rsquo;affaires et un homme politique local. Les deux b\u00e2timents ont \u00e9t\u00e9 d\u00e9di\u00e9s en d\u00e9cembre 2020.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74eb560 e-con-full e-flex e-con e-parent\" data-id=\"74eb560\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-5b360b1 e-con-full e-flex e-con e-child\" data-id=\"5b360b1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7b9b1f e-con-full e-flex e-con e-child\" data-id=\"d7b9b1f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d8fd2ea e-con-full e-flex e-con e-child\" data-id=\"d8fd2ea\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b0e272 elementor-widget elementor-widget-text-editor\" data-id=\"9b0e272\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Un retour \u00e0 la radio au Moyen-Orient &#8211; Beyrouth, Liban<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16ee56a elementor-widget elementor-widget-text-editor\" data-id=\"16ee56a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour la premi\u00e8re fois au Moyen-Orient, une station de radio \u00e9vang\u00e9lique chr\u00e9tienne a \u00e9t\u00e9 lanc\u00e9e en novembre 2020. Be Light FM (105.6 FM) est la premi\u00e8re station de radio \u00e9vang\u00e9lique de langue arabe bas\u00e9e au Liban et s&rsquo;associe maintenant \u00e0 Mission mondiale Broadcast.<\/p><p>Apr\u00e8s 16 ans de production de programmes t\u00e9l\u00e9vis\u00e9s et de podcasts, WMB diffuse maintenant sa production sur Be Light FM, en commen\u00e7ant par la premi\u00e8re \u00e9mission de radio diffus\u00e9e sur TransWorld Radio en 2004 jusqu&rsquo;au programme t\u00e9l\u00e9vis\u00e9 le plus r\u00e9cent produit en 2019 \u00e0 la t\u00e9l\u00e9vision. C&rsquo;est une b\u00e9n\u00e9diction pour les minist\u00e8res des m\u00e9dias nazar\u00e9ens au Moyen-Orient de rejoindre encore plus de gens dans le monde arabe par le biais de la premi\u00e8re station de radio \u00e9vang\u00e9lique au Liban.<\/p><p>Le pasteur Ayman Kafrouny continue de diriger le minist\u00e8re de la t\u00e9l\u00e9vision arabe dans le monde entier. Une nouvelle saison de \u00ab Esalouni An Yasouh \u00bb (Demandez-moi \u00e0 propos de J\u00e9sus) est actuellement en production. Le programme t\u00e9l\u00e9vis\u00e9, qui \u00e9tait \u00e0 l&rsquo;origine un programme sp\u00e9cial de car\u00eame de 40 \u00e9pisodes, est maintenant une s\u00e9rie hebdomadaire qui comprend un \u00e9pisode interactif en direct chaque mois. Dans un nouvel accord de partenariat, le minist\u00e8re d\u00e9placera \u00e9galement la production et la diffusera sur un nouveau r\u00e9seau satellite mondial, Le Royaume Sat d&rsquo;Atlanta, G\u00e9orgie en 2021.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34b94e5 e-con-full e-flex e-con e-parent\" data-id=\"34b94e5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-5ddf73f e-con-full e-flex e-con e-child\" data-id=\"5ddf73f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7e4d35 e-con-full e-flex e-con e-child\" data-id=\"c7e4d35\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b3b4ec5 e-con-full e-flex e-con e-child\" data-id=\"b3b4ec5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad5641b elementor-widget elementor-widget-text-editor\" data-id=\"ad5641b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Lorsque la porte se ferme, vous pivot &#8211; Am\u00e9rique latine<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bd8c12 elementor-widget elementor-widget-text-editor\" data-id=\"8bd8c12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les planteurs d&rsquo;\u00e9glises Marcelo Fretes et Viviana Perez sont partenaires de World Mission Broadcast depuis pr\u00e8s de 20 ans. Lorsque la pand\u00e9mie a ferm\u00e9 les portes de leur \u00e9glise, ils ont lanc\u00e9 EsperanzaHoy.net (EspoirAujourd&rsquo;hui) pour le disciple mondial, atteignant non seulement leur jeune congr\u00e9gation mais le monde hispanophone.<br><br>Par le biais du site Web et des m\u00e9dias sociaux, ils partagent des d\u00e9votions graphiques et organisent des discussions en direct chaque semaine, au-del\u00e0 de leurs flux de service dominicaux. Leur minist\u00e8re est devenu mondial, avec des gens de diverses r\u00e9gions, y compris des tsiganes analphab\u00e8tes en Argentine et un m\u00e9decin au P\u00e9rou, s&rsquo;engageant dans le contenu.<br><br>Un coiffeur nomm\u00e9 Evan est venu au Christ par leur minist\u00e8re et a maintenant un impact sur sa communaut\u00e9. Ils ont m\u00eame re\u00e7u des encouragements de l&rsquo;\u00e9vang\u00e9liste Luis Palau \u00e0 poursuivre leurs efforts.<br><br>Des plans sont en cours pour deux nouveaux packages d\u00e9votionnels num\u00e9riques pour les \u00e9glises, \u00e9largissant leur port\u00e9e. Mission mondiale diffus\u00e9e continue de partager l&rsquo;espoir d&rsquo;un Dieu aimant et immuable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mission mondiale diffus\u00e9e Des milliers de vies sont transform\u00e9es par le travail du Saint-Esprit et les programmes missionnaires mondiaux (WMB). WMB a commenc\u00e9 en tant que Ligue radio nazar\u00e9enne en 1944 et s&rsquo;est \u00e9largie pour devenir un r\u00e9seau mondial de programmes contextualis\u00e9s pour les auditeurs et les t\u00e9l\u00e9spectateurs du monde entier. Liens rapides Donner en [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"content-type":"","_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"class_list":["post-37765","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mission mondiale diffus\u00e9e - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mission mondiale diffus\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Mission mondiale diffus\u00e9e Des milliers de vies sont transform\u00e9es par le travail du Saint-Esprit et les programmes missionnaires mondiaux (WMB). WMB a commenc\u00e9 en tant que Ligue radio nazar\u00e9enne en 1944 et s&rsquo;est \u00e9largie pour devenir un r\u00e9seau mondial de programmes contextualis\u00e9s pour les auditeurs et les t\u00e9l\u00e9spectateurs du monde entier. Liens rapides Donner en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T03:33:01+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/mission-mondiale-diffusee\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/mission-mondiale-diffusee\\\/\",\"name\":\"Mission mondiale diffus\u00e9e - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"datePublished\":\"2025-02-20T16:43:01+00:00\",\"dateModified\":\"2026-02-26T03:33:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/mission-mondiale-diffusee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/mission-mondiale-diffusee\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/mission-mondiale-diffusee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mission mondiale diffus\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mission mondiale diffus\u00e9e - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/","og_locale":"fr_FR","og_type":"article","og_title":"Mission mondiale diffus\u00e9e","og_description":"Mission mondiale diffus\u00e9e Des milliers de vies sont transform\u00e9es par le travail du Saint-Esprit et les programmes missionnaires mondiaux (WMB). WMB a commenc\u00e9 en tant que Ligue radio nazar\u00e9enne en 1944 et s&rsquo;est \u00e9largie pour devenir un r\u00e9seau mondial de programmes contextualis\u00e9s pour les auditeurs et les t\u00e9l\u00e9spectateurs du monde entier. Liens rapides Donner en [&hellip;]","og_url":"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","article_modified_time":"2026-02-26T03:33:01+00:00","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/","url":"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/","name":"Mission mondiale diffus\u00e9e - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"datePublished":"2025-02-20T16:43:01+00:00","dateModified":"2026-02-26T03:33:01+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/mission-mondiale-diffusee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Mission mondiale diffus\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/pages\/37765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/comments?post=37765"}],"version-history":[{"count":1,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/pages\/37765\/revisions"}],"predecessor-version":[{"id":67943,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/pages\/37765\/revisions\/67943"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=37765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}