{"id":50660,"date":"2020-03-10T00:00:00","date_gmt":"2020-03-10T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/"},"modified":"2020-03-10T00:00:00","modified_gmt":"2020-03-10T05:00:00","slug":"les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants","status":"publish","type":"news","link":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/","title":{"rendered":"Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants"},"content":{"rendered":"<p>Une \u00e9quipe de Travail et t\u00e9moin du district du Texas ouest a servi \u00e0 la fronti\u00e8re sud \u00e0 Tapachula, Chiapas, Mexique. L&rsquo;\u00e9quipe consistait de 14 personnes repr\u00e9sentant cinq \u00c9glises de district.<\/p>\n<p>L&rsquo;\u00e9quipe a travaill\u00e9 pendant les matins avec les congr\u00e9gations locales \u00e0 la convention de district et au camp. Ils ont aid\u00e9 \u00e0 pr\u00e9parer la terre pour la construction d&rsquo;une salle \u00e0 manger et ils ont paysag\u00e9 et construit les structures de renforcement pour le b\u00e2timent.<\/p>\n<p>Au cours de l&rsquo;ann\u00e9e derni\u00e8re, plusieurs \u00c9glises \u00e0 Tapachula ont soutenu les immigrants qui sont entr\u00e9s au Mexique et attendent leur documentation, pour rester et travailler au Mexique ou pour continuer leur voyage aux \u00c9tats-Unis ou au Canada.<\/p>\n<p>L&rsquo;\u00e9quipe du Texas ouest a rejoint les cliniques m\u00e9dicales des minist\u00e8res nazar\u00e9ens de compassion qui ont servi ces migrants en jouant avec les enfants des patients. Les cliniques m\u00e9dicales ont aid\u00e9 de nombreuses personnes qui n&rsquo;auraient pas autrement acc\u00e8s aux soins m\u00e9dicaux et dentaires. En outre, les membres de l&rsquo;\u00c9glise locale ont offert des coupes de cheveux.<\/p>\n<p>Il \u00e9tait int\u00e9ressant d&rsquo;entendre leurs histoires de voyage de leurs pays d&rsquo;origine (Ha\u00efti, pays en Afrique, Cuba, etc.) en Am\u00e9rique du Sud puis en Am\u00e9rique centrale pour atteindre le Mexique \u00bb, a d\u00e9clar\u00e9 Shelley Webb, membre de l&rsquo;\u00e9quipe Travail et t\u00e9moin.&nbsp;<\/p>\n<p>Le leader d&rsquo;\u00e9quipe Steve Pettit a pr\u00each\u00e9 dans deux services sur le sujet de l&rsquo;esclavage moderne. &nbsp;Ce probl\u00e8me n&rsquo;a pas \u00e9t\u00e9 largement discut\u00e9 dans le sud du Mexique, les leaders \u00e9taient donc int\u00e9ress\u00e9s \u00e0 conna\u00eetre des moyens d&rsquo;aider cette crise mondiale.&nbsp;<\/p>\n<p>En outre, Pettit a parl\u00e9 avec des leaders des \u00c9glises mexicaines travaillant avec des immigrants ha\u00eftiens sur la culture et les gens d&rsquo;Ha\u00efti. Pettit a servi de missionnaire en Ha\u00efti pendant deux ans.<\/p>\n<p>Le pasteur Socorro a ouvert l&rsquo;\u00c9glise (pour les immigrants ha\u00eftiens) chaque dimanche pour un lieu d&rsquo;adoration \u00bb, a d\u00e9clar\u00e9 Pettit. Ils organisent un service \u00e0 8 a.m. suivi d&rsquo;un petit-d\u00e9jeuner que leurs gens paient [pour]. Il transporte \u00e9galement environ 70 d&rsquo;entre eux chaque semaine et le fait lui-m\u00eame et tout cela avant son propre service \u00e0 10 heures. \u00ab\u00a0<\/p>\n<p>Shelley Webb a d\u00e9clar\u00e9 que certaines des \u00c9glises dans le district du Texas ouest pr\u00e9voient de revenir au district de fronti\u00e8re sud pour continuer \u00e0 construire les relations qui ont \u00e9t\u00e9 initi\u00e9es par cette premi\u00e8re \u00e9quipe.<\/p>\n<p>L&rsquo;\u00e9quipe du Texas comprenait quatre jeunes, y compris Bailey, 17.&nbsp;<\/p>\n<p>Il n&rsquo;\u00e9tait qu&rsquo;une semaine \u00bb, a d\u00e9clar\u00e9 Bailey. Une semaine de travail dans le camp. Une semaine de jeu avec les enfants. Une semaine pour essayer toute la nourriture mexicaine nouvelle et authentique. Mais dans cette semaine, j&rsquo;ai vu Dieu dans le monde plus que je l&rsquo;ai vu dans toute ma vie. J&rsquo;ai vu des gens passionn\u00e9s et des amoureux de Dieu partout o\u00f9 j&rsquo;ai regard\u00e9. J&rsquo;ai vu une \u00e9nergie \u00e0 Tapachula que je voulais prendre \u00e0 la maison. Il n&rsquo;\u00e9tait qu&rsquo;une semaine, mais c&rsquo;\u00e9tait l&rsquo;exp\u00e9rience d&rsquo;une vie. \u00ab\u00a0<\/p>\n<p><a href=\"https:\/\/www.mesoamericaregion.org\">\u00c9glise de la M\u00e9so-Am\u00e9rique nazar\u00e9enne<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une \u00e9quipe de Travail et t\u00e9moin du district du Texas ouest a servi \u00e0 la fronti\u00e8re sud \u00e0 Tapachula, Chiapas, Mexique. L&rsquo;\u00e9quipe consistait de 14 personnes repr\u00e9sentant cinq \u00c9glises de district. L&rsquo;\u00e9quipe a travaill\u00e9 pendant les matins avec les congr\u00e9gations locales \u00e0 la convention de district et au camp. Ils ont aid\u00e9 \u00e0 pr\u00e9parer la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25643,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[1471,862,1584],"class_list":["post-50660","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-mexique","news-tag-region-de-meso-amerique","news-tag-texas-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants\" \/>\n<meta property=\"og:description\" content=\"Une \u00e9quipe de Travail et t\u00e9moin du district du Texas ouest a servi \u00e0 la fronti\u00e8re sud \u00e0 Tapachula, Chiapas, Mexique. L&rsquo;\u00e9quipe consistait de 14 personnes repr\u00e9sentant cinq \u00c9glises de district. L&rsquo;\u00e9quipe a travaill\u00e9 pendant les matins avec les congr\u00e9gations locales \u00e0 la convention de district et au camp. Ils ont aid\u00e9 \u00e0 pr\u00e9parer la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\\\/\",\"name\":\"Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mexico-WW.jpg\",\"datePublished\":\"2020-03-10T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mexico-WW.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mexico-WW.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/","og_locale":"fr_FR","og_type":"article","og_title":"Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants","og_description":"Une \u00e9quipe de Travail et t\u00e9moin du district du Texas ouest a servi \u00e0 la fronti\u00e8re sud \u00e0 Tapachula, Chiapas, Mexique. L&rsquo;\u00e9quipe consistait de 14 personnes repr\u00e9sentant cinq \u00c9glises de district. L&rsquo;\u00e9quipe a travaill\u00e9 pendant les matins avec les congr\u00e9gations locales \u00e0 la convention de district et au camp. Ils ont aid\u00e9 \u00e0 pr\u00e9parer la [&hellip;]","og_url":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/","url":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/","name":"Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Mexico-WW.jpg","datePublished":"2020-03-10T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Mexico-WW.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Mexico-WW.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/news\/les-eglises-frontalieres-du-mexique-font-equipe-avec-le-district-du-texas-pour-servir-les-migrants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Les \u00c9glises frontali\u00e8res du Mexique font \u00e9quipe avec le district du Texas pour servir les migrants"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/50660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/50660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/25643"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=50660"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-categories?post=50660"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-region-taxonomy?post=50660"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-tag?post=50660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}