{"id":50539,"date":"2020-04-17T00:00:00","date_gmt":"2020-04-17T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/"},"modified":"2020-04-17T00:00:00","modified_gmt":"2020-04-17T05:00:00","slug":"couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux","status":"publish","type":"news","link":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/","title":{"rendered":"Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux"},"content":{"rendered":"<p>Jes\u00fas Alberto L\u00f3pez Chevez et Brenda Ovando Torres, un couple de la Premi\u00e8re \u00c9glise du Nazar\u00e9en \u00e0 Tuxtla Guti\u00e9rrez, Mexique, utilisent leurs comp\u00e9tences pour cr\u00e9er des masques de protection pour le personnel m\u00e9dical, gratuitement.<\/p>\n<p>Le couple a \u00e9t\u00e9 inspir\u00e9 par la parabole des talents dans Marc 25 pour servir les autres par leur profession. Jes\u00fas est un ing\u00e9nieur m\u00e9canique et Brenda est un ing\u00e9nieur industriel.<\/p>\n<p>Ils sont des jeunes tr\u00e8s compatissants et il a toujours \u00e9t\u00e9 clair pour eux que leur vocation est un don de Dieu \u00bb, a d\u00e9clar\u00e9 Edi Montejo des Minist\u00e8res nazar\u00e9ens de compassion du Mexique.<\/p>\n<p>Apr\u00e8s avoir vu des histoires sur les m\u00e9dias sociaux et les nouvelles qu&rsquo;il y avait une p\u00e9nurie d&rsquo;\u00e9quipement de protection de base dans les h\u00f4pitaux, ils savaient qu&rsquo;ils pouvaient aider \u00e0 s&rsquo;assurer que le personnel m\u00e9dical a re\u00e7u des masques de visage demand\u00e9s de mani\u00e8re urgente.&nbsp;<\/p>\n<p>Chaque masque visage imprim\u00e9 3D a un temps de production de 1,4 heure. Les mat\u00e9riaux requis sont une bande \u00e9lastique, une feuille d&rsquo;ac\u00e9tate et un filament PLA (mat\u00e9riau plastique biod\u00e9gradable).&nbsp;<\/p>\n<p>Il y a quelques jours, Silvia Santiago, coordonnateur du district NCM sud du Mexique, a mis le couple en contact avec le minist\u00e8re de la Sant\u00e9 de la municipalit\u00e9 d&rsquo;Independencia, Chiapas. Silvia, avec l&rsquo;aide d&rsquo;autres femmes dans l&rsquo;\u00c9glise, a obtenu le mat\u00e9riel pour l&rsquo;assemblage de 15 masques protecteurs, qui sont d\u00e9j\u00e0 entre les mains de professionnels de la sant\u00e9.&nbsp;<\/p>\n<p>Sans un doute, dans ces moments de crises de sant\u00e9, ce sera toujours un plaisir d&rsquo;entendre des t\u00e9moignages de jeunes qui aident la soci\u00e9t\u00e9 et partagent l&rsquo;amour de J\u00e9sus-Christ par sa vocation, c&rsquo;est-\u00e0-dire \u00e0 vivre la compassion comme mode de vie \u00bb, a d\u00e9clar\u00e9 Montejo.&nbsp;<\/p>\n<p>Continuons \u00e0 prier pour cette situation qui affecte de nombreuses nations ; prions pour les professionnels de la sant\u00e9 et leurs familles. Au milieu de cette pand\u00e9mie, notre bon Dieu est en contr\u00f4le ; faisons l&rsquo;espoir de J\u00e9sus-Christ contagieux, pas la peur. \u00ab\u00a0<\/p>\n<p><a href=\"www.mesoamericaregion.org\">\u00c9glise de la M\u00e9so-Am\u00e9rique nazar\u00e9enne<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un couple d&rsquo;ing\u00e9nieurs du Mexique utilise leurs talents pour faire des masques pour le personnel m\u00e9dical, gratuitement.<\/p>\n","protected":false},"author":1,"featured_media":25783,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[2338,1375,1471],"class_list":["post-50539","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-coronavirus-fr","news-tag-meso-amerique","news-tag-mexique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux\" \/>\n<meta property=\"og:description\" content=\"Un couple d&#039;ing\u00e9nieurs du Mexique utilise leurs talents pour faire des masques pour le personnel m\u00e9dical, gratuitement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\\\/\",\"name\":\"Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mexico-Couple.jpg\",\"datePublished\":\"2020-04-17T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mexico-Couple.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Mexico-Couple.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux","og_description":"Un couple d'ing\u00e9nieurs du Mexique utilise leurs talents pour faire des masques pour le personnel m\u00e9dical, gratuitement.","og_url":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/","url":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/","name":"Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Mexico-Couple.jpg","datePublished":"2020-04-17T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Mexico-Couple.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Mexico-Couple.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/news\/couple-nazareen-au-mexique-font-des-masques-pour-les-travailleurs-de-la-sante-locaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Couple nazar\u00e9en au Mexique font des masques pour les travailleurs de la sant\u00e9 locaux"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/50539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/50539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/25783"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=50539"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-categories?post=50539"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-region-taxonomy?post=50539"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-tag?post=50539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}