{"id":49726,"date":"2020-09-15T00:00:00","date_gmt":"2020-09-15T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/"},"modified":"2020-09-15T00:00:00","modified_gmt":"2020-09-15T05:00:00","slug":"aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19","status":"publish","type":"news","link":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/","title":{"rendered":"Aide de l&rsquo;\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19"},"content":{"rendered":"<p><i>Iglesia del Nazareno Servidores de Dios<\/i>, \u00e0 Madriz, Nicaragua, sert activement les personnes avec des besoins apport\u00e9s par la pand\u00e9mie de COVID-19. Chaque semaine, ils partagent de la nourriture et des articles d&rsquo;hygi\u00e8ne personnelle avec des familles \u00e0 faible revenu qui ont \u00e9t\u00e9 impact\u00e9es par la pand\u00e9mie de diverses fa\u00e7ons.<\/p>\n<p>L&rsquo;\u00c9glise re\u00e7oit de la nourriture de la Banque alimentaire du Nicaragua en plus des articles d&rsquo;hygi\u00e8ne tels que la cr\u00e8me de rasage, le shampooing, le savon et le d\u00e9odorant. Les articles sont ensuite organis\u00e9s dans des paquets par un groupe de membres de l&rsquo;\u00c9glise coordonn\u00e9s par Marta Moreno, pr\u00e9sident des &nbsp;minist\u00e8res de compassion de l&rsquo;\u00c9glise et femme du pasteur de l&rsquo;\u00c9glise, Evelio D\u00edaz. Chaque semaine, l&rsquo;\u00e9quipe distribue des packets aux familles dans le besoin.<\/p>\n<p>Cent cinquante familles ont b\u00e9n\u00e9fici\u00e9, qui ont tous des ressources \u00e9conomiques rares. Parmi eux il y a des membres de l&rsquo;\u00c9glise locale et des \u00c9glises voisines, des gens de la communaut\u00e9 environnante et les sans-abri. Des 150 familles b\u00e9n\u00e9ficiaires, 50 re\u00e7oivent en permanence le package d&rsquo;approvisionnement chaque mois.<\/p>\n<p>Je remercie Dieu d&rsquo;avoir des gens qui pratiquent l&rsquo;amour du Seigneur par la compassion, puisque dans le monde et dans notre pays, en raison de la pand\u00e9mie, de nombreuses familles ont \u00e9t\u00e9 au ch\u00f4mage \u00bb, a d\u00e9clar\u00e9 Blanca P\u00e9rez, un membre de l&rsquo;\u00c9glise qui a re\u00e7u de l&rsquo;aide. Je suis un membre de l&rsquo;\u00c9glise des Servidores de Dios dans la ville de Somoto et un r\u00e9sident de l&rsquo;un des secteurs les plus pauvres et j&rsquo;ai b\u00e9n\u00e9fici\u00e9 de ce beau projet. Nous sommes une famille de quatre et nous sommes tr\u00e8s reconnaissants \u00e0 Dieu et \u00e0 l&rsquo;\u00c9glise qui rend possible d&rsquo;avoir de la nourriture sur notre table. \u00ab\u00a0<\/p>\n<p>D\u00edaz croit que l&#8217;emphase de son \u00c9glise sur la compassion a conduit la congr\u00e9gation \u00e0 tendre la main \u00e0 ceux qui sont dans le besoin autour d&rsquo;eux.<\/p>\n<p>La compassion est un sentiment qui vous conduit \u00e0 s&rsquo;impliquer, vous engage de votre c\u0153ur \u00e0 se rapprocher et agir au milieu de la r\u00e9alit\u00e9 \u00bb, a d\u00e9clar\u00e9 D\u00edaz.<\/p>\n<p><a href=\"http:\/\/www.mesoamericaregion.org\/\" target=\"_blank\">\u00c9glise de la r\u00e9gion nazar\u00e9enne de M\u00e9so-Am\u00e9rique<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iglesia del Nazareno Servidores de Dios partage de la nourriture et des articles d&rsquo;hygi\u00e8ne personnelle avec des familles \u00e0 faible revenu qui ont \u00e9t\u00e9 impact\u00e9es par la pand\u00e9mie de diverses fa\u00e7ons.<\/p>\n","protected":false},"author":1,"featured_media":26479,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[2338,1756,862],"class_list":["post-49726","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-coronavirus-fr","news-tag-nicaragua-fr","news-tag-region-de-meso-amerique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aide de l&#039;\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19 - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aide de l&#039;\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19\" \/>\n<meta property=\"og:description\" content=\"Iglesia del Nazareno Servidores de Dios partage de la nourriture et des articles d&#039;hygi\u00e8ne personnelle avec des familles \u00e0 faible revenu qui ont \u00e9t\u00e9 impact\u00e9es par la pand\u00e9mie de diverses fa\u00e7ons.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\\\/\",\"name\":\"Aide de l'\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19 - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Nicaragua-Feature.png\",\"datePublished\":\"2020-09-15T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Nicaragua-Feature.png\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Nicaragua-Feature.png\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aide de l&#8217;\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aide de l'\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19 - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/","og_locale":"fr_FR","og_type":"article","og_title":"Aide de l'\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19","og_description":"Iglesia del Nazareno Servidores de Dios partage de la nourriture et des articles d'hygi\u00e8ne personnelle avec des familles \u00e0 faible revenu qui ont \u00e9t\u00e9 impact\u00e9es par la pand\u00e9mie de diverses fa\u00e7ons.","og_url":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/","url":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/","name":"Aide de l'\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19 - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Nicaragua-Feature.png","datePublished":"2020-09-15T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Nicaragua-Feature.png","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Nicaragua-Feature.png","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/news\/aide-de-leglise-du-nicaragua-congregation-a-risque-membres-de-la-communaute-pendant-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Aide de l&#8217;\u00c9glise du Nicaragua congr\u00e9gation \u00e0 risque, membres de la communaut\u00e9 pendant COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/49726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/49726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/26479"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=49726"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-categories?post=49726"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-region-taxonomy?post=49726"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-tag?post=49726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}