{"id":49576,"date":"2020-10-15T00:00:00","date_gmt":"2020-10-15T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/"},"modified":"2020-10-15T00:00:00","modified_gmt":"2020-10-15T05:00:00","slug":"district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie","status":"publish","type":"news","link":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/","title":{"rendered":"District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie"},"content":{"rendered":"<p>Malgr\u00e9 les difficult\u00e9s \u00e9conomiques apport\u00e9es par la pand\u00e9mie de COVID-19, l&rsquo;\u00c9glise est en mouvement dans le district de Mexique Oaxaca.&nbsp;<\/p>\n<p>Au mois de septembre, le surintendant de district d&rsquo;Oaxaca Nicol\u00e1s Guzm\u00e1n a pr\u00e9sid\u00e9 plusieurs r\u00e9unions de fin d&rsquo;ann\u00e9e de l&rsquo;\u00c9glise dans le district, qui a 80 \u00c9glises organis\u00e9es et plus de 7 000 membres.&nbsp;<\/p>\n<p>Les gens dans les communaut\u00e9s ont montr\u00e9 un grand engagement au travail de Dieu en donnant leur offre \u00bb, Guzm\u00e0n. Ils participent \u00e9galement \u00e0 toutes les activit\u00e9s de l&rsquo;\u00c9glise et chaque fois que les leaders de district visitent [la communaut\u00e9] cela me rend tr\u00e8s heureux. \u00ab\u00a0<\/p>\n<p>Dans la communaut\u00e9 de Rinc\u00f3n Ju\u00e1rez, une petite communaut\u00e9 de p\u00eache avec des ressources \u00e9conomiques tr\u00e8s limit\u00e9es, Nicol\u00e1s \u00e9tait pr\u00e9par\u00e9 \u00e0 entendre des histoires de la fa\u00e7on dont l&rsquo;\u00c9glise n&rsquo;\u00e9tait pas capable de r\u00e9pondre \u00e0 leurs budgets en raison de l&rsquo;impact financier du COVID-19. Au lieu de cela, l&rsquo;\u00c9glise l&rsquo;a accueilli avec leur offre de district et offre d&rsquo;\u00e9vang\u00e9lisation mondiale dans des sacs en plastique. Nicolas a dit qu&rsquo;il a \u00e9t\u00e9 rappel\u00e9 de l&rsquo;\u00c9glise philippine qui a soutenu l&rsquo;ap\u00f4tre Paul.<\/p>\n<p>Dieu a b\u00e9ni notre district \u00bb, a d\u00e9clar\u00e9 Guzm\u00e1n. M\u00eame au milieu de la pand\u00e9mie, une fois de plus, nous avons vu des miracles arriver. L&rsquo;ann\u00e9e derni\u00e8re, nous n&rsquo;avons soulev\u00e9 que 80 pour cent de nos budgets annuels, mais cette ann\u00e9e, nous avons soulev\u00e9 93 pour cent. \u00c0 cause de cela, nous sommes capables d&rsquo;envoyer plus [de fonds] au WEF. Dieu est toujours fid\u00e8le. \u00ab\u00a0<\/p>\n<p>Dans un autre voyage cette semaine-l\u00e0, Guzm\u00e1n a visit\u00e9 Shaddai, une \u00c9glise de type mission situ\u00e9e \u00e0 Tehuantepec. Il y a un peu plus d&rsquo;un an, les leaders de ce nouveau travail lui ont dit qu&rsquo;ils \u00ab semaient \u00bb des colonnes de b\u00e9ton par la foi alors qu&rsquo;ils n&rsquo;\u00e9taient pas s\u00fbrs de la fa\u00e7on dont ils seraient capables de lever des fonds pour progresser avec la construction. Malgr\u00e9 les difficult\u00e9s \u00e9conomiques auxquelles leur communaut\u00e9 est confront\u00e9e, l&rsquo;\u00c9glise a \u00e9t\u00e9 capable de verser le sol en b\u00e9ton et vient de finir de mettre sur le toit. Bien qu&rsquo;il ne soit pas encore une \u00c9glise organis\u00e9e, ils ont 50 personnes se r\u00e9unissant l\u00e0.<\/p>\n<p><a href=\"mesoamericaregion.org\">\u00c9glise de la r\u00e9gion nazar\u00e9enne de M\u00e9so-Am\u00e9rique<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malgr\u00e9 les difficult\u00e9s \u00e9conomiques apport\u00e9es par la pand\u00e9mie de COVID-19, le district du Mexique Oaxaca a d\u00e9pass\u00e9 le don de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente aux budgets de district et au Fonds d&rsquo;\u00e9vang\u00e9lisation mondial.<\/p>\n","protected":false},"author":1,"featured_media":26599,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[2338,2376,1471,862],"class_list":["post-49576","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-coronavirus-fr","news-tag-generosite","news-tag-mexique","news-tag-region-de-meso-amerique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie\" \/>\n<meta property=\"og:description\" content=\"Malgr\u00e9 les difficult\u00e9s \u00e9conomiques apport\u00e9es par la pand\u00e9mie de COVID-19, le district du Mexique Oaxaca a d\u00e9pass\u00e9 le don de l&#039;ann\u00e9e pr\u00e9c\u00e9dente aux budgets de district et au Fonds d&#039;\u00e9vang\u00e9lisation mondial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\\\/\",\"name\":\"District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Moneybags.png\",\"datePublished\":\"2020-10-15T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Moneybags.png\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Moneybags.png\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/","og_locale":"fr_FR","og_type":"article","og_title":"District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie","og_description":"Malgr\u00e9 les difficult\u00e9s \u00e9conomiques apport\u00e9es par la pand\u00e9mie de COVID-19, le district du Mexique Oaxaca a d\u00e9pass\u00e9 le don de l'ann\u00e9e pr\u00e9c\u00e9dente aux budgets de district et au Fonds d'\u00e9vang\u00e9lisation mondial.","og_url":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/","url":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/","name":"District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Moneybags.png","datePublished":"2020-10-15T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Moneybags.png","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Moneybags.png","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/news\/district-du-mexique-oaxaca-rapporte-donner-une-augmentation-malgre-la-pandemie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"District du Mexique Oaxaca rapporte donner une augmentation malgr\u00e9 la pand\u00e9mie"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/49576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/49576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/26599"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=49576"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-categories?post=49576"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-region-taxonomy?post=49576"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-tag?post=49576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}