{"id":46821,"date":"2021-10-01T00:00:00","date_gmt":"2021-10-01T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/"},"modified":"2021-10-01T00:00:00","modified_gmt":"2021-10-01T05:00:00","slug":"la-generosite-seme-des-graines-de-lespoir-transformant-du-christ","status":"publish","type":"news","link":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/","title":{"rendered":"La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l&rsquo;espoir transformant du Christ"},"content":{"rendered":"<p>En tant que chr\u00e9tiens, nous sommes appel\u00e9s \u00e0 \u00eatre ambassadeurs du Royaume dans le monde entier. Et en tant que \u00c9glise mondiale du Nazar\u00e9en, vous faites exactement cela. En fait, vous s\u00e8me des graines de l&rsquo;espoir transformant du Christ non seulement dans vos propres communaut\u00e9s &nbsp;mais \u00e9galement \u00e0 de nombreuses personnes \u00e0 des milliers de miles de distance.<\/p>\n<p>\u00c0 Chiang Mai, Tha\u00eflande, l&rsquo;\u00c9cole de la promesse aide les enfants \u00e0 apprendre de mani\u00e8re holistique. Leur mission est de fournir aux enfants de l&rsquo;espoir et un &nbsp;avenir dans un pays en d\u00e9veloppement par le partage de l&rsquo;\u00c9vangile de J\u00e9sus-Christ et de l&rsquo;\u00e9ducation ainsi que de briser le cycle de pauvret\u00e9 et d&rsquo;oppression aux enfants. Selon la missionnaire Christine Dialing, environ 50 % des \u00e9tudiants sont consid\u00e9r\u00e9s \u00e0 risque et assistent &nbsp;et aux cours sur les bourses fournies par l&rsquo;\u00e9cole.&nbsp;<\/p>\n<p>Chacun des enfants a [ses ou sa] propres histoires \u00e0 dire \u00bb, a d\u00e9clar\u00e9 Dialing. Certaines histoires briseront votre c\u0153ur et certaines vous laisseront voir \u00e0 quel point vous \u00eates b\u00e9ni et chanceux. \u00ab\u00a0<\/p>\n<p>Composant \u00e9galement \u00e0 la Maison des enfants tribale Maetang, qui offre des cours d&rsquo;anglais aux enfants et les aide \u00e0 apprendre des histoires de la Bible. Ceux qui servent obtiennent \u00e9galement une chance de jouer avec eux et de les garder actifs.&nbsp;<\/p>\n<p>Le propre appel de Commuter aux missions est venu dans son enfance lorsqu&rsquo;elle a \u00e9t\u00e9 inspir\u00e9e par un livre missionnaire sur Susan Fitkin.&nbsp;<\/p>\n<p>L&rsquo;appel de Susan est devenu vivant dans mon c\u0153ur \u00bb, a d\u00e9clar\u00e9 Dialing. Avec des larmes dans mes yeux, j&rsquo;ai dit \u00ab Ici, je suis, envoyez-moi \u00bb. Et depuis lors, je savais un jour je serais un missionnaire. \u00ab\u00a0<\/p>\n<p>Composant aime l&rsquo;opportunit\u00e9 de partager sa vie avec ses \u00e9tudiants et de les voir apprendre et grandir ensemble dans le Seigneur.&nbsp;<\/p>\n<p>Malgr\u00e9 les ant\u00e9c\u00e9dents douloureux qu&rsquo;ils ont, il me donne beaucoup de joie \u00bb, a d\u00e9clar\u00e9 Dialing. Malgr\u00e9 les d\u00e9fis, il ne nous arr\u00eatera pas de planter la graine d&rsquo;espoir dans la vie des enfants. \u00ab\u00a0<\/p>\n<p>Chaque fois que vous priez pour l&rsquo;\u00c9glise, donnez aux missions nazar\u00e9ennes ou allez sur un voyage missionnaire, vous partagez l&rsquo;amour du Christ et aidez \u00e0 transformer des vies. Gr\u00e2ce \u00e0 votre g\u00e9n\u00e9rosit\u00e9, nous sommes capables de continuer \u00e0 r\u00e9pandre l&rsquo;amour du Christ dans tous les coins du monde, y compris en Tha\u00eflande \u00e0 l&rsquo;\u00c9cole de la promesse et \u00e0 la Maison des enfants tribale Maeteng.<\/p>\n<p>L&rsquo;\u00c9glise mondiale de la famille nazar\u00e9enne a investi et a fait une diff\u00e9rence dans ma vie \u00bb, a d\u00e9clar\u00e9 Dialing. Dans ce voyage missionnaire, je veux partager la vie que j&rsquo;ai donn\u00e9e \u00e0 mes \u00e9tudiants, avec une mission pour leur donner la meilleure \u00e9ducation pour chacun d&rsquo;eux. Ils m\u00e9ritent d&rsquo;\u00eatre donn\u00e9e de l&rsquo;importance et ils m\u00e9ritent tous de recevoir la meilleure \u00e9ducation. \u00ab\u00a0<\/p>\n<p>Les ressources sont maintenant disponibles pour &nbsp;l&rsquo;Offre de remerciement &nbsp;\u00e0 venir pour les missions nazar\u00e9ennes.&nbsp;<\/p>\n<p>Le site Web d&rsquo;offre, &nbsp;<a href=\"\/generosity\">nazarene.org\/g\u00e9n\u00e9rosit\u00e9<\/a>, comprend du mat\u00e9riel promotionnel, tel que des graphiques de m\u00e9dias sociaux, des vid\u00e9os, des affiches, des brochures, un graphique PowerPoint et des inserts de bulletin pour soutenir les \u00c9glises locales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En raison de votre g\u00e9n\u00e9rosit\u00e9, l&rsquo;\u00c9cole de la Promesse et la maison des enfants tribaux Maetang \u00e9duquent et s\u00e8ment des graines de l&rsquo;espoir transformant du Christ dans leurs \u00e9tudiants.<\/p>\n","protected":false},"author":1,"featured_media":26527,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[2210,1792,1486,2209],"class_list":["post-46821","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-fem-fr","news-tag-offre-de-remerciement","news-tag-ressources","news-tag-wef-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l&#039;espoir transformant du Christ - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l&#039;espoir transformant du Christ\" \/>\n<meta property=\"og:description\" content=\"En raison de votre g\u00e9n\u00e9rosit\u00e9, l&#039;\u00c9cole de la Promesse et la maison des enfants tribaux Maetang \u00e9duquent et s\u00e8ment des graines de l&#039;espoir transformant du Christ dans leurs \u00e9tudiants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\\\/\",\"name\":\"La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l'espoir transformant du Christ - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Give-Thanks-Article-copy-1.jpg\",\"datePublished\":\"2021-10-01T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Give-Thanks-Article-copy-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Give-Thanks-Article-copy-1.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l&#8217;espoir transformant du Christ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l'espoir transformant du Christ - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/","og_locale":"fr_FR","og_type":"article","og_title":"La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l'espoir transformant du Christ","og_description":"En raison de votre g\u00e9n\u00e9rosit\u00e9, l'\u00c9cole de la Promesse et la maison des enfants tribaux Maetang \u00e9duquent et s\u00e8ment des graines de l'espoir transformant du Christ dans leurs \u00e9tudiants.","og_url":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/","url":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/","name":"La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l'espoir transformant du Christ - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Give-Thanks-Article-copy-1.jpg","datePublished":"2021-10-01T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Give-Thanks-Article-copy-1.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Give-Thanks-Article-copy-1.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/news\/la-generosite-seme-des-graines-de-lespoir-transformant-du-christ\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"La g\u00e9n\u00e9rosit\u00e9 s\u00e8me des graines de l&#8217;espoir transformant du Christ"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/46821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/46821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/26527"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=46821"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-categories?post=46821"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-region-taxonomy?post=46821"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-tag?post=46821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}