{"id":46477,"date":"2022-03-10T00:00:00","date_gmt":"2022-03-10T06:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/"},"modified":"2022-03-10T00:00:00","modified_gmt":"2022-03-10T06:00:00","slug":"le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette","status":"publish","type":"news","link":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/","title":{"rendered":"Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette"},"content":{"rendered":"<p>Deux mois ont pass\u00e9 depuis que Typhoon Odette a d\u00e9vast\u00e9 la r\u00e9gion de Visayas centrale. Tout au long de ce temps, les \u00c9glises locales dans les r\u00e9gions affect\u00e9es ont continu\u00e9 \u00e0 s&rsquo;engager dans diff\u00e9rents programmes pour servir les divers besoins urgents des gens. &nbsp;<\/p>\n<p>Mais au milieu de ceux-ci, Dieu est au travail alors que les \u00c9glises s&rsquo;unissent pour \u00eatre les mains et les pieds de J\u00e9sus.<\/p>\n<p>\u00c0 St. Bernard, Sud Leyte, o\u00f9 les minist\u00e8res nazar\u00e9ens de compassion (NCM) a un centre de d\u00e9veloppement de l&rsquo;enfant, l&rsquo;\u00e9quipe de r\u00e9ponse en cas de catastrophe de l&rsquo;\u00c9glise locale a distribu\u00e9 de l&rsquo;eau potable, des lampes solaires, des kits d&rsquo;abri qui comprennent des b\u00e2ches, de la nourriture, des kits d&rsquo;hygi\u00e8ne et des masques. En outre, ils ont install\u00e9 des filtres \u00e0 eau dans cinq quartiers, ont ex\u00e9cut\u00e9 des programmes d&rsquo;alimentation, ont effectu\u00e9 des conseils en traumatisme et ont cr\u00e9\u00e9 des espaces amis des enfants.<\/p>\n<p>Sur l&rsquo;\u00eele \u00e0 Olango, le pasteur Josefin Ano-os de l&rsquo;\u00c9glise de roche solide du Nazar\u00e9en a d\u00e9couvert qu&rsquo;en plus de la fourniture de ressources mat\u00e9rielles, les gens d\u00e9siraient \u00eatre entendus et ont pri\u00e9 pour. L&rsquo;\u00c9glise a minist\u00e9r\u00e9 \u00e0 la communaut\u00e9 en \u00e9coutant les histoires des gens, priant pour eux et \u00e9tendant le confort et l&rsquo;encouragement.<\/p>\n<p>\u00c0 Loboc, Bohol, l&rsquo;\u00c9glise est reconnaissante pour le privil\u00e8ge de servir de mani\u00e8re holistique. Malgr\u00e9 le fait d&rsquo;\u00eatre eux-m\u00eames victimes du typhon, certains volontaires ont choisi de servir les autres qui ont \u00e9galement \u00e9t\u00e9 affect\u00e9s.<\/p>\n<p>\u00c0 Palawan, le pasteur Jerson Lumahan a appr\u00e9ci\u00e9 les \u00c9glises dans tout les Philippines et au-del\u00e0 pour leur g\u00e9n\u00e9rosit\u00e9 et pour l&rsquo;opportunit\u00e9 pour leur \u00c9glise locale de participer \u00e0 ce minist\u00e8re et de vivre vraiment la \u00ab compassion en tant que style de vie \u00bb.<\/p>\n<p>Dans la r\u00e9gion de Visayas, les espaces amis des enfants (CFS) ont \u00e9t\u00e9 cr\u00e9\u00e9s pour aider les enfants dans les communaut\u00e9s. Dans ces espaces s\u00fbrs, les enfants peuvent partager leurs histoires et traiter le traumatisme m\u00eame alors que leur esprit peut \u00eatre soulev\u00e9 par des chansons et des jeux. Ici, ils re\u00e7oivent \u00e9galement des articles essentiels comme de la nourriture et des kits d&rsquo;hygi\u00e8ne.<\/p>\n<p>Alors que le travail de secours continue dans ces zones de r\u00e9ponse en cas de catastrophe, NCM Philippines et les \u00e9quipes de r\u00e9ponse en cas de catastrophe locales planifient les prochaines \u00e9tapes et les strat\u00e9gies pour les besoins de r\u00e9adaptation \u00e0 long terme. Les \u00e9quipes voient&nbsp;the&nbsp;irefforts expressions &nbsp;tangibles de l&rsquo;amour de Dieu.<\/p>\n<p>Nous sommes reconnaissants \u00e0 nos \u00c9glises d&rsquo;\u00eatre un participant actif de ce que Dieu fait d\u00e9j\u00e0 dans ce monde bris\u00e9. Et par la gr\u00e2ce de Dieu, nous pouvons \u00eatre des agents de transformation alors que nous vivons la ressemblance avec Christ \u00bb, a d\u00e9clar\u00e9 Leody Tan Echavez, coordonnateur NCM Philippines.<\/p>\n<p>Prier pour :<\/p>\n<ul>\n<li>Le travail de secours et de r\u00e9habilitation dans les r\u00e9gions affect\u00e9es.<\/li>\n<li>Force spirituelle et physique pour les pasteurs et les \u00e9quipes de r\u00e9ponse locales en cas de catastrophe.<\/li>\n<li>Provision de ressources pour les besoins en cours dans les communaut\u00e9s affect\u00e9es.<\/li>\n<\/ul>\n<p>Pour \u00eatre partenaire de la r\u00e9ponse Typhoon Odette, vous pouvez donner au <a href=\"https:\/\/give.nazarene.org\/donate\/f\/106117\">Fonds de secours d&rsquo;urgence NCM-mondial<\/a>.<\/p>\n<p><a href=\"asiapacificregion.org\" target=\"_blank\">\u00c9glise de l&rsquo;Asie-Pacifique<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deux mois ont pass\u00e9 depuis que Typhoon Odette a d\u00e9vast\u00e9 la r\u00e9gion de Visayas centrale. Tout au long de ce temps, les \u00c9glises locales dans les r\u00e9gions affect\u00e9es ont continu\u00e9 \u00e0 s&rsquo;engager dans diff\u00e9rents programmes pour servir les divers besoins urgents des gens. <\/p>\n","protected":false},"author":1,"featured_media":28219,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[806,750],"class_list":["post-46477","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-philippines-fr","news-tag-region-asie-pacifique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette\" \/>\n<meta property=\"og:description\" content=\"Deux mois ont pass\u00e9 depuis que Typhoon Odette a d\u00e9vast\u00e9 la r\u00e9gion de Visayas centrale. Tout au long de ce temps, les \u00c9glises locales dans les r\u00e9gions affect\u00e9es ont continu\u00e9 \u00e0 s&#039;engager dans diff\u00e9rents programmes pour servir les divers besoins urgents des gens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\\\/\",\"name\":\"Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/2022-Odette-response.png\",\"datePublished\":\"2022-03-10T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/2022-Odette-response.png\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/2022-Odette-response.png\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/","og_locale":"fr_FR","og_type":"article","og_title":"Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette","og_description":"Deux mois ont pass\u00e9 depuis que Typhoon Odette a d\u00e9vast\u00e9 la r\u00e9gion de Visayas centrale. Tout au long de ce temps, les \u00c9glises locales dans les r\u00e9gions affect\u00e9es ont continu\u00e9 \u00e0 s'engager dans diff\u00e9rents programmes pour servir les divers besoins urgents des gens.","og_url":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/","url":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/","name":"Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/2022-Odette-response.png","datePublished":"2022-03-10T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/2022-Odette-response.png","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/2022-Odette-response.png","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/news\/le-travail-de-secours-en-cas-de-catastrophe-continue-aux-philippines-apres-typhoon-odette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Le travail de secours en cas de catastrophe continue aux Philippines apr\u00e8s Typhoon Odette"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/46477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/46477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/28219"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=46477"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-categories?post=46477"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-region-taxonomy?post=46477"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-tag?post=46477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}