{"id":45140,"date":"2023-03-23T00:00:00","date_gmt":"2023-03-23T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/"},"modified":"2023-03-23T00:00:00","modified_gmt":"2023-03-23T05:00:00","slug":"plus-de-100-pasteurs-nicaraguayens-equipes-par-conference","status":"publish","type":"news","link":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/","title":{"rendered":"Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence"},"content":{"rendered":"<p>Plus de 100 pasteurs et leaders des quatre districts du Nicaragua ont particip\u00e9 \u00e0 la premi\u00e8re conf\u00e9rence nationale des pasteurs du 27 f\u00e9vrier au 1 mars au Centre biblique nazar\u00e9en \u00e0 San Jorge, Rivas, Nicaragua.<\/p>\n<p>Le th\u00e8me de la conf\u00e9rence \u00e9tait \u00ab Vision, \u00e9vang\u00e9lisation et disciple \u00bb.&nbsp;<\/p>\n<p>Nous avons commenc\u00e9 avec un grand service inspirant et puissant \u00bb, a d\u00e9clar\u00e9 le pasteur Denis Espinoza. Le Saint-Esprit s&rsquo;est manifest\u00e9 par la musique, la pri\u00e8re et en particulier [lors] l&rsquo;exposition de la Parole de Dieu et les temps de cons\u00e9cration \u00e0 l&rsquo;autel. \u00a0\u00bb&nbsp;<\/p>\n<p>Ce service d&rsquo;ouverture a \u00e9t\u00e9 suivi par des d\u00e9votions du matin et du soir dirig\u00e9es par les districts respectifs. Les orateurs de note cl\u00e9 de l&rsquo;\u00e9v\u00e9nement \u00e9taient Orlando Serrano, Dale Schaeffer, Roberto Hodgson, Ernesto Bello et Olena P\u00e9rez.<\/p>\n<p>La conf\u00e9rence comprenait \u00e9galement quatre sessions pl\u00e9ni\u00e8res : La vie de l&rsquo;\u00c9glise, Strat\u00e9gies d&rsquo;\u00e9vang\u00e9lisation, Disciple intentionnel et L&rsquo;appel au minist\u00e8re. Ces sessions ont \u00e9t\u00e9 dirig\u00e9es par Orlando Serrano, Edgar D\u00edaz et David Alberto P\u00e9rez des \u00c9tats-Unis ; Felipe Flores du Costa Rica &#8211; SENDAS ; Gadiel Morales, Isra\u00ebl Acosta, Paulino Mu\u00f1oz et Franlym Pe\u00f1a du Nicaragua.<\/p>\n<p>Le dernier jour de la conf\u00e9rence, les participants avaient une chance de partager un temps sp\u00e9cial avec certains dipl\u00f4m\u00e9s vivant des premi\u00e8res d\u00e9cennies d&rsquo;\u00e9ducation \u00e0 l&rsquo;ancien Institut biblique nazar\u00e9en (maintenant Centre biblique nazar\u00e9en).<\/p>\n<p>Daniel Vega est la seule personne vivant encore de la premi\u00e8re g\u00e9n\u00e9ration des dipl\u00f4m\u00e9s de 1950 de &nbsp;l&rsquo;Institut biblique nazar\u00e9en (maintenant le Centre biblique nazar\u00e9en). Ernesto Bello, Francisco Pe\u00f1a et Denis Espinoza &#8211; dipl\u00f4m\u00e9s des deux d\u00e9cennies suivantes &#8211; \u00e9taient \u00e9galement pr\u00e9sents. Ensemble, ils se sont engag\u00e9s avec les g\u00e9n\u00e9rations plus r\u00e9centes dans leurs efforts pour r\u00e9ouvrir le Centre biblique nazar\u00e9en.<\/p>\n<p>C&rsquo;\u00e9tait une b\u00e9n\u00e9diction de rencontrer les grands hommes qui ont commenc\u00e9 ce grand travail au Nicaragua et \u00e9galement apprendre sur certaines strat\u00e9gies de croissance dans le minist\u00e8re \u00bb, a d\u00e9clar\u00e9 le pasteur Antonio Garcia. Ce qui m&rsquo;a le plus frapp\u00e9 \u00e9tait d&rsquo;avoir ces hommes qui ont servi le Seigneur avec un grand effort dans des temps difficiles mais a r\u00e9ussi \u00e0 avoir l&rsquo;\u00c9glise du Nazar\u00e9en dans de nombreux endroits au Nicaragua. \u00ab\u00a0<\/p>\n<p>En plus de la formation \u00e0 l&rsquo;\u00e9v\u00e9nement, les leaders ont pris du temps &nbsp;&nbsp;pour l&rsquo;unit\u00e9 et la fraternit\u00e9 alors qu&rsquo;ils faisaient une tourn\u00e9e du lac Nicaragua et du port du lac de San Jorge.<\/p>\n<p>Cette conf\u00e9rence \u00e9tait puissante. Les sujets et les orateurs \u00e9taient \u00e0 la hauteur de la t\u00e2che d'[aider les] Nazar\u00e9ens du Nicaragua \u00e0 continuer [\u00e0 grandir et \u00e0 avancer] le royaume de Dieu dans notre pays \u00bb, a d\u00e9clar\u00e9 le pasteur Edwin Montenegro.<\/p>\n<p>\u00c9glise de la Nazar\u00e9enne M\u00e9so-Am\u00e9rique<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus de 100 pasteurs et leaders des quatre districts du Nicaragua ont particip\u00e9 \u00e0 la premi\u00e8re conf\u00e9rence nationale des pasteurs au Centre biblique nazar\u00e9en \u00e0 San Jorge, Rivas, Nicaragua.<\/p>\n","protected":false},"author":1,"featured_media":29223,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[1756,862],"class_list":["post-45140","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-nicaragua-fr","news-tag-region-de-meso-amerique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence\" \/>\n<meta property=\"og:description\" content=\"Plus de 100 pasteurs et leaders des quatre districts du Nicaragua ont particip\u00e9 \u00e0 la premi\u00e8re conf\u00e9rence nationale des pasteurs au Centre biblique nazar\u00e9en \u00e0 San Jorge, Rivas, Nicaragua.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\\\/\",\"name\":\"Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Nicaragua-Pastors-Retreat.jpg\",\"datePublished\":\"2023-03-23T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Nicaragua-Pastors-Retreat.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Nicaragua-Pastors-Retreat.jpg\",\"width\":1040,\"height\":555},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence","og_description":"Plus de 100 pasteurs et leaders des quatre districts du Nicaragua ont particip\u00e9 \u00e0 la premi\u00e8re conf\u00e9rence nationale des pasteurs au Centre biblique nazar\u00e9en \u00e0 San Jorge, Rivas, Nicaragua.","og_url":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/","url":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/","name":"Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Nicaragua-Pastors-Retreat.jpg","datePublished":"2023-03-23T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Nicaragua-Pastors-Retreat.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Nicaragua-Pastors-Retreat.jpg","width":1040,"height":555},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/news\/plus-de-100-pasteurs-nicaraguayens-equipes-par-conference\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Plus de 100 pasteurs nicaraguayens \u00e9quip\u00e9s par conf\u00e9rence"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/45140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/45140\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/29223"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=45140"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-categories?post=45140"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-region-taxonomy?post=45140"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-tag?post=45140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}