{"id":42300,"date":"2025-04-15T01:19:05","date_gmt":"2025-04-15T06:19:05","guid":{"rendered":"https:\/\/nazarene.org\/news\/drapeaux-des-nations-vanuatu\/"},"modified":"2025-07-09T01:28:05","modified_gmt":"2025-07-09T06:28:05","slug":"drapeaux-des-nations-vanuatu","status":"publish","type":"news","link":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/","title":{"rendered":"Drapeaux des nations : Vanuatu"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Depuis le 1 septembre 2009, le Centre du minist\u00e8re mondial de l&rsquo;\u00c9glise du Nazar\u00e9en (GMC) flotte fi\u00e8rement un drapeau chaque semaine de l&rsquo;une des nombreuses nations dans lesquelles la d\u00e9nomination est pr\u00e9sente dans le minist\u00e8re. Les leaders ont \u00e9t\u00e9 invit\u00e9s \u00e0 envoyer un drapeau national \u00e0 voler au GMC aux c\u00f4t\u00e9s du drapeau des \u00c9tats-Unis *. Les drapeaux nationaux tournent chaque semaine et les photos d&rsquo;eux lev\u00e9s sont envoy\u00e9es aux leaders de l&rsquo;\u00c9glise de ce pays.<\/p>\n\n<p class=\"wp-block-paragraph\">Cette semaine : <strong>Vanuatu<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00c9glise du Nazar\u00e9en est officiellement entr\u00e9e au Vanuatu en 2001.<\/p>\n\n<p class=\"wp-block-paragraph\">Vanuatu avait une population de 318 007 en 2024. La m\u00eame ann\u00e9e, Vanuatu a rapport\u00e9 12 \u00c9glises du Nazar\u00e9en, dont cinq avaient \u00e9t\u00e9 officiellement organis\u00e9es. Vanuatu a 437 membres totaux.<\/p>\n\n<p class=\"wp-block-paragraph\">Situ\u00e9 dans la r\u00e9gion Asie-Pacifique, Vanuatu est un district de phase 1. Pour plus d&rsquo;informations sur la r\u00e9gion Asie-Pacifique, visitez <a href=\"http:\/\/asiapacificnazarene.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">asiapacificnazarene.org<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">Le drapeau hebdomadaire surlign\u00e9 est lev\u00e9 au milieu de trois p\u00f4les en conformit\u00e9 avec les protocoles du gouvernement am\u00e9ricain. Il vole \u00e0 gauche du drapeau de la nation h\u00f4te GMC, qui vole au-dessus du drapeau de l&rsquo;\u00c9tat h\u00f4te du Kansas. Le drapeau chr\u00e9tien vole sur le troisi\u00e8me poteau.<\/p>\n\n<p class=\"wp-block-paragraph\">Le Centre du minist\u00e8re mondial est le centre de mission et de service de l&rsquo;\u00c9glise du Nazar\u00e9en.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le 1 septembre 2009, le Centre du minist\u00e8re mondial de l&rsquo;\u00c9glise du Nazar\u00e9en (GMC) flotte fi\u00e8rement un drapeau chaque semaine de l&rsquo;une des nombreuses nations dans lesquelles la d\u00e9nomination est pr\u00e9sente dans le minist\u00e8re. Les leaders ont \u00e9t\u00e9 invit\u00e9s \u00e0 envoyer un drapeau national \u00e0 voler au GMC aux c\u00f4t\u00e9s du drapeau des \u00c9tats-Unis [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":32362,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[928,1371,1539],"class_list":["post-42300","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-asie-pacifique","news-tag-drapeaux","news-tag-vanuatu-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Drapeaux des nations : Vanuatu - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Drapeaux des nations : Vanuatu\" \/>\n<meta property=\"og:description\" content=\"Depuis le 1 septembre 2009, le Centre du minist\u00e8re mondial de l&rsquo;\u00c9glise du Nazar\u00e9en (GMC) flotte fi\u00e8rement un drapeau chaque semaine de l&rsquo;une des nombreuses nations dans lesquelles la d\u00e9nomination est pr\u00e9sente dans le minist\u00e8re. Les leaders ont \u00e9t\u00e9 invit\u00e9s \u00e0 envoyer un drapeau national \u00e0 voler au GMC aux c\u00f4t\u00e9s du drapeau des \u00c9tats-Unis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T06:28:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/Vanuatu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/drapeaux-des-nations-vanuatu\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/drapeaux-des-nations-vanuatu\\\/\",\"name\":\"Drapeaux des nations : Vanuatu - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/drapeaux-des-nations-vanuatu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/drapeaux-des-nations-vanuatu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Vanuatu.jpg\",\"datePublished\":\"2025-04-15T06:19:05+00:00\",\"dateModified\":\"2025-07-09T06:28:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/drapeaux-des-nations-vanuatu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/drapeaux-des-nations-vanuatu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/drapeaux-des-nations-vanuatu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Vanuatu.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Vanuatu.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/drapeaux-des-nations-vanuatu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Drapeaux des nations : Vanuatu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Drapeaux des nations : Vanuatu - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/","og_locale":"fr_FR","og_type":"article","og_title":"Drapeaux des nations : Vanuatu","og_description":"Depuis le 1 septembre 2009, le Centre du minist\u00e8re mondial de l&rsquo;\u00c9glise du Nazar\u00e9en (GMC) flotte fi\u00e8rement un drapeau chaque semaine de l&rsquo;une des nombreuses nations dans lesquelles la d\u00e9nomination est pr\u00e9sente dans le minist\u00e8re. Les leaders ont \u00e9t\u00e9 invit\u00e9s \u00e0 envoyer un drapeau national \u00e0 voler au GMC aux c\u00f4t\u00e9s du drapeau des \u00c9tats-Unis [&hellip;]","og_url":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","article_modified_time":"2025-07-09T06:28:05+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/Vanuatu.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/","url":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/","name":"Drapeaux des nations : Vanuatu - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/Vanuatu.jpg","datePublished":"2025-04-15T06:19:05+00:00","dateModified":"2025-07-09T06:28:05+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/Vanuatu.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/Vanuatu.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/news\/drapeaux-des-nations-vanuatu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/fr\/news\/"},{"@type":"ListItem","position":3,"name":"Drapeaux des nations : Vanuatu"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/42300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news\/42300\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/32362"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=42300"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-categories?post=42300"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-region-taxonomy?post=42300"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/news-tag?post=42300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}