{"id":41863,"date":"2024-06-26T16:02:28","date_gmt":"2024-06-26T21:02:28","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/quiz-de-la-bible-des-enfants\/"},"modified":"2024-06-26T16:02:28","modified_gmt":"2024-06-26T21:02:28","slug":"quiz-de-la-bible-des-enfants","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/","title":{"rendered":"Quiz de la Bible des enfants"},"content":{"rendered":"<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\">Quand est le meilleur temps pour commencer le quiz des enfants ?&nbsp; <\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\">Il n&rsquo;y a jamais un mauvais temps ! Le quiz biblique des enfants suit un cycle de six ans. Les ann\u00e9es de quiz courent avec la plupart des calendriers scolaires am\u00e9ricains (septembre \u00e0 ao\u00fbt).&nbsp;&nbsp; <\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\">Nous venons de finir l&rsquo;\u00c9vangile de Matthieu et le prochain livre de la Bible que nous pr\u00e9voyons d&rsquo;\u00e9tudier est Actes. Quelle aventure excitante ! Les \u00e9tudiants liront et apprendront de nouvelles choses sur Dieu, l&rsquo;\u00c9glise et eux-m\u00eames alors qu&rsquo;ils se concentrent sur les 28 chapitres d&rsquo;un livre excitant de la Bible. <\/span><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\">Si vous avez des questions ou avez besoin de plus d&rsquo;informations, veuillez contacter Dorothy Whipp, <a href=\"mailto:dwhipp@nazarene.org\" style=\"color:#467886; text-decoration:underline\">dwhipp@nazarene.org<\/a>. <\/span><\/span><\/p>\n","protected":false},"featured_media":21864,"menu_order":0,"template":"","ndi-journey-tags":[1327],"class_list":["post-41863","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-quizzing-des-enfants"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Quiz de la Bible des enfants - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quiz de la Bible des enfants\" \/>\n<meta property=\"og:description\" content=\"Quand est le meilleur temps pour commencer le quiz des enfants ?&nbsp; &nbsp; Il n&rsquo;y a jamais un mauvais temps ! Le quiz biblique des enfants suit un cycle de six ans. Les ann\u00e9es de quiz courent avec la plupart des calendriers scolaires am\u00e9ricains (septembre \u00e0 ao\u00fbt).&nbsp;&nbsp; &nbsp; Nous venons de finir l&rsquo;\u00c9vangile de Matthieu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/quiz-de-la-bible-des-enfants\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/quiz-de-la-bible-des-enfants\\\/\",\"name\":\"Quiz de la Bible des enfants - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/quiz-de-la-bible-des-enfants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/quiz-de-la-bible-des-enfants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Bible-Quizzing2.jpg\",\"datePublished\":\"2024-06-26T21:02:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/quiz-de-la-bible-des-enfants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/quiz-de-la-bible-des-enfants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/quiz-de-la-bible-des-enfants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Bible-Quizzing2.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Bible-Quizzing2.jpg\",\"width\":550,\"height\":804},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/quiz-de-la-bible-des-enfants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quiz de la Bible des enfants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quiz de la Bible des enfants - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/","og_locale":"fr_FR","og_type":"article","og_title":"Quiz de la Bible des enfants","og_description":"Quand est le meilleur temps pour commencer le quiz des enfants ?&nbsp; &nbsp; Il n&rsquo;y a jamais un mauvais temps ! Le quiz biblique des enfants suit un cycle de six ans. Les ann\u00e9es de quiz courent avec la plupart des calendriers scolaires am\u00e9ricains (septembre \u00e0 ao\u00fbt).&nbsp;&nbsp; &nbsp; Nous venons de finir l&rsquo;\u00c9vangile de Matthieu [&hellip;]","og_url":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/","url":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/","name":"Quiz de la Bible des enfants - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/01\/Bible-Quizzing2.jpg","datePublished":"2024-06-26T21:02:28+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/01\/Bible-Quizzing2.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/01\/Bible-Quizzing2.jpg","width":550,"height":804},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/quiz-de-la-bible-des-enfants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/fr\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"Quiz de la Bible des enfants"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/ndi-journey\/41863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/ndi-journey\/41863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/21864"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=41863"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/ndi-journey-tags?post=41863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}