{"id":41477,"date":"2025-03-12T16:20:54","date_gmt":"2025-03-12T21:20:54","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/paque-heritage-disrael-en-afrique\/"},"modified":"2025-03-12T16:20:54","modified_gmt":"2025-03-12T21:20:54","slug":"paque-heritage-disrael-en-afrique","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/","title":{"rendered":"P\u00e2que : H\u00e9ritage d&rsquo;Isra\u00ebl en Afrique"},"content":{"rendered":"<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\">L&rsquo;une des c\u00e9l\u00e9brations principales de l&rsquo;\u00c9glise du Christ dans le monde est P\u00e2ques. Les chr\u00e9tiens du monde entier c\u00e9l\u00e8brent \u00e0 l&rsquo;unisson la mort vicaire de notre Sauveur et sa r\u00e9surrection. Cependant, cette c\u00e9l\u00e9bration remonte \u00e0 l&rsquo;Ancien Testament, lorsque le peuple d&rsquo;Isra\u00ebl a \u00e9t\u00e9 r\u00e9duit en esclavage en \u00c9gypte et a cri\u00e9 pour la d\u00e9livrance. Il \u00e9tait, en fait, avec leurs pieds fermement plant\u00e9s sur le continent africain que la premi\u00e8re r\u00e9v\u00e9lation de P\u00e2que a \u00e9t\u00e9 accord\u00e9e \u00e0 l&rsquo;humanit\u00e9.<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><strong>Attachez les chaussures, car le salut est urgent !<\/strong><\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\">La P\u00e2que juive, qui a eu lieu il y a environ 3 500 ans, \u00e9tablit les fondements th\u00e9ologiques pour la compr\u00e9hension de P\u00e2ques. Par cons\u00e9quent, la compr\u00e9hension des origines de P\u00e2ques \u00e9tablira comment le plan de Dieu tout au long de l&rsquo;histoire est r\u00e9v\u00e9l\u00e9 de mani\u00e8re coh\u00e9sive.<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\">Le livre de l&rsquo;Exode nous r\u00e9v\u00e8le la triste situation du peuple h\u00e9breu : esclave et humili\u00e9 sous la servitude \u00e9gyptienne dure. Mais Dieu a entendu leur cri et a livr\u00e9 son peuple choisi par de nombreux miracles. <\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\">Avant leur lib\u00e9ration, Dieu a \u00e9tabli P\u00e2que. Selon Exode 12 : 2, cette date \u00e9tait si importante pour le calendrier h\u00e9breu qu&rsquo;elle serait consid\u00e9r\u00e9e \u00ab le premier des mois \u00bb. Mais quelque chose dans le texte biblique attire notre attention : les gens devaient manger l&rsquo;agneau r\u00f4ti, le pain non lev\u00e9 et les herbes am\u00e8res \u00ab avec leurs long ceints, les sandales \u00e0 leurs pieds et le personnel \u00e0 la main ; ils le mangeront en h\u00e2te ; c&rsquo;est la P\u00e2que du Seigneur \u00bb (Exode 12 : 11). P\u00e2que \u00e9tait observ\u00e9 alors que les gens \u00e9taient pr\u00eats \u00e0 quitter l&rsquo;\u00c9gypte. <\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><b>Ce sens d&rsquo;urgence nous accompagne \u00e0 P\u00e2ques chr\u00e9tienne. <\/b><\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\">Bien que nos coutumes aient chang\u00e9 de mani\u00e8re significative depuis le temps de Mo\u00efse, l&rsquo;appel urgent de Dieu continue \u00e0 r\u00e9sonner sur la terre, nous exhortant \u00e0 quitter l&rsquo;esclavage du p\u00e9ch\u00e9 et \u00e0 embrasser une nouvelle vie de saintet\u00e9 et de joie dans le Christ J\u00e9sus. L&rsquo;appel de Dieu est pour vous et il est pour aujourd&rsquo;hui !<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\">L&rsquo;une des plus belles r\u00e9v\u00e9lations que le livre de l&rsquo;Exode nous donne est que le peuple d&rsquo;Isra\u00ebl a \u00e9t\u00e9 libre, mais \u00ab une multitude mixte de toutes sortes d&rsquo;\u00e9trangers est mont\u00e9e avec eux \u00bb (Exode 12 : 38). La libert\u00e9 est un don trop pr\u00e9cieux pour \u00eatre gard\u00e9 pour une seule personne. C&rsquo;est pourquoi, depuis l&rsquo;Exode, Dieu a inclus des gens de toutes les nations.<\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><b>En Afrique aujourd&rsquo;hui<\/b><\/span><\/span><\/p>\n<p><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\">Les jours de P\u00e2ques sont un temps pour c\u00e9l\u00e9brer les grandes nouvelles du salut. Nos \u00c9glises locales se r\u00e9unissent pour un temps de cons\u00e9cration et d&rsquo;\u00e9vang\u00e9lisation. Dans une mobilisation puissante et unie, la famille nazar\u00e9enne d&rsquo;Afrique proclame avec tout leur c\u0153ur que le jour de la libert\u00e9 est venu ! Le m\u00eame sol africain qui a \u00e9t\u00e9 t\u00e9moin de l&rsquo;exode miraculeux du peuple d&rsquo;Isra\u00ebl d&rsquo;\u00c9gypte continue \u00e0 \u00eatre t\u00e9moin de la perc\u00e9e puissante du salut pour tous les peuples dans le Christ J\u00e9sus.<\/span><\/span><\/p>\n","protected":false},"featured_media":21802,"menu_order":0,"template":"","ndi-journey-tags":[1348],"class_list":["post-41477","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-paques-en-afrique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>P\u00e2que : H\u00e9ritage d&#039;Isra\u00ebl en Afrique - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00e2que : H\u00e9ritage d&#039;Isra\u00ebl en Afrique\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;une des c\u00e9l\u00e9brations principales de l&rsquo;\u00c9glise du Christ dans le monde est P\u00e2ques. Les chr\u00e9tiens du monde entier c\u00e9l\u00e8brent \u00e0 l&rsquo;unisson la mort vicaire de notre Sauveur et sa r\u00e9surrection. Cependant, cette c\u00e9l\u00e9bration remonte \u00e0 l&rsquo;Ancien Testament, lorsque le peuple d&rsquo;Isra\u00ebl a \u00e9t\u00e9 r\u00e9duit en esclavage en \u00c9gypte et a cri\u00e9 pour la d\u00e9livrance. Il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/paque-heritage-disrael-en-afrique\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/paque-heritage-disrael-en-afrique\\\/\",\"name\":\"P\u00e2que : H\u00e9ritage d'Isra\u00ebl en Afrique - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/paque-heritage-disrael-en-afrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/paque-heritage-disrael-en-afrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Africa-Logo-1_Gray_EN-scaled.jpg\",\"datePublished\":\"2025-03-12T21:20:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/paque-heritage-disrael-en-afrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/paque-heritage-disrael-en-afrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/paque-heritage-disrael-en-afrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Africa-Logo-1_Gray_EN-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Africa-Logo-1_Gray_EN-scaled.jpg\",\"width\":2560,\"height\":2118},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/paque-heritage-disrael-en-afrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"P\u00e2que : H\u00e9ritage d&#8217;Isra\u00ebl en Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"P\u00e2que : H\u00e9ritage d'Isra\u00ebl en Afrique - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/","og_locale":"fr_FR","og_type":"article","og_title":"P\u00e2que : H\u00e9ritage d'Isra\u00ebl en Afrique","og_description":"L&rsquo;une des c\u00e9l\u00e9brations principales de l&rsquo;\u00c9glise du Christ dans le monde est P\u00e2ques. Les chr\u00e9tiens du monde entier c\u00e9l\u00e8brent \u00e0 l&rsquo;unisson la mort vicaire de notre Sauveur et sa r\u00e9surrection. Cependant, cette c\u00e9l\u00e9bration remonte \u00e0 l&rsquo;Ancien Testament, lorsque le peuple d&rsquo;Isra\u00ebl a \u00e9t\u00e9 r\u00e9duit en esclavage en \u00c9gypte et a cri\u00e9 pour la d\u00e9livrance. Il [&hellip;]","og_url":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/","url":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/","name":"P\u00e2que : H\u00e9ritage d'Isra\u00ebl en Afrique - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Africa-Logo-1_Gray_EN-scaled.jpg","datePublished":"2025-03-12T21:20:54+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Africa-Logo-1_Gray_EN-scaled.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Africa-Logo-1_Gray_EN-scaled.jpg","width":2560,"height":2118},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/fr\/ndi-journey\/paque-heritage-disrael-en-afrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/fr\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/fr\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"P\u00e2que : H\u00e9ritage d&#8217;Isra\u00ebl en Afrique"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/fr\/#website","url":"https:\/\/nazarene.org\/fr\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/fr\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/ndi-journey\/41477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/ndi-journey\/41477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media\/21802"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/media?parent=41477"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/fr\/wp-json\/wp\/v2\/ndi-journey-tags?post=41477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}