{"id":72483,"date":"2026-04-16T16:30:06","date_gmt":"2026-04-16T21:30:06","guid":{"rendered":"https:\/\/nazarene.org\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/"},"modified":"2026-04-17T13:02:10","modified_gmt":"2026-04-17T18:02:10","slug":"celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/","title":{"rendered":"Celebrando la vida y el ministerio de Cosmas Mutowa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cosmas Mutowa, de 62 a\u00f1os, de Roodepoort Gauteng, Sud\u00e1frica, falleci\u00f3 el 10 de abril de 2026. Fue coordinador de estrategia del \u00c1rea Africa South East; y sirvi\u00f3 como misionero con asignaci\u00f3n global desde 2007.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nacido el 28 de junio de 1963 en Zimbabue, Cosmas reconoci\u00f3 el llamado de Dios para servir en el ministerio a la edad de 19 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego, se mud\u00f3 a Swazilandia, donde comenz\u00f3 su educaci\u00f3n teol\u00f3gica. Obtuvo una licenciatura en Teolog\u00eda, ofrecida a trav\u00e9s de Canadian Nazarene College (ahora, Ambrose). Se gradu\u00f3 en 1988, y regres\u00f3 a su casa en Zimbabue para ministrar. Fue ordenado en 1990; y se uni\u00f3 al cuerpo docente de la facultad del Nazarene Bible College, tambi\u00e9n sirviendo como tesorero de la universidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1993, Mutowa fue nombrado vicerrector del Bible College, sirviendo en ese papel hasta que se mud\u00f3 para obtener su maestr\u00eda en Africa Nazarene University en Kenia. Obtuvo una maestr\u00eda en Religi\u00f3n, en 1999.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s tarde, obtuvo una segunda maestr\u00eda, ahora en Ministerio de Compasi\u00f3n y Pr\u00e1cticas Humanitarias\/Desarrollo en el Nazarene Theological College, Manchester.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde 2008, Mutowa sirvi\u00f3 como coordinador de Ministerios Nazarenos de Compasi\u00f3n de la Regi\u00f3n \u00c1frica; y como director ejecutivo de Helping Hands Africa. Fue nombrado CEA del \u00c1rea Africa South East en 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su ministerio impact\u00f3 a muchos a lo largo de los a\u00f1os. Una <a href=\"https:\/\/www.facebook.com\/share\/p\/18JTdwMJXo\/\" type=\"link\" id=\"https:\/\/www.facebook.com\/share\/p\/18JTdwMJXo\/\">publicaci\u00f3n de Facebook<\/a> de la Iglesia del Nazareno Regi\u00f3n \u00c1frica recibi\u00f3 casi 500 comentarios, muchos llenos de historias de Cosmas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEra un verdadero compa\u00f1ero en el ministerio\u00bb, escribi\u00f3 Mario Mart\u00ednez. \u00abUn hombre de buen coraz\u00f3n que dej\u00f3 una impresi\u00f3n duradera en aquellos de nosotros que tuvimos el privilegio de caminar junto a \u00e9l. Su vida fue un testimonio sincero de su amor por Dios y por los dem\u00e1s\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le sobreviven su esposa, Andronica Mutowa; y sus hijos, Nomsa, Daniel y Panashe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La semana pasada se llev\u00f3 a cabo un servicio conmemorativo en su honor. Para ver el servicio, <a href=\"https:\/\/www.facebook.com\/nazafrica\/videos\/1263639642055122\">haga clic aqu\u00ed<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cosmas Mutowa, de 62 a\u00f1os, de Roodepoort Gauteng, Sud\u00e1frica, falleci\u00f3 el 10 de abril de 2026. Fue coordinador de estrategia del \u00c1rea Africa South East; y sirvi\u00f3 como misionero con asignaci\u00f3n global desde 2007. Nacido el 28 de junio de 1963 en Zimbabue, Cosmas reconoci\u00f3 el llamado de Dios para servir en el ministerio a [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":72484,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[2862],"news-tag":[946,792],"class_list":["post-72483","news","type-news","status-publish","has-post-thumbnail","hentry","news-region-taxonomy-africa-es","news-tag-misiones","news-tag-pasos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Celebrando la vida y el ministerio de Cosmas Mutowa - Church of the Nazarene<\/title>\n<meta name=\"description\" content=\"Cosmas Mutowa, de 62 a\u00f1os, de Roodepoort Gauteng, Sud\u00e1frica, falleci\u00f3 el 10 de abril de 2026. Fue coordinador de estrategia del \u00c1rea Africa South East; y sirvi\u00f3 como misionero con asignaci\u00f3n global desde 2007.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrando la vida y el ministerio de Cosmas Mutowa\" \/>\n<meta property=\"og:description\" content=\"Cosmas Mutowa, de 62 a\u00f1os, de Roodepoort Gauteng, Sud\u00e1frica, falleci\u00f3 el 10 de abril de 2026. Fue coordinador de estrategia del \u00c1rea Africa South East; y sirvi\u00f3 como misionero con asignaci\u00f3n global desde 2007.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T18:02:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/2026\/04\/Cosmas-Mutowa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\\\/\",\"name\":\"Celebrando la vida y el ministerio de Cosmas Mutowa - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Cosmas-Mutowa.jpg\",\"datePublished\":\"2026-04-16T21:30:06+00:00\",\"dateModified\":\"2026-04-17T18:02:10+00:00\",\"description\":\"Cosmas Mutowa, de 62 a\u00f1os, de Roodepoort Gauteng, Sud\u00e1frica, falleci\u00f3 el 10 de abril de 2026. Fue coordinador de estrategia del \u00c1rea Africa South East; y sirvi\u00f3 como misionero con asignaci\u00f3n global desde 2007.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Cosmas-Mutowa.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Cosmas-Mutowa.jpg\",\"width\":1500,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Celebrando la vida y el ministerio de Cosmas Mutowa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Celebrando la vida y el ministerio de Cosmas Mutowa - Church of the Nazarene","description":"Cosmas Mutowa, de 62 a\u00f1os, de Roodepoort Gauteng, Sud\u00e1frica, falleci\u00f3 el 10 de abril de 2026. Fue coordinador de estrategia del \u00c1rea Africa South East; y sirvi\u00f3 como misionero con asignaci\u00f3n global desde 2007.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/","og_locale":"es_ES","og_type":"article","og_title":"Celebrando la vida y el ministerio de Cosmas Mutowa","og_description":"Cosmas Mutowa, de 62 a\u00f1os, de Roodepoort Gauteng, Sud\u00e1frica, falleci\u00f3 el 10 de abril de 2026. Fue coordinador de estrategia del \u00c1rea Africa South East; y sirvi\u00f3 como misionero con asignaci\u00f3n global desde 2007.","og_url":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","article_modified_time":"2026-04-17T18:02:10+00:00","og_image":[{"width":1500,"height":800,"url":"https:\/\/nazarene.org\/wp-content\/uploads\/2026\/04\/Cosmas-Mutowa.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/","url":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/","name":"Celebrando la vida y el ministerio de Cosmas Mutowa - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2026\/04\/Cosmas-Mutowa.jpg","datePublished":"2026-04-16T21:30:06+00:00","dateModified":"2026-04-17T18:02:10+00:00","description":"Cosmas Mutowa, de 62 a\u00f1os, de Roodepoort Gauteng, Sud\u00e1frica, falleci\u00f3 el 10 de abril de 2026. Fue coordinador de estrategia del \u00c1rea Africa South East; y sirvi\u00f3 como misionero con asignaci\u00f3n global desde 2007.","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2026\/04\/Cosmas-Mutowa.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2026\/04\/Cosmas-Mutowa.jpg","width":1500,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/celebrando-la-vida-y-el-ministerio-de-cosmas-mutowa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"Celebrando la vida y el ministerio de Cosmas Mutowa"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/72483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":2,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/72483\/revisions"}],"predecessor-version":[{"id":72499,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/72483\/revisions\/72499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/72484"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=72483"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=72483"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=72483"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=72483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}