{"id":67635,"date":"2026-02-13T12:10:13","date_gmt":"2026-02-13T18:10:13","guid":{"rendered":"https:\/\/nazarene.org\/?post_type=news&#038;p=67635"},"modified":"2026-02-13T09:59:24","modified_gmt":"2026-02-13T15:59:24","slug":"banderas-de-las-naciones-alemania","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/","title":{"rendered":"Banderas de las Naciones: Alemania"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Desde el 1 de septiembre de 2009, el Centro de Ministerio Global (CMG) de la Iglesia del Nazareno orgullosamente iza cada semana la bandera de una de las muchas naciones donde la denominaci\u00f3n est\u00e1 ministrando actualmente. Los l\u00edderes fueron invitados a enviar una bandera nacional para ser izada en el CMG junto a la bandera de los Estados Unidos*. Las banderas nacionales se rotan semanalmente y fotos de ellas son enviadas a los l\u00edderes de las iglesias en ese pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta semana:&nbsp;<strong>Alemania<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Iglesia del Nazareno entr\u00f3 oficialmente&nbsp;a Alemania en el a\u00f1o&nbsp;1958.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alemania ten\u00eda una poblaci\u00f3n de\u00a084,012,284\u00a0en 2024. Ese mismo a\u00f1o, Alemania report\u00f3 20\u00a0Iglesias del Nazareno, 18 de los cuales han sido organizadas oficialmente. Alemania tiene 1,784 miembros en total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Localizada&nbsp;en la Regi\u00f3n Eurasia, Alemania es un distrito Fase 3. Para m\u00e1s informaci\u00f3n acerca de la Regi\u00f3n Eurasia, visite&nbsp;<a href=\"http:\/\/www.eurasiaregion.org\/\">eurasiaregion.org<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*= La bandera destacada semanalmente se iza a en el poste medio de tres postes en conformidad con los protocolos del gobierno de Estados Unidos. A la izquierda ondea&nbsp;la bandera de Estados Unidos, el pa\u00eds anfitri\u00f3n del CMG, que a su vez ondea sobre la bandera de Kansas, el estado anfitri\u00f3n. La bandera cristiana ondea en el tercer poste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro de Ministerio Global es el centro de misi\u00f3n y servicio de la Iglesia del Nazareno.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el 1 de septiembre de 2009, el Centro de Ministerio Global (CMG) de la Iglesia del Nazareno orgullosamente iza cada semana la bandera de una de las muchas naciones donde la denominaci\u00f3n est\u00e1 ministrando actualmente. Los l\u00edderes fueron invitados a enviar una bandera nacional para ser izada en el CMG junto a la bandera [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":24458,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[2883],"news-tag":[1740,1392,1481,809],"class_list":["post-67635","news","type-news","status-publish","has-post-thumbnail","hentry","news-region-taxonomy-eurasia-es","news-tag-alemania","news-tag-banderas","news-tag-eurasia-es","news-tag-region-de-eurasia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Banderas de las Naciones: Alemania - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banderas de las Naciones: Alemania\" \/>\n<meta property=\"og:description\" content=\"Desde el 1 de septiembre de 2009, el Centro de Ministerio Global (CMG) de la Iglesia del Nazareno orgullosamente iza cada semana la bandera de una de las muchas naciones donde la denominaci\u00f3n est\u00e1 ministrando actualmente. Los l\u00edderes fueron invitados a enviar una bandera nacional para ser izada en el CMG junto a la bandera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Germany-1_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/banderas-de-las-naciones-alemania\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/banderas-de-las-naciones-alemania\\\/\",\"name\":\"Banderas de las Naciones: Alemania - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/banderas-de-las-naciones-alemania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/banderas-de-las-naciones-alemania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Germany-1_0.jpg\",\"datePublished\":\"2026-02-13T18:10:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/banderas-de-las-naciones-alemania\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/banderas-de-las-naciones-alemania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/banderas-de-las-naciones-alemania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Germany-1_0.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Germany-1_0.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/banderas-de-las-naciones-alemania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Banderas de las Naciones: Alemania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Banderas de las Naciones: Alemania - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/","og_locale":"es_ES","og_type":"article","og_title":"Banderas de las Naciones: Alemania","og_description":"Desde el 1 de septiembre de 2009, el Centro de Ministerio Global (CMG) de la Iglesia del Nazareno orgullosamente iza cada semana la bandera de una de las muchas naciones donde la denominaci\u00f3n est\u00e1 ministrando actualmente. Los l\u00edderes fueron invitados a enviar una bandera nacional para ser izada en el CMG junto a la bandera [&hellip;]","og_url":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","og_image":[{"width":750,"height":400,"url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Germany-1_0.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/","url":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/","name":"Banderas de las Naciones: Alemania - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Germany-1_0.jpg","datePublished":"2026-02-13T18:10:13+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Germany-1_0.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Germany-1_0.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/banderas-de-las-naciones-alemania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"Banderas de las Naciones: Alemania"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/67635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/17"}],"version-history":[{"count":1,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/67635\/revisions"}],"predecessor-version":[{"id":67636,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/67635\/revisions\/67636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/24458"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=67635"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=67635"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=67635"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=67635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}