{"id":53349,"date":"2019-07-10T00:00:00","date_gmt":"2019-07-10T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/"},"modified":"2019-07-10T00:00:00","modified_gmt":"2019-07-10T05:00:00","slug":"alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/","title":{"rendered":"Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n"},"content":{"rendered":"<div style=\"text-align:center\">\n<figure class=\"image\" style=\"display:inline-block\"><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Resources\/IllPushYou.jpg\" width=\"750\"><figcaption>Los amigos de toda la vida Patrick Gray y Justin Skeesuck aparecen en un nuevo documental, \u00abEmpujar\u00e9 a usted\u00bb, sobre su viaje de 500 millas en El Camino de Santiago. (Foto de Idaho Press-Tribune)<\/figcaption><\/figure>\n<\/div>\n<p>Dos ex alumnos nazarenos estrenar\u00e1n un documental basado en su viaje de seis semanas a trav\u00e9s de El Camino de Santiago de Espa\u00f1a (El Camino de San James) la pr\u00f3xima semana.<\/p>\n<p><em>Lo empujar\u00e9: Un viaje de 500 millas, dos mejores amigos y una silla de ruedas&nbsp;<\/em>viene a los cines durante una noche el 2 de noviembre para contar la historia de dos amigos de toda la vida, Justin Skeesuck y Patrick Gray,&nbsp;mientras Gray empuja a Skeesuck, que est\u00e1 luchando contra una enfermedad neuromuscular degenerativa, en una silla de ruedas a lo largo de todo el viaje.<\/p>\n<p>Hace tres a\u00f1os, nos propusimos lograr este viaje imposible, dijo &nbsp;&nbsp;Skeesuck.Tenerlo documentado en la pel\u00edcula fue un sue\u00f1o hecho realidad, pero finalmente poder compartirlo con el mundo, no estoy seguro de que tenga palabras para describir adecuadamente la alegr\u00eda que siento.<\/p>\n<p>Despu\u00e9s de la proyecci\u00f3n habr\u00e1 una discusi\u00f3n de panel exclusiva entre Skeesuck, Gray y los cineastas, facilitada por el embajador de la Asociaci\u00f3n de Distrofia Muscular y Billy Gilman, nominado a Grammy.<\/p>\n<p>Finalmente tener una oportunidad de compartir con tantas personas es incre\u00edble, dijo &nbsp;&nbsp;Gray.Hemos sido bendecidos con vivir esta vida, para ser una parte de esta historia. Que otros encuentren esperanza en es una cosa hermosa y humilde.<\/p>\n<p>Caminar esta antigua peregrinaci\u00f3n a lo largo del vasto terreno es lo suficientemente desafiante para la persona promedio, pero Justin y Patrick est\u00e1n lejos del promedio. Si bien estos dos amigos enfrentan varios desaf\u00edos, vienen a darse cuenta de que las mayores recompensas del viaje son las del autodescubrimiento, un sentido renovado de prop\u00f3sito y una apreciaci\u00f3n m\u00e1s profunda por la comunidad, todo lo que en \u00faltima instancia redefine el significado de la frase, \u00abTe empujar\u00e9\u00bb. &nbsp;<\/p>\n<p>Este incre\u00edble evento presenta una amistad incre\u00edble y autosacrificial, dijo Kymberli Frueh, vicepresidente &nbsp;de programaci\u00f3n de &nbsp;Fathom Events. Ver su viaje desarrollarse, con cada obst\u00e1culo a lo largo del camino, inspira el esp\u00edritu humano innato de la aventura y le recuerda lo que significa ser un verdadero y buen amigo. La tenacidad, la resistencia y el enorme amor de Justin y Patrick por otro es una cosa hermosa de ver.<\/p>\n<p>Terry Parish, codirector de <em>I&#8217;ll Push You<\/em>, explic\u00f3 su motivaci\u00f3n para unirse al proyecto.<\/p>\n<p>Para nosotros, el Camino y este proyecto siempre ha sido sobre el poder de nuestras comunidades, grandes o peque\u00f1as, &nbsp;dijo.De asociarse con Fathom&nbsp;a trabajar con el MD&nbsp;A o colaborar con grupos de m\u00fasica &nbsp;como Switchfoot en la banda sonora, &nbsp;este evento es la culminaci\u00f3n de nuestro trabajo de 4 a\u00f1os <em>por<\/em> amor.<\/p>\n<p>Chris Karcher, socio director, cree que la pel\u00edcula es importante en el clima cultural de hoy.<\/p>\n<p>En un tiempo en que muchos se est\u00e1n sintiendo en on-edge, estamos realmente orgullosos de estar ofreciendo un documental que demuestra que nuestros d\u00edas no son casi tan oscuros como a veces somos llevados a creer, pero m\u00e1s bien est\u00e1n iluminados con la bondad y la posibilidad de una conexi\u00f3n real.<\/p>\n<p>Skeesuck y Gray son graduados de 1997 de la Universidad Nazarena de Point Loma y la Universidad Nazarena del Noroeste, respectivamente.<\/p>\n<p>Para m\u00e1s informaci\u00f3n y boletos, visit&nbsp;<a href=\"https:\/\/www.fathomevents.com\/events\/ill-push-you\">fathomevents.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"text-align:center\">\n<figure class=\"image\" style=\"display:inline-block\"><img alt=\"\" heig=\"\"><\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[878,1538,1901,1498],"class_list":["post-53349","news","type-news","status-publish","hentry","news-tag-escuela-colegial","news-tag-nnu-es","news-tag-point-loma-es","news-tag-recursos-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Resources\/IllPushYou.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\\\/\",\"name\":\"Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Resources\\\/IllPushYou.jpg\",\"datePublished\":\"2019-07-10T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Resources\\\/IllPushYou.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Resources\\\/IllPushYou.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/","og_locale":"es_ES","og_type":"article","og_title":"Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n","og_url":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","og_image":[{"url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Resources\/IllPushYou.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/","url":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/","name":"Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Resources\/IllPushYou.jpg","datePublished":"2019-07-10T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Resources\/IllPushYou.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Resources\/IllPushYou.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/alumnos-nazarenos-presentados-en-el-documental-sobre-la-peregrinacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"Alumnos nazarenos presentados en el documental sobre la peregrinaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/53349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/53349\/revisions"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=53349"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=53349"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=53349"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=53349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}