{"id":53276,"date":"2019-07-10T00:00:00","date_gmt":"2019-07-10T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/"},"modified":"2019-07-10T00:00:00","modified_gmt":"2019-07-10T05:00:00","slug":"las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/","title":{"rendered":"Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Rico\/UnloadinginArecibo.jpg\" width=\"750\"><\/p>\n<p>En los d\u00edas siguientes a la devastaci\u00f3n total que el hurac\u00e1n Mar\u00eda caus\u00f3 en Puerto Rico, las iglesias nazarenas all\u00ed se han movilizado para responder, en asociaci\u00f3n con otras iglesias nazarenas de todo el mundo. &nbsp;<\/p>\n<p>La semana pasada, una carga de suministros de ayuda humanitaria de la izquierda de Lenexa, Kansas, se dirigi\u00f3 a Puerto Rico. Los <a href=\"http:\/\/www.ncm.org\" target=\"_blank\">Ministerios Nazarenos Compasivos<\/a> se asociaron con Heart a Heart International, que pudo usar sus conexiones con FedEx para volar en el env\u00edo.&nbsp;<\/p>\n<p>Despu\u00e9s de que el avi\u00f3n lleg\u00f3 a San Juan, el contenido se transfiri\u00f3 a un cami\u00f3n grande. Un grupo de 30 voluntarios de las iglesias nazarenas locales pas\u00f3 horas el 2 de octubre descargando los suministros, incluidos&nbsp;filtros de agua, miles de Kits de Crisis Care enviados de muchas iglesias nazarenas y 42,000 libras de paquetes de alimentos donados a trav\u00e9s de una asociaci\u00f3n con Convoy de Hope, una organizaci\u00f3n sin fines de lucro basada en la fe enfocada en la alimentaci\u00f3n y la respuesta al desastres. El martes, m\u00e1s voluntarios y pastores comenzaron el proceso de distribuir los suministros a familias vulnerables y personas m\u00e1s que 10 comunidades.<\/p>\n<p>Los voluntarios de una iglesia nazarena en Dorado fueron a Naranjito, una ciudad de monta\u00f1a empobrecida donde ministran regularmente, para distribuir kits de alimentos y atenci\u00f3n. La iglesia en Vega Baja llev\u00f3 comida y CCKs a un hogar para adultos mayores que carec\u00eda de recursos. Voluntarios de una iglesia nazarena en Cata\u00f1o distribuyeron alimentos y Kits de Crisis Care en La Puntilla, un vecindario empobrecido que fue inundado en gran parte por el agua del oc\u00e9ano.<\/p>\n<p><img decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Rico\/NowWeHaveFood.jpg\" width=\"750\"><\/p>\n<p>Mientras el grupo estaba dejando La Puntilla, un voluntario escuch\u00f3 a una ni\u00f1a joven decir a su madre, \u00abMira mam\u00e1, Ahora tenemos algo que comer\u00bb.<\/p>\n<p>A medida que llegan m\u00e1s suministros, las iglesias nazarenas est\u00e1n preparadas para continuar obteniendo ayuda a aquellos que la necesitan.<\/p>\n<p>La Iglesia del Distrito del Sur de Florida de la Nazarena organiz\u00f3 entregar un contenedor de carga de suministros, que actualmente est\u00e1 en ruta y programado para llegar a Puerto Rico antes del fin de semana. El contenedor incluye m\u00e1s de mil filtros de agua Sawyer, comprados con donaciones de respuesta a desastres que han venido a los Ministerios Nazarenos Compasivos de iglesias y personas de todo el mundo. La mayor\u00eda de la isla todav\u00eda no tiene acceso al agua potable, haciendo que los filtros de agua sean una necesidad cr\u00edtica de prevenir enfermedades debido a enfermedades transmitidas por el agua.<\/p>\n<p><img decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Rico\/VolunteersUnloadSupplies.jpg\" width=\"750\"><\/p>\n<p>Un env\u00edo de Crisis Care Kit tambi\u00e9n se envi\u00f3 a Puerto Rico a trav\u00e9s de una fuente improbable: Dallas Mavericks de la Asociaci\u00f3n Nacional de Baloncesto. J. J. Barea, un guardia de punto para el equipo que es de Puerto Rico, primero&nbsp;<a href=\"https:\/\/www.washingtonpost.com\/news\/early-lead\/wp\/2017\/09\/26\/mark-cuban-lends-mavericks-plane-to-puerto-rico-native-j-j-barea-for-hurricane-relief-efforts\/?utm_term=.7674e235c423\" target=\"_blank\">llev\u00f3 el avi\u00f3n &nbsp;privado del equipo a Puerto Rico<\/a> &nbsp;durante la semana pasada para traer a su familia a los Estados Unidos. Esta semana hizo un segundo viaje con 600 CCKs de la Iglesia del Oeste y del Norte \/ Este de Texas de los distritos nazarenos.<\/p>\n<p>Barea am\u00f3 a los CCKs y tom\u00f3 una caja para mostrar a los l\u00edderes de su fundaci\u00f3n como un ejemplo de una gran idea para ayudar, &nbsp;dijo Chrissy Maldonado, un pastor juvenil de Arlington, Texas, Primera Iglesia de la Nazarena, <a href=\"https:\/\/www.facebook.com\/groups\/1244069052275624\/permalink\/1905479656134557\/\" target=\"_blank\">que ayud\u00f3 a cargar los kits<\/a>. El avi\u00f3n estar\u00e1 haciendo un segundo viaje y les gustar\u00eda que traj\u00e9ramos el resto de nuestras cajas para enviar nuevamente.<\/p>\n<div>\n<div>\n<p>Pastor Ron Adams de la Iglesia de Ovilla Road de la Nazarena vino por primera vez en contacto con el equipo hace dos a\u00f1os cuando&nbsp;<a href=\"http:\/\/www.nazarene.org\/article\/tornado-downs-texas-church-missionaries-safe-okc\" target=\"_blank\">un tornado destruy\u00f3 su iglesia<\/a> &nbsp;mientras asist\u00eda a un juego de Mavericks.&nbsp;Cuando escuch\u00f3 sobre el viaje de Barea, se comunic\u00f3 con el equipo para ver si ten\u00edan espacio para CCK. El propietario de Mavericks, Mark Cuban, hizo posibles los viajes.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"450\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/USACanada\/Texas\/Mavs2.jpg\" width=\"600\"><\/p>\n<\/div>\n<\/div>\n<p>Heart a Heart tambi\u00e9n est\u00e1 programado para volar otro env\u00edo de suministros en nombre de los Ministerios Nazarenos Compasivos el 9 de octubre. La carga planea de ayuda incluir\u00e1 generadores, tarps, bater\u00edas, productos enlatados, pa\u00f1ales, comida para beb\u00e9s y f\u00f3rmula para beb\u00e9s. Los generadores y las bater\u00edas, en particular, ayudar\u00e1n a proporcionar necesidades urgentes. Los funcionarios estiman que tomar\u00e1 hasta seis meses <a href=\"http:\/\/www.latimes.com\/nation\/la-na-puerto-rico-power-20170925-story.html\" target=\"_blank\">restaurar la energ\u00eda<\/a> a toda la isla.<\/p>\n<p>Nestor Hernandez creci\u00f3 en Puerto Rico, donde su padre, Andres Hernandez, sirve como superintendente de distrito del Distrito Este del pa\u00eds. Nestor, que sirve como pastor de la vida juvenil y la comunidad en Melbourne, Florida, est\u00e1 actualmente en Puerto Rico ayudando a coordinar env\u00edos y los esfuerzos de respuesta a desastres en nombre de los Ministerios Nazarenos Compasivos.<\/p>\n<p>Por favor, contin\u00fae orando, escribi\u00f3 en un informe de las actividades de la iglesia. Mientras continuamos conect\u00e1ndonos con las iglesias, el n\u00famero de nazarenos desplazados aumenta.<\/p>\n<p>La situaci\u00f3n en Puerto Rico est\u00e1 creciendo m\u00e1s preocupante el d\u00eda. La mayor\u00eda de las \u00e1reas est\u00e1n sin energ\u00eda, creando situaciones que amenazan la vida para las personas que dependen del poder para tratamientos m\u00e9dicos, as\u00ed como para atender a los residentes de hogares que son vulnerables al calor excesivo. Tambi\u00e9n hay una escasez de alimentos y agua potable segura.<\/p>\n<p>Hay mucho trabajo que hacer, pero tenemos nazarenos incre\u00edbles que est\u00e1n emocionados de salir de sus hogares y hacer algo por su isla, escribi\u00f3 Nestor. Gracias a NCM y el apoyo de la iglesia global, ahora est\u00e1n recibiendo recursos para hacerlo.<\/p>\n<p>Si bien los suministros est\u00e1n en el camino, se necesita m\u00e1s ayuda. Aquellos que quieren apoyar los esfuerzos de respuesta a desastres en Puerto Rico se alientan a visitar <a href=\"http:\/\/www.ncm.org\/maria.html\">ncm.org\/Maria<\/a>.<\/p>\n<p><strong>C\u00f3mo ayudar<\/strong><\/p>\n<p><strong>Orar<\/strong><\/p>\n<p>Ore por aquellos que son m\u00e1s vulnerables a la p\u00e9rdida de poder y la escasez de alimentos y agua segura. Ore por las familias y las personas que se dejan para reconstruir sus vidas, que los recursos vendr\u00edan. Ore por aquellos que est\u00e1n de duelo por la p\u00e9rdida de seres queridos. Ore por aquellos que est\u00e1n temerosos, de que experimentar\u00edan el amor y la paz de Cristo. Ore por la seguridad para los l\u00edderes de la iglesia local y los voluntarios mientras viajan para distribuir ayuda a aquellos que la necesitan. Para enviar una oraci\u00f3n o nota de aliento, vaya a <a href=\"http:\/\/www.ncm.org\/pray.html\">ncm.org\/pray<\/a>.<\/p>\n<p><strong>Voluntario<\/strong><\/p>\n<p>Los viajes todav\u00eda son limitados, y las iglesias a\u00fan no pueden recibir voluntarios. Cualquiera interesado en ser voluntario una vez que se abran posibilidades puede completar un formulario de informaci\u00f3n de voluntarios en <a href=\"http:\/\/www.ncm.org\/maria.html\">ncm.org\/Maria<\/a>.<\/p>\n<p><strong>DAR<\/strong><\/p>\n<p>Las iglesias y las personas de todo el mundo pueden proporcionar apoyo &nbsp;a trav\u00e9s del Fondo de Socorro de <a href=\"https:\/\/give.nazarene.org\/donate\/f\/128313\">Emergencia: Hurac\u00e1n Mar\u00eda<\/a>. Las donaciones se usar\u00e1n para suministros de emergencia, as\u00ed como para la recuperaci\u00f3n a largo plazo y los esfuerzos de reconstrucci\u00f3n.<\/p>\n<p>Para enviar donaciones por correo:<\/p>\n<p>En &nbsp;the<strong>.U.<\/strong>, haga cheques pagables al \u00abTesorero General\u00bb y env\u00edelos a:&nbsp;<\/p>\n<p>Servicios globales de tesorer\u00eda<br \/>\nIglesia del Nazareno<br \/>\nP.O. Box 843116<br \/>\nKansas City, MO 64184-3116<\/p>\n<p>Aseg\u00farese de poner <strong>128313<\/strong> en el \u00e1rea de Memo.<\/p>\n<p>In&nbsp;<strong>Canada<\/strong>, haga cheques pagables a la \u00abIglesia de la Nazarena de Canad\u00e1\u00bb y env\u00edelos a:<\/p>\n<p>Iglesia de la Nazarena de Canad\u00e1<br \/>\n20 Regan Road, Unidad 9<br \/>\nBrampton, Ontario L7A 1C3<\/p>\n<p>Aseg\u00farese de poner <strong>128313<\/strong> en el \u00e1rea de Memo.<\/p>\n<p><strong>Para cualquier otro pa\u00eds<\/strong>, d\u00e9 a trav\u00e9s de su iglesia local o distrito, &nbsp;designando su regalo al <strong>Fondo de Socorro de Emergencia: Hurac\u00e1n Mar\u00eda.<\/strong><\/p>\n<p><a href=\"http:\/\/www.ncm.org\/\" target=\"_blank\">Ministerios nazarenos compasivos<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" alt=\"\" height=\"400\" src=\"\/sites\/default\/files\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Ri&lt;\/div&gt;\"><\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[1395,807,2097],"class_list":["post-53276","news","type-news","status-publish","hentry","news-tag-mesoamerica-es","news-tag-ncm-es","news-tag-puerto-rico-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Rico\/UnloadinginArecibo.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\\\/\",\"name\":\"Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Mesoamerica\\\/Puerto%20Rico\\\/UnloadinginArecibo.jpg\",\"datePublished\":\"2019-07-10T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Mesoamerica\\\/Puerto%20Rico\\\/UnloadinginArecibo.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Mesoamerica\\\/Puerto%20Rico\\\/UnloadinginArecibo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/","og_locale":"es_ES","og_type":"article","og_title":"Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda","og_url":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","og_image":[{"url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Rico\/UnloadinginArecibo.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/","url":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/","name":"Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Rico\/UnloadinginArecibo.jpg","datePublished":"2019-07-10T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Rico\/UnloadinginArecibo.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Mesoamerica\/Puerto%20Rico\/UnloadinginArecibo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/las-iglesias-se-movilizan-en-puerto-rico-despues-del-huracan-maria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"Las iglesias se movilizan en Puerto Rico despu\u00e9s del hurac\u00e1n Mar\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/53276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/53276\/revisions"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=53276"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=53276"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=53276"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=53276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}