{"id":53241,"date":"2019-07-10T00:00:00","date_gmt":"2019-07-10T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/"},"modified":"2019-07-10T00:00:00","modified_gmt":"2019-07-10T05:00:00","slug":"los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/","title":{"rendered":"Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Africa\/HOAVillage.jpg\" width=\"750\"><\/p>\n<p>El verano de 2017 ha tenido m\u00e1s de su parte de desastres naturales: huracanes Harvey, Irma y Maria, terremotos en M\u00e9xico, deslizamientos de tierra en Sierra Leona, inundaciones en la India y Bangladesh, da\u00f1o a la propiedad sin precedentes y una p\u00e9rdida continua de vida. La migraci\u00f3n humana, impulsada por la guerra, la enfermedad, el desastre y el hambre ha interrumpido millones de vidas. Las agencias de ayuda, los voluntarios y los donantes intentan mantenerse con una calamidad despu\u00e9s de otra mientras anticipan la pr\u00f3xima crisis.<\/p>\n<p>Sintiendo la fatiga de dar hacia otro desastre, recib\u00ed un correo electr\u00f3nico humilde y desgarrador del reverendo Don Gardner, coordinador de estrategia de campo de la Iglesia de la Nazarena en \u00c1frica Oriental. Fue una llamada al alivio del desastre en respuesta a los deslizamientos de tierra en Sierra Leona que mataron a aproximadamente 1,000 personas.&nbsp;<\/p>\n<p>Katy Rodebush, coordinadora del Ministerio Nazareno Compasivo para el Cuerno de \u00c1frica, escribi\u00f3 a Gardner preguntando si el Cuerno de \u00c1frica podr\u00eda recibir una ofrenda especial en todos sus distritos en el Horn para apoyar a sus hermanos y hermanas en Sierra Leona.&nbsp;<\/p>\n<p>Respuesta de Gardner:&nbsp;\u00abAbsolutamente\u00bb<\/p>\n<p>Katy escribi\u00f3 alg\u00fan tiempo despu\u00e9s dando los detalles espec\u00edficos de los distritos que dieron, teniendo en cuenta que cada una de estas \u00e1reas est\u00e1 experimentando la peor sequ\u00eda en la historia registrada. Estos distritos y \u00e1reas pudieron dar un gran total de US$2,021.&nbsp;<\/p>\n<p>La cadena de correo electr\u00f3nico contin\u00faa con un mensaje incre\u00edble del reverendo John Yual, superintendente de distrito de la Iglesia de la Nazarena sirviendo a refugiados en el Cuerno de \u00c1frica.<\/p>\n<p>Ahora, la Iglesia de la Nazarena en el \u00c1rea 1 ha contribuido con $517. Algunas de las colecciones se hicieron en ma\u00edz (asignaci\u00f3n de alimentos) en los campamentos de refugiados, y las vendemos y llegar a esa cantidad &#8230; Muchos de nuestros miembros en los campamentos de refugiados han intentado su mejor.&nbsp;<\/p>\n<p>S\u00ed, lees eso correctamente. Los miembros de la iglesia &nbsp;en el &nbsp;campamento de refugiados en el Cuerno de \u00c1frica, donde hay una hambruna severa, vendieron su asignaci\u00f3n de ma\u00edz para que pudieran donar a ayudar a los sobrevivientes en Sierra Leona.<\/p>\n<p>Quiz\u00e1s uno de los mensajes m\u00e1s convincentes del campo fue del liderazgo en Addis Abba que escribi\u00f3, \u00abHay varias iglesias locales peque\u00f1as y remotas en el \u00c1rea II de Etiop\u00eda que han recopilado algo de dinero, pero a\u00fan no han podido enviarlo a nosotros; el banco m\u00e1s cercano es viajar de uno a dos d\u00edas lejos de ellos\u00bb.<\/p>\n<p>Estos correos electr\u00f3nicos se enfocan en una de las regiones m\u00e1s pobres del mundo, donde sus personas experimentan regularmente el trauma y la p\u00e9rdida asociada con la guerra, la guerra civil, la sequ\u00eda, el hambre y la enfermedad, <em>pero esta regi\u00f3n recopil\u00f3 un total de US$2,538.<\/em><\/p>\n<p>\u00bfQu\u00e9 es las personas de fe que las lleva a tales niveles de sacrificio y compasi\u00f3n que dan de sus escasos medios para ayudar a las personas que han perdido todos los medios?<\/p>\n<p>Este sacrificio de nuestros hermanos y hermanas africanos renunciando a su comida para ayudar a las personas a miles de millas de distancia, personas que nunca conocer\u00e1n, &nbsp;es realmente humillante. Est\u00e1n preparados para \u00abvenir al lado\u00bb del sufrimiento de extranjeros y, de su pobreza, dar aliento y esperanza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" alt=\"\" height=\"400\" src=\"\/sites\/default\/files\/migrated_images\/NCN%20News\/Africa\/HOAVillage.jpg&lt;\/div&gt;\"><\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[877,2478,1688,1481,1529,1395,1474,2273,2026],"class_list":["post-53241","news","type-news","status-publish","hentry","news-tag-africa-es","news-tag-bangladesh-es","news-tag-etiopia-es","news-tag-eurasia-es","news-tag-india-es","news-tag-mesoamerica-es","news-tag-mexico-es","news-tag-refugiado-es","news-tag-sierra-leona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Africa\/HOAVillage.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\\\/\",\"name\":\"Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Africa\\\/HOAVillage.jpg\",\"datePublished\":\"2019-07-10T05:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Africa\\\/HOAVillage.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/migrated_images\\\/NCN%20News\\\/Africa\\\/HOAVillage.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/","og_locale":"es_ES","og_type":"article","og_title":"Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento","og_url":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","og_image":[{"url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Africa\/HOAVillage.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/","url":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/","name":"Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Africa\/HOAVillage.jpg","datePublished":"2019-07-10T05:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Africa\/HOAVillage.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/migrated_images\/NCN%20News\/Africa\/HOAVillage.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/los-miembros-de-la-iglesia-del-cuerno-de-africa-contribuyen-al-alivio-del-desastre-a-pesar-del-hambre-el-desplazamiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"Los miembros de la iglesia del Cuerno de \u00c1frica contribuyen al alivio del desastre a pesar del hambre, el desplazamiento"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/53241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/53241\/revisions"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=53241"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=53241"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=53241"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=53241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}