{"id":50955,"date":"2020-01-31T00:00:00","date_gmt":"2020-01-31T06:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/all-terrain-4x4-hace-impacto-en-mexico\/"},"modified":"2020-01-31T00:00:00","modified_gmt":"2020-01-31T06:00:00","slug":"all-terrain-4x4-hace-impacto-en-mexico","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/","title":{"rendered":"All-Terrain 4&#215;4 hace impacto en M\u00e9xico"},"content":{"rendered":"<p>All-Terrain 4&#215;4 envi\u00f3 un equipo de j\u00f3venes y adolescentes a la ciudad de Monterrey, M\u00e9xico, &nbsp;a apo&nbsp;yar a las comunidades en la necesidad del 26 de diciembre de 2019 &nbsp;al 1 de enero de 2020, en las comunidades de Fomerrey 23 y Valle del Roble de Monterrey.<\/p>\n<p>Veintid\u00f3s j\u00f3venes presentaron el mensaje del Evangelio de varias maneras con el apoyo de los misioneros de G\u00e9nesis Daniel y Andrea Santiago. Pusieron en una escuela b\u00edblica de ni\u00f1os, oraron por los enfermos y limpiaron hogares. La Palabra se comparti\u00f3 individualmente y con familias en sus hogares, entre otros.<\/p>\n<p>Durante este tiempo, m\u00e1s de 60 ni\u00f1os fueron servidos, y 43 personas aceptaron a Jesucristo como su Se\u00f1or y Salvador.<\/p>\n<p>All-Terrain 4&#215;4 est\u00e1 celebrando su aniversario de 10 a\u00f1os este enero. Su misi\u00f3n es proporcionar un espacio para que los j\u00f3venes que participan &nbsp;en el Campamento de Orientaci\u00f3n de la Misi\u00f3n para descubrir o confirmar su llamada a misiones. Los j\u00f3venes son enviados durante una semana a trabajar para fortalecer nuevas misiones e iglesias y plantar nuevas iglesias.<\/p>\n<p>All-Terrain 4 \u00d7 4 se ha convertido en un evento que trae esperanza, paz, amor y salvaci\u00f3n a los hogares urbanos a trav\u00e9s de compartir a Jesucristo como el mejor regalo que las personas pueden recibir, dijo Mar\u00eda Eugenia Rodr\u00edguez, coordinadora del programa. Estoy agradecido a Dios por darme el privilegio de liderar a muchos j\u00f3venes durante 10 a\u00f1os, vi\u00e9ndolos desarrollarse y crecer en favor de Dios y los hombres.<\/p>\n<p>La participante Valeria Rodr\u00edguez, 14, comparti\u00f3 lo siguiente:&nbsp;<\/p>\n<p>Durante dos a\u00f1os Dios confirm\u00f3 mi llamada a las misiones. Durante el 4 \u00d7 4, mi equipo y yo tuvimos que ir a una casa con gran necesidad, y ofrecimos limpiarla. Conocimos a una ni\u00f1a de 19 a\u00f1os que cuid\u00f3 de su abuela que est\u00e1 en la cama y no puede moverse o hablar. \u00c9ramos un gran apoyo para ellos. Expres\u00f3 que no sab\u00eda c\u00f3mo agradecernos.&nbsp;<\/p>\n<p>Lo que m\u00e1s me golpe\u00f3 fue el momento que nos reunimos para orar por la mujer joven (Kelly) y la dama (Cristina). Tuvimos un tiempo cuando no pod\u00edamos dejar de llorar y le pedimos a Dios que cuidara de \u00e9l y lo sanara, para darles fuerza para seguir adelante. Dejamos muy felices, y repetimos esto durante tres d\u00edas. Siete personas aceptaron a Cristo en sus corazones.<\/p>\n<p>Lea su testimonio completo <a href=\"https:\/\/transformaelmundo.com\/2020\/01\/28\/que-clase-de-personas\/\" target=\"_blank\">aqu\u00ed<\/a>.<\/p>\n<p><a href=\"mesoamericaregion\">Iglesia de la Regi\u00f3n Nazarena de Mesoam\u00e9rica<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>All-Terrain 4&#215;4 envi\u00f3 un equipo de j\u00f3venes y adolescentes a la ciudad de Monterrey, M\u00e9xico, &nbsp;a apo&nbsp;yar a las comunidades en la necesidad del 26 de diciembre de 2019 &nbsp;al 1 de enero de 2020, en las comunidades de Fomerrey 23 y Valle del Roble de Monterrey. Veintid\u00f3s j\u00f3venes presentaron el mensaje del Evangelio de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25422,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[1474,854],"class_list":["post-50955","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-mexico-es","news-tag-region-de-mesoamerica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>All-Terrain 4x4 hace impacto en M\u00e9xico - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"All-Terrain 4x4 hace impacto en M\u00e9xico\" \/>\n<meta property=\"og:description\" content=\"All-Terrain 4&#215;4 envi\u00f3 un equipo de j\u00f3venes y adolescentes a la ciudad de Monterrey, M\u00e9xico, &nbsp;a apo&nbsp;yar a las comunidades en la necesidad del 26 de diciembre de 2019 &nbsp;al 1 de enero de 2020, en las comunidades de Fomerrey 23 y Valle del Roble de Monterrey. Veintid\u00f3s j\u00f3venes presentaron el mensaje del Evangelio de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/all-terrain-4x4-hace-impacto-en-mexico\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/all-terrain-4x4-hace-impacto-en-mexico\\\/\",\"name\":\"All-Terrain 4x4 hace impacto en M\u00e9xico - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/all-terrain-4x4-hace-impacto-en-mexico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/all-terrain-4x4-hace-impacto-en-mexico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/4X4-Picture.jpg\",\"datePublished\":\"2020-01-31T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/all-terrain-4x4-hace-impacto-en-mexico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/all-terrain-4x4-hace-impacto-en-mexico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/all-terrain-4x4-hace-impacto-en-mexico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/4X4-Picture.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/4X4-Picture.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/all-terrain-4x4-hace-impacto-en-mexico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"All-Terrain 4&#215;4 hace impacto en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"All-Terrain 4x4 hace impacto en M\u00e9xico - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/","og_locale":"es_ES","og_type":"article","og_title":"All-Terrain 4x4 hace impacto en M\u00e9xico","og_description":"All-Terrain 4&#215;4 envi\u00f3 un equipo de j\u00f3venes y adolescentes a la ciudad de Monterrey, M\u00e9xico, &nbsp;a apo&nbsp;yar a las comunidades en la necesidad del 26 de diciembre de 2019 &nbsp;al 1 de enero de 2020, en las comunidades de Fomerrey 23 y Valle del Roble de Monterrey. Veintid\u00f3s j\u00f3venes presentaron el mensaje del Evangelio de [&hellip;]","og_url":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/","url":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/","name":"All-Terrain 4x4 hace impacto en M\u00e9xico - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/4X4-Picture.jpg","datePublished":"2020-01-31T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/4X4-Picture.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/4X4-Picture.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/all-terrain-4x4-hace-impacto-en-mexico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"All-Terrain 4&#215;4 hace impacto en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/50955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/50955\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/25422"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=50955"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=50955"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=50955"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=50955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}