{"id":50219,"date":"2020-06-05T00:00:00","date_gmt":"2020-06-05T05:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/"},"modified":"2025-07-01T20:51:56","modified_gmt":"2025-07-02T01:51:56","slug":"distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/","title":{"rendered":"Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas"},"content":{"rendered":"<p>El Distrito de Vanuatu envi\u00f3 recientemente a su primer equipo a la isla del norte de Espiritu Santo para comenzar a establecer la Iglesia de la presencia de la nazarena all\u00ed.&nbsp;<\/p>\n<p>El equipo particip\u00f3 en un servicio de comisionamiento a mediados de mayo. Durante el servicio, una pastora testific\u00f3 que hab\u00eda estado orando durante muchos a\u00f1os para que Dios ayudara a traer el mensaje de santidad a su familia en Santo.&nbsp;<\/p>\n<p>Dios ha respondido a mis oraciones, dijo.&nbsp;<\/p>\n<p>Cuando el equipo lleg\u00f3 a la primera aldea, comenzaron a ganar la confianza de los residentes distribuyendo peces, ropa, platos, tazas y cucharas. Tambi\u00e9n entregaron Biblias y libros para los ni\u00f1os. El jefe de la aldea acept\u00f3 sus regalos, dando su bendici\u00f3n para que el equipo evangelice alrededor de la aldea.&nbsp;<\/p>\n<p>Cada noche, el equipo celebr\u00f3 un servicio de adoraci\u00f3n. El 23 de mayo, 21 personas aceptaron a Cristo como su Se\u00f1or y Salvador. La siguiente noche, el equipo celebr\u00f3 un gran servicio de adoraci\u00f3n donde otras 15 personas comprometieron sus vidas a Cristo.<\/p>\n<p>Esta han sido nuestras oraciones durante mucho tiempo, traer a la Iglesia de la Nazarena a las islas del norte, y Dios est\u00e1 respondiendo nuestra oraci\u00f3n, *Peter.<\/p>\n<p>Un nuevo creyente ofreci\u00f3 su propiedad como una ubicaci\u00f3n para un refugio de la iglesia. M\u00e1s tarde, un segundo hombre le pidi\u00f3 al equipo que construyera el refugio en el centro de la aldea. El equipo estaba feliz de cambiar ubicaciones y construy\u00f3 la estructura con la ayuda de varios hombres de la aldea.<\/p>\n<p>Otros dos equipos tambi\u00e9n fueron comisionados en el servicio como parte del proyecto del distrito para llegar a nuevas \u00e1reas. El segundo equipo viajar\u00e1 a otras dos islas del norte, Malekula y Ambrym, y el tercer equipo seguir\u00e1.&nbsp;<\/p>\n<p><em>*Nombre retenido por razones de seguridad<\/em><\/p>\n<p><a href=\"asiapacificnazarene.org\" target=\"_blank\">Iglesia de la Nazarena de Asia-Pac\u00edfico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Distrito de Vanuatu envi\u00f3 recientemente a su primer equipo a la isla del norte de Espiritu Santo para comenzar a establecer la Iglesia de la presencia de la nazarena all\u00ed. Como resultado, casi 40 personas aceptaron a Cristo.<\/p>\n","protected":false},"author":1,"featured_media":26014,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[927,1542],"class_list":["post-50219","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-asia-y-el-pacifico","news-tag-vanuatu-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas\" \/>\n<meta property=\"og:description\" content=\"El Distrito de Vanuatu envi\u00f3 recientemente a su primer equipo a la isla del norte de Espiritu Santo para comenzar a establecer la Iglesia de la presencia de la nazarena all\u00ed. Como resultado, casi 40 personas aceptaron a Cristo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T01:51:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Vanuatu-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\\\/\",\"name\":\"Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Vanuatu-3.jpg\",\"datePublished\":\"2020-06-05T05:00:00+00:00\",\"dateModified\":\"2025-07-02T01:51:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Vanuatu-3.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Vanuatu-3.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/","og_locale":"es_ES","og_type":"article","og_title":"Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas","og_description":"El Distrito de Vanuatu envi\u00f3 recientemente a su primer equipo a la isla del norte de Espiritu Santo para comenzar a establecer la Iglesia de la presencia de la nazarena all\u00ed. Como resultado, casi 40 personas aceptaron a Cristo.","og_url":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","article_modified_time":"2025-07-02T01:51:56+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Vanuatu-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/","url":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/","name":"Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Vanuatu-3.jpg","datePublished":"2020-06-05T05:00:00+00:00","dateModified":"2025-07-02T01:51:56+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Vanuatu-3.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/Vanuatu-3.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/distrito-de-vanuatu-comienza-el-trabajo-en-las-islas-no-alcanzadas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"Distrito de Vanuatu comienza el trabajo en las islas no alcanzadas"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/50219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/50219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/26014"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=50219"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=50219"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=50219"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=50219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}