{"id":43452,"date":"2023-11-16T00:00:00","date_gmt":"2023-11-16T06:00:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/"},"modified":"2023-11-16T00:00:00","modified_gmt":"2023-11-16T06:00:00","slug":"el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/","title":{"rendered":"El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India"},"content":{"rendered":"<p>Un retiro de matrimonio para los l\u00edderes y sus c\u00f3nyuges se celebr\u00f3 en el Centro Internacional de Goa en la India del 17 al 19 de octubre de 2023, centrado en el tema \u00abFirewall Su Matrimonio\u00bb. Los principales oradores de la conferencia fueron Franky y Shabeena Fernandes, y Pravin Samudre.&nbsp;<\/p>\n<p>A lo largo del retiro, los asistentes participaron en discusiones que cubren varios temas, incluido el perd\u00f3n, el dise\u00f1o de Dios del matrimonio, la intimidad con Dios, la intimidad con su c\u00f3nyuge, la coadministraci\u00f3n, la cobertura de oraci\u00f3n por el matrimonio, la idea de Dios de la paternidad, y salir, escindir y la unidad. En el primer d\u00eda, se pidi\u00f3 a todos que completaran un formulario de autoevaluaci\u00f3n, que benefici\u00f3 tanto a los facilitadores como a los asistentes.<\/p>\n<p>Una salida a la playa se program\u00f3 durante una tarde, y todos tuvieron un buen tiempo. El personal de la Oficina de Campo de la India cuid\u00f3 de los hijos de los asistentes, nueve de ellos, &nbsp;todos bajo 12. Los ni\u00f1os estaban involucrados en actividades al aire libre y bajo techo, saboreando la piscina del centro, dibujando y cantando canciones de adoraci\u00f3n. Franky y Getsy Raja lideraron sesiones devocionales orientadas a la familia. El retiro concluy\u00f3 con la Comuni\u00f3n, donde los c\u00f3nyuges intercambiaron elementos de la Comuni\u00f3n.<br \/>\nLos l\u00edderes y sus c\u00f3nyuges expresaron gratitud por la oportunidad de participar en el retiro, se\u00f1alando su impacto positivo en su enfoque de su matrimonio. Algunas parejas identificaron \u00e1reas donde quer\u00edan enfocarse m\u00e1s en avanzar.&nbsp;<\/p>\n<p>El retiro de la familia de los Leaders [reson\u00f3 con] &nbsp;mi esposa y yo &nbsp;personalmente y nos ayud\u00f3 a evaluarnos y a identificar y rectificar las brechas en nuestro matrimonio, dijo S. Wilson Jabaraj, un asistente.<\/p>\n<p>En general, el retiro demostr\u00f3 ser una fuente de gran refresco y energ\u00eda renovada para cada pareja, dej\u00e1ndolos a regresar a su ministerio con la alegr\u00eda reci\u00e9n encontrada y una perspectiva transformada en el matrimonio y la familia.<br \/>\nEsta conferencia me ha proporcionado nuevas ideas sobre la familia y la crianza de los hijos, dijo Manohar Pawar, otro asistente. Muchos de nosotros pudimos identificar nuestros propios defectos gracias a las propias experiencias de los oradores de la conferencia.<\/p>\n<p>Iglesia de la Regi\u00f3n Nazarena de Eurasia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un retiro de matrimonio para los l\u00edderes y sus c\u00f3nyuges se celebr\u00f3 en el Centro Internacional de Goa en la India del 17 al 19 de octubre de 2023, centrado en el tema \u00abFirewall Su Matrimonio\u00bb.<\/p>\n","protected":false},"author":1,"featured_media":29986,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[1529,809],"class_list":["post-43452","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-india-es","news-tag-region-de-eurasia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India\" \/>\n<meta property=\"og:description\" content=\"Un retiro de matrimonio para los l\u00edderes y sus c\u00f3nyuges se celebr\u00f3 en el Centro Internacional de Goa en la India del 17 al 19 de octubre de 2023, centrado en el tema &quot;Firewall Su Matrimonio&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\\\/\",\"name\":\"El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/India-Marriage-Retreat.png\",\"datePublished\":\"2023-11-16T06:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/India-Marriage-Retreat.png\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/India-Marriage-Retreat.png\",\"width\":3126,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/","og_locale":"es_ES","og_type":"article","og_title":"El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India","og_description":"Un retiro de matrimonio para los l\u00edderes y sus c\u00f3nyuges se celebr\u00f3 en el Centro Internacional de Goa en la India del 17 al 19 de octubre de 2023, centrado en el tema \"Firewall Su Matrimonio\".","og_url":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/","url":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/","name":"El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/India-Marriage-Retreat.png","datePublished":"2023-11-16T06:00:00+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/India-Marriage-Retreat.png","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/02\/India-Marriage-Retreat.png","width":3126,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/el-retiro-del-matrimonio-y-la-familia-trae-la-renovacion-a-los-lideres-de-la-india\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"El retiro del matrimonio y la Familia trae la renovaci\u00f3n a los l\u00edderes de la India"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/43452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/43452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/29986"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=43452"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=43452"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=43452"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=43452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}