{"id":42369,"date":"2025-04-15T01:56:00","date_gmt":"2025-04-15T06:56:00","guid":{"rendered":"https:\/\/nazarene.org\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/"},"modified":"2025-07-08T22:31:53","modified_gmt":"2025-07-09T03:31:53","slug":"vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra","status":"publish","type":"news","link":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/","title":{"rendered":"Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En febrero de 2025, Vandana Kinkar fue elegida superintendente del Distrito Oriental de Maharashtra de la India.<\/p>\n\n<p class=\"wp-block-paragraph\">Su elecci\u00f3n es efectiva el 18 de marzo de 2025. Sigue a Daniel Bhalero, que est\u00e1 jubil\u00e1ndose despu\u00e9s de liderar el distrito del Este de Maharashtra durante la \u00faltima d\u00e9cada.<br\/>El nombramiento de Kinkar es un testimonio de su compromiso de por vida de servir al Se\u00f1or y la iglesia.<\/p>\n\n<p class=\"wp-block-paragraph\">Vandana acept\u00f3 a Cristo a una edad joven y dedic\u00f3 sus primeros a\u00f1os adultos a servir en el ministerio juvenil, finalmente convirti\u00e9ndose en la presidenta juvenil de distrito en 1988. En 1992, se cas\u00f3 con Madhukar Kinkar, un pastor y profesor en el Colegio B\u00edblico Nazareno en Washim, Maharashtra.<\/p>\n\n<p class=\"wp-block-paragraph\">Vandana persigui\u00f3 carreras en la educaci\u00f3n y la administraci\u00f3n mientras apoyaba activamente a sus Misiones Nazarenas Internacionales locales y los ministerios de la escuela dominical. Complet\u00f3 sus estudios teol\u00f3gicos en el Colegio B\u00edblico Nazareno de Asia del Sur y recibi\u00f3 la licencia de su predicador de distrito. En 2019, la Iglesia de la Nazarena la orden\u00f3 como anciano.<\/p>\n\n<p class=\"wp-block-paragraph\">Ha servido en varios roles de liderazgo, incluido como miembro de la junta asesora de distrito desde 2022. Su elecci\u00f3n como superintendente de distrito es un reconocimiento de su fe firme, el liderazgo y la dedicaci\u00f3n al reino de Dios.<\/p>\n\n<p class=\"wp-block-paragraph\">Este es el hacer del Se\u00f1or, comparte Vandana. Alabo a Dios por esta enorme e importante responsabilidad. Har\u00e9 mi mejor para servir con la servidumbre y la humildad de Jesucristo para mejorar su reino.<\/p>\n\n<p class=\"wp-block-paragraph\">Iglesia de la Regi\u00f3n Nazarena de Eurasia<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En febrero de 2025, Vandana Kinkar fue elegida superintendente del Distrito Oriental de Maharashtra de la India. Su elecci\u00f3n es efectiva el 18 de marzo de 2025. Sigue a Daniel Bhalero, que est\u00e1 jubil\u00e1ndose despu\u00e9s de liderar el distrito del Este de Maharashtra durante la \u00faltima d\u00e9cada.El nombramiento de Kinkar es un testimonio de su [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":32442,"menu_order":0,"template":"","news-categories":[],"news-region-taxonomy":[],"news-tag":[1481,1529],"class_list":["post-42369","news","type-news","status-publish","has-post-thumbnail","hentry","news-tag-eurasia-es","news-tag-india-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra - Church of the Nazarene<\/title>\n<meta name=\"description\" content=\"En febrero de 2025, Vandana Kinkar fue elegida superintendente del Distrito Oriental de Maharashtra de la India. El nombramiento es efectivo el 18 de marzo de 2025. Sigue a Daniel Bhalero, que est\u00e1 jubil\u00e1ndose despu\u00e9s de liderar el distrito del Este de Maharashtra durante la \u00faltima d\u00e9cada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra\" \/>\n<meta property=\"og:description\" content=\"En febrero de 2025, Vandana Kinkar fue elegida superintendente del Distrito Oriental de Maharashtra de la India. El nombramiento es efectivo el 18 de marzo de 2025. Sigue a Daniel Bhalero, que est\u00e1 jubil\u00e1ndose despu\u00e9s de liderar el distrito del Este de Maharashtra durante la \u00faltima d\u00e9cada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T03:31:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/India-DS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1550\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\\\/\",\"name\":\"Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/India-DS.jpg\",\"datePublished\":\"2025-04-15T06:56:00+00:00\",\"dateModified\":\"2025-07-09T03:31:53+00:00\",\"description\":\"En febrero de 2025, Vandana Kinkar fue elegida superintendente del Distrito Oriental de Maharashtra de la India. El nombramiento es efectivo el 18 de marzo de 2025. Sigue a Daniel Bhalero, que est\u00e1 jubil\u00e1ndose despu\u00e9s de liderar el distrito del Este de Maharashtra durante la \u00faltima d\u00e9cada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/India-DS.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/India-DS.jpg\",\"width\":1550,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra - Church of the Nazarene","description":"En febrero de 2025, Vandana Kinkar fue elegida superintendente del Distrito Oriental de Maharashtra de la India. El nombramiento es efectivo el 18 de marzo de 2025. Sigue a Daniel Bhalero, que est\u00e1 jubil\u00e1ndose despu\u00e9s de liderar el distrito del Este de Maharashtra durante la \u00faltima d\u00e9cada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/","og_locale":"es_ES","og_type":"article","og_title":"Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra","og_description":"En febrero de 2025, Vandana Kinkar fue elegida superintendente del Distrito Oriental de Maharashtra de la India. El nombramiento es efectivo el 18 de marzo de 2025. Sigue a Daniel Bhalero, que est\u00e1 jubil\u00e1ndose despu\u00e9s de liderar el distrito del Este de Maharashtra durante la \u00faltima d\u00e9cada.","og_url":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","article_modified_time":"2025-07-09T03:31:53+00:00","og_image":[{"width":1550,"height":800,"url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/India-DS.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/","url":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/","name":"Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/India-DS.jpg","datePublished":"2025-04-15T06:56:00+00:00","dateModified":"2025-07-09T03:31:53+00:00","description":"En febrero de 2025, Vandana Kinkar fue elegida superintendente del Distrito Oriental de Maharashtra de la India. El nombramiento es efectivo el 18 de marzo de 2025. Sigue a Daniel Bhalero, que est\u00e1 jubil\u00e1ndose despu\u00e9s de liderar el distrito del Este de Maharashtra durante la \u00faltima d\u00e9cada.","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/India-DS.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/04\/India-DS.jpg","width":1550,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/news\/vandana-kinkar-elegida-superintendente-del-distrito-del-este-de-maharashtra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/nazarene.org\/es\/news\/"},{"@type":"ListItem","position":3,"name":"Vandana Kinkar elegida superintendente del Distrito del Este de Maharashtra"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/42369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/users\/12"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news\/42369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/32442"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=42369"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-categories?post=42369"},{"taxonomy":"news-region-taxonomy","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-region-taxonomy?post=42369"},{"taxonomy":"news-tag","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/news-tag?post=42369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}