{"id":44851,"date":"2024-06-27T13:38:45","date_gmt":"2024-06-27T18:38:45","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/"},"modified":"2024-06-27T13:38:45","modified_gmt":"2024-06-27T18:38:45","slug":"ndi-en-palcon-matters-debido-a-usted","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/","title":{"rendered":"NDI en PALCON Matters Debido a usted"},"content":{"rendered":"<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">El Discipleship Nazareno Internacional (NDI) se siente honrado de estar presente en cada uno de los tres PALCONs de Estados Unidos 2024. La oportunidad de conectarse y establecer una red con usted es siempre un honor que nuestra oficina no toma por garantizado. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">Las conversaciones en la mesa de exhibiciones de NDI importan porque nos permiten escuchar y aprender de usted. Gracias si asisti\u00f3 a un PALCON y se detuvo para vernos. Si su PALCON a\u00fan est\u00e1 por venir, vis\u00edtenos en nuestra mesa de exhibici\u00f3n y entre en el dibujo para un regalo. M\u00e1s que cualquier cosa, queremos saber c\u00f3mo podemos servirlo, orar con usted y venir junto a usted en el ministerio.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">El Ministerio de Discapacidad de NDI, liderado por el reverendo Ryan Nelson (<a href=\"mailto:rnelson@nazarene.org\" style=\"color:#0563c1; text-decoration:underline\">rnelson@nazarene.org<\/a>), tiene talleres en cada PALCON. El equipo, incluido Barbara Stanley y Leah Whicker del Ministerio de <a href=\"https:\/\/www.wonderfulworks.net\/\" style=\"color:#0563c1; text-decoration:underline\">Wonderful Works<\/a>, ha comenzado a consultar y proporcionar recursos a las iglesias, y PALCON proporciona una gran oportunidad de compartir y desarrollar relaciones. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">El <a href=\"https:\/\/discipleshipplace.org\/\" style=\"color:#0563c1; text-decoration:underline\">Discipleship Place<\/a> celebr\u00f3 talleres sobre el discipleship como un Viaje de curaci\u00f3n y Un Plan Digital para el Discipleship Diario en la iglesia local en los ENC y MVNU PALCONs. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">Queremos agradecerle por su fidelidad a la formaci\u00f3n de disc\u00edpulos y su deseo de ayudar a otro a caminar m\u00e1s de cerca con Jesucristo. Estamos mejor juntos.<\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":22655,"menu_order":0,"template":"","ndi-journey-tags":[2028],"class_list":["post-44851","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-ndi-en-palcon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>NDI en PALCON Matters Debido a usted - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NDI en PALCON Matters Debido a usted\" \/>\n<meta property=\"og:description\" content=\"El Discipleship Nazareno Internacional (NDI) se siente honrado de estar presente en cada uno de los tres PALCONs de Estados Unidos 2024. La oportunidad de conectarse y establecer una red con usted es siempre un honor que nuestra oficina no toma por garantizado. Las conversaciones en la mesa de exhibiciones de NDI importan porque nos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/ndi-en-palcon-matters-debido-a-usted\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/ndi-en-palcon-matters-debido-a-usted\\\/\",\"name\":\"NDI en PALCON Matters Debido a usted - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/ndi-en-palcon-matters-debido-a-usted\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/ndi-en-palcon-matters-debido-a-usted\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Social-Media-Templates_Banner-Image_v1.png\",\"datePublished\":\"2024-06-27T18:38:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/ndi-en-palcon-matters-debido-a-usted\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/ndi-en-palcon-matters-debido-a-usted\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/ndi-en-palcon-matters-debido-a-usted\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Social-Media-Templates_Banner-Image_v1.png\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Social-Media-Templates_Banner-Image_v1.png\",\"width\":4000,\"height\":2095},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/ndi-en-palcon-matters-debido-a-usted\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NDI en PALCON Matters Debido a usted\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NDI en PALCON Matters Debido a usted - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/","og_locale":"es_ES","og_type":"article","og_title":"NDI en PALCON Matters Debido a usted","og_description":"El Discipleship Nazareno Internacional (NDI) se siente honrado de estar presente en cada uno de los tres PALCONs de Estados Unidos 2024. La oportunidad de conectarse y establecer una red con usted es siempre un honor que nuestra oficina no toma por garantizado. Las conversaciones en la mesa de exhibiciones de NDI importan porque nos [&hellip;]","og_url":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/","url":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/","name":"NDI en PALCON Matters Debido a usted - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Social-Media-Templates_Banner-Image_v1.png","datePublished":"2024-06-27T18:38:45+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Social-Media-Templates_Banner-Image_v1.png","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Social-Media-Templates_Banner-Image_v1.png","width":4000,"height":2095},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/ndi-en-palcon-matters-debido-a-usted\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/es\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"NDI en PALCON Matters Debido a usted"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/44851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/44851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/22655"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=44851"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey-tags?post=44851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}