{"id":41499,"date":"2025-03-11T15:38:56","date_gmt":"2025-03-11T20:38:56","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/lo-que-estamos-aqui-para\/"},"modified":"2025-03-11T15:38:56","modified_gmt":"2025-03-11T20:38:56","slug":"lo-que-estamos-aqui-para","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/","title":{"rendered":"Lo que estamos aqu\u00ed para"},"content":{"rendered":"<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">\u00bfAlguna vez te has encontrado preguntando, \u00abQu\u00e9 estoy haciendo aqu\u00ed?\u00bb Espero que no sea el \u00fanico, Hice esa pregunta cuando estaba en el Ej\u00e9rcito cada vez que estaba a punto de saltar de un avi\u00f3n perfectamente bueno: \u00ab\u00bfQu\u00e9 estoy haciendo?\u00bb Hubo algunos d\u00edas cuando estaba haciendo una caminata en solo del Appalachian Trail que hice esa misma pregunta, \u00ab\u00bfQu\u00e9 estoy haciendo?\u00bb. Tambi\u00e9n he estado en las reuniones cuando he hecho esa pregunta, a veces en voz alta, \u00ab\u00bfQu\u00e9 estamos haciendo aqu\u00ed?\u00bb Quiz\u00e1s otra forma de hacer la pregunta es \u00ab\u00bfCu\u00e1l es el punto?\u00bb Es importante reducir la velocidad cada vez que a menudo y recordar la gran imagen: \u00bfqu\u00e9 es que estamos aqu\u00ed para lograr? La respuesta a esa pregunta debe ayudarnos a evaluar nuestras prioridades. \u00bfC\u00f3mo esta cosa (programa \/ actividad) nos ayuda a lograr esa cosa que estamos aqu\u00ed para hacer?<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">En la vida y el ministerio de Jes\u00fas, esa cosa fue la cruz. Seguro, hay muchas cosas importantes que Jes\u00fas hizo y orden\u00f3. Pero si Jes\u00fas nunca fue a la cruz e hizo eso una vez y para toda la expiaci\u00f3n por los pecados del mundo, \u00bfd\u00f3nde estar\u00edamos? La cruz era como un im\u00e1n gigante en el ministerio de Jes\u00fas, tir\u00e1ndolo hacia adelante. Jes\u00fas trat\u00f3 de preparar a los disc\u00edpulos para este climax cr\u00edtico y desgarrador de su ministerio, pero no lo aceptar\u00edan. Lucas 9:51 nos dice que Jes\u00fas \u00abresueltamente\u00bb se estableci\u00f3 para Jerusal\u00e9n y la cruz. Es lo que estaba aqu\u00ed para hacer. Este es el coraz\u00f3n del Evangelio, las buenas noticias para el mundo entero: puedes ser perdonado y reconciliado con Dios. <\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">No solo celebramos la expiaci\u00f3n en la Semana Santa (Viernes Santo), sino que tambi\u00e9n celebramos la esperanza de cambiar la vida de la Pascua, Jes\u00fas est\u00e1 resucitado. La cruz era un camino necesario para la resurrecci\u00f3n: no puedes tener uno sin el otro. Y es el primer fruto, la promesa y la garant\u00eda de la futura resurrecci\u00f3n corporal de cada creyente. No solo podemos ser perdonados de nuestros pecados y ser reconciliados con Dios, pero tambi\u00e9n podemos tener la victoria sobre la tumba. (1 Corintios 15) Como dice la canci\u00f3n, no es solo buenas noticias, es la \u00abmejor noticia de la historia\u00bb La cruz es el punto de todo, la raz\u00f3n por la que vino. Entonces, \u00bfpara qu\u00e9 estamos aqu\u00ed? Simplemente difundir la palabra. Somos creyentes en Jes\u00fas y lo que hizo, y estamos viviendo nuestra fe en la obediencia a los mandos de Jes\u00fas como sus seguidores. Luego estamos sobre compartir estas buenas noticias con otros; incluy\u00e9ndolos, bautiz\u00e1ndolos en la fe y ense\u00f1\u00e1ndoles a obedecer los mandos de Jes\u00fas tanto por nuestra palabra como por la acci\u00f3n (Mateo 28:19-20). <\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">Pascua, es lo que estamos aqu\u00ed. No te pierdas el punto.<\/span><\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":21843,"menu_order":0,"template":"","ndi-journey-tags":[1003],"class_list":["post-41499","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-pascua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lo que estamos aqu\u00ed para - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que estamos aqu\u00ed para\" \/>\n<meta property=\"og:description\" content=\"\u00bfAlguna vez te has encontrado preguntando, \u00abQu\u00e9 estoy haciendo aqu\u00ed?\u00bb Espero que no sea el \u00fanico, Hice esa pregunta cuando estaba en el Ej\u00e9rcito cada vez que estaba a punto de saltar de un avi\u00f3n perfectamente bueno: \u00ab\u00bfQu\u00e9 estoy haciendo?\u00bb Hubo algunos d\u00edas cuando estaba haciendo una caminata en solo del Appalachian Trail que hice [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/lo-que-estamos-aqui-para\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/lo-que-estamos-aqui-para\\\/\",\"name\":\"Lo que estamos aqu\u00ed para - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/lo-que-estamos-aqui-para\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/lo-que-estamos-aqui-para\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/wooden-crucifix-in-the-aragonese-castle-2024-05-29-22-23-51-utc-scaled.jpg\",\"datePublished\":\"2025-03-11T20:38:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/lo-que-estamos-aqui-para\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/lo-que-estamos-aqui-para\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/lo-que-estamos-aqui-para\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/wooden-crucifix-in-the-aragonese-castle-2024-05-29-22-23-51-utc-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/wooden-crucifix-in-the-aragonese-castle-2024-05-29-22-23-51-utc-scaled.jpg\",\"width\":1827,\"height\":2560,\"caption\":\"Wooden crucifix in the Aragonese Castle sheer above the sea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/lo-que-estamos-aqui-para\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lo que estamos aqu\u00ed para\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lo que estamos aqu\u00ed para - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/","og_locale":"es_ES","og_type":"article","og_title":"Lo que estamos aqu\u00ed para","og_description":"\u00bfAlguna vez te has encontrado preguntando, \u00abQu\u00e9 estoy haciendo aqu\u00ed?\u00bb Espero que no sea el \u00fanico, Hice esa pregunta cuando estaba en el Ej\u00e9rcito cada vez que estaba a punto de saltar de un avi\u00f3n perfectamente bueno: \u00ab\u00bfQu\u00e9 estoy haciendo?\u00bb Hubo algunos d\u00edas cuando estaba haciendo una caminata en solo del Appalachian Trail que hice [&hellip;]","og_url":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/","url":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/","name":"Lo que estamos aqu\u00ed para - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/wooden-crucifix-in-the-aragonese-castle-2024-05-29-22-23-51-utc-scaled.jpg","datePublished":"2025-03-11T20:38:56+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/wooden-crucifix-in-the-aragonese-castle-2024-05-29-22-23-51-utc-scaled.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/wooden-crucifix-in-the-aragonese-castle-2024-05-29-22-23-51-utc-scaled.jpg","width":1827,"height":2560,"caption":"Wooden crucifix in the Aragonese Castle sheer above the sea"},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/lo-que-estamos-aqui-para\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/es\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"Lo que estamos aqu\u00ed para"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/41499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/41499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/21843"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=41499"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey-tags?post=41499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}