{"id":41479,"date":"2025-03-12T14:59:32","date_gmt":"2025-03-12T19:59:32","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/"},"modified":"2025-03-12T14:59:32","modified_gmt":"2025-03-12T19:59:32","slug":"la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/","title":{"rendered":"La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia"},"content":{"rendered":"<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><span style=\"line-height:107%\">Mientras estamos pensando en la primavera y el verano y los meses m\u00e1s c\u00e1lidos, \u00bfqu\u00e9 es m\u00e1s alegre que una fiesta de bloque de vecindario? \u00bfQu\u00e9 tal una fiesta de bloques de vecindario con una oportunidad de compartir a Jes\u00fas con sus amigos y vecinos? Encuentre un parque del vecindario, patio o incluso un camino, y podemos suministrar todas las ideas para historias de la Biblia, juegos, artesan\u00edas, bocadillos y diversi\u00f3n. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><span style=\"line-height:107%\">La Escuela B\u00edblica de Vacaciones puede celebrarse en una variedad de configuraciones.&nbsp; No es solo para un establecimiento de la iglesia. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><span style=\"line-height:107%\">Descargue este <a href=\"https:\/\/nazarene.org\/es\/escuela-biblica-de-vacaciones\/\" style=\"color:#0563c1; text-decoration:underline\">curr\u00edculo gratuito de VBS<\/a> y abroche sus cinturones de seguridad mientras va en un viaje incre\u00edble en Starlight Airlines durante cuatro viajes de regreso en el tiempo que transformar\u00e1n su presente y futuro. Los boletos a su destino incluyen verdades b\u00edblicas como \u00abDios me hizo\u00bb, \u00abDios me salva\u00bb, \u00abDios me llama\u00bb y \u00abDios me fortalece\u00bb. Las rotaciones como el Tribunal de Alimentos, The Runway y la Tienda de Recuerdos proporcionan grandes formas de compartir las noticias del amor de Dios con ni\u00f1os y familias de todas las edades. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans Light','Arial',sans-serif;\"><span style=\"line-height:107%\">No necesita un pasaporte o una cuenta de gastos, solo descargar y dejar que comiencen las aventuras.<\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":21824,"menu_order":0,"template":"","ndi-journey-tags":[1056],"class_list":["post-41479","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-vbs-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia\" \/>\n<meta property=\"og:description\" content=\"Mientras estamos pensando en la primavera y el verano y los meses m\u00e1s c\u00e1lidos, \u00bfqu\u00e9 es m\u00e1s alegre que una fiesta de bloque de vecindario? \u00bfQu\u00e9 tal una fiesta de bloques de vecindario con una oportunidad de compartir a Jes\u00fas con sus amigos y vecinos? Encuentre un parque del vecindario, patio o incluso un camino, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\\\/\",\"name\":\"La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Social-Post-1-scaled.jpg\",\"datePublished\":\"2025-03-12T19:59:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Social-Post-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Social-Post-1-scaled.jpg\",\"width\":2048,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/","og_locale":"es_ES","og_type":"article","og_title":"La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia","og_description":"Mientras estamos pensando en la primavera y el verano y los meses m\u00e1s c\u00e1lidos, \u00bfqu\u00e9 es m\u00e1s alegre que una fiesta de bloque de vecindario? \u00bfQu\u00e9 tal una fiesta de bloques de vecindario con una oportunidad de compartir a Jes\u00fas con sus amigos y vecinos? Encuentre un parque del vecindario, patio o incluso un camino, [&hellip;]","og_url":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/","url":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/","name":"La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Social-Post-1-scaled.jpg","datePublished":"2025-03-12T19:59:32+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Social-Post-1-scaled.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2025\/03\/Social-Post-1-scaled.jpg","width":2048,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/la-escuela-biblica-de-vacaciones-no-es-solo-para-una-configuracion-de-la-iglesia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/es\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"La Escuela B\u00edblica de vacaciones no es solo para una configuraci\u00f3n de la iglesia"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/41479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/41479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/21824"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=41479"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey-tags?post=41479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}