{"id":41362,"date":"2024-11-15T10:11:51","date_gmt":"2024-11-15T16:11:51","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/vbs-adventures\/"},"modified":"2024-11-15T10:11:51","modified_gmt":"2024-11-15T16:11:51","slug":"vbs-adventures","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/","title":{"rendered":"VBS Adventures"},"content":{"rendered":"<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">Agarra una toalla; algunos de nosotros todav\u00eda estamos h\u00famedos. Si experiment\u00f3 la Aventura de Rafting de la Escuela <i>B\u00edblica de Vacaciones<\/i>, entonces todav\u00eda puede estar sec\u00e1ndose tambi\u00e9n. La aventura del verano de 2024 fue una de las mejores. Incluy\u00f3 seguir a dos amigos, Bobby y Sammy, mientras se aventuraban en un viaje m\u00e1s emocionante a trav\u00e9s de los r\u00e1pidos. Historias de Campfire, puntos de picnic, juegos r\u00e1pidos rugentes y artesan\u00edas del campamento llenaron este curr\u00edculo con muchas oportunidades para que los ni\u00f1os y ayudantes experimenten el amor de Jes\u00fas de nuevas maneras.&nbsp; <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">Los vers\u00edculos de memoria, los puntos clave y cavar a trav\u00e9s del libro de Hechos nos llevaron a nuevas verdades sobre el poder de Dios. Bobby y Sammy usaron remos para ayudar a navegar los r\u00e1pidos, y los estudiantes usaron remos para aprender puntos de la Biblia, como \u00abDios nos llena de su amor\u00bb, \u00abDios nos transforma con su amor\u00bb, \u00abDios nos salva con su amor\u00bb y \u00abDios quiere que compartamos su amor\u00bb. Los estudiantes memorizaron las buenas noticias de Hechos 2:21: \u00abTodos los que llaman el nombre del Se\u00f1or ser\u00e1n salvados\u00bb. <\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">Y hay m\u00e1s buenas noticias. Este curr\u00edculo es gratis para que descargue y puede usarse para cualquier reuni\u00f3n, no solo la Escuela B\u00edblica de Vacaciones. Yendo junto con el curr\u00edculo de cuestionarios de los ni\u00f1os durante este a\u00f1o, puedes agarrar tu balsa y usar esta para la escuela dominical o clases de grupos peque\u00f1os, los mi\u00e9rcoles por la noche o la iglesia de ni\u00f1os. Solo no te olvides de empacar tu toalla.<\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-size:14px;\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"line-height:107%\">Compru\u00e9balo en <a href=\"https:\/\/nazarene.org\/es\/escuela-biblica-de-vacaciones\/\" style=\"color:#0563c1; text-decoration:underline\">https:\/\/nazarene.org\/vbs<\/a> <\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":22590,"menu_order":0,"template":"","ndi-journey-tags":[1236],"class_list":["post-41362","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-vbs-2025-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>VBS Adventures - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VBS Adventures\" \/>\n<meta property=\"og:description\" content=\"Agarra una toalla; algunos de nosotros todav\u00eda estamos h\u00famedos. Si experiment\u00f3 la Aventura de Rafting de la Escuela B\u00edblica de Vacaciones, entonces todav\u00eda puede estar sec\u00e1ndose tambi\u00e9n. La aventura del verano de 2024 fue una de las mejores. Incluy\u00f3 seguir a dos amigos, Bobby y Sammy, mientras se aventuraban en un viaje m\u00e1s emocionante a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/vbs-adventures\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/vbs-adventures\\\/\",\"name\":\"VBS Adventures - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/vbs-adventures\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/vbs-adventures\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/General-Ad_Portrait_Design-1.jpg\",\"datePublished\":\"2024-11-15T16:11:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/vbs-adventures\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/vbs-adventures\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/vbs-adventures\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/General-Ad_Portrait_Design-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/General-Ad_Portrait_Design-1.jpg\",\"width\":6667,\"height\":8333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/vbs-adventures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VBS Adventures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"VBS Adventures - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/","og_locale":"es_ES","og_type":"article","og_title":"VBS Adventures","og_description":"Agarra una toalla; algunos de nosotros todav\u00eda estamos h\u00famedos. Si experiment\u00f3 la Aventura de Rafting de la Escuela B\u00edblica de Vacaciones, entonces todav\u00eda puede estar sec\u00e1ndose tambi\u00e9n. La aventura del verano de 2024 fue una de las mejores. Incluy\u00f3 seguir a dos amigos, Bobby y Sammy, mientras se aventuraban en un viaje m\u00e1s emocionante a [&hellip;]","og_url":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/","url":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/","name":"VBS Adventures - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/11\/General-Ad_Portrait_Design-1.jpg","datePublished":"2024-11-15T16:11:51+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/11\/General-Ad_Portrait_Design-1.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/11\/General-Ad_Portrait_Design-1.jpg","width":6667,"height":8333},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/vbs-adventures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/es\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"VBS Adventures"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/41362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/41362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/22590"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=41362"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey-tags?post=41362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}