{"id":41358,"date":"2024-11-15T09:22:10","date_gmt":"2024-11-15T15:22:10","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/"},"modified":"2024-11-15T09:22:10","modified_gmt":"2024-11-15T15:22:10","slug":"tradiciones-unicas-de-accion-de-gracias","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/","title":{"rendered":"Tradiciones \u00fanicas de Acci\u00f3n de Gracias"},"content":{"rendered":"<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:14px;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">Si bien todos tenemos nuestras propias tradiciones \u00fanicas de Acci\u00f3n de Gracias, creo que la mayor\u00eda de nuestras celebraciones tienen mucho en com\u00fan. Reunir a la familia y los amigos, participando en una gran comida, compartiendo lo que estamos agradecidos, y tal vez incluso un poco de f\u00fatbol. <\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:14px;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">En mi hogar, despu\u00e9s de que hemos comido nuestra comida, vamos alrededor de la mesa y damos a cada persona la oportunidad de compartir lo que est\u00e1n agradecidos. Esto es bueno, pero para el creyente hay un elemento importante para la celebraci\u00f3n que no debe dejarse fuera. La mayor\u00eda de todos est\u00e1n felices de compartir el <b>tema<\/b> de sus agradecimientos, que es, por lo que est\u00e1n agradecidos. Pero con demasiada frecuencia, el <b>objeto<\/b> de nuestros agradecimientos se asume o se deja fuera. Como creyentes, nunca debemos fallar en recordar a qui\u00e9n estamos agradecidos. <\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:14px;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">El Salm106:1 dice, \u00abAlabar al Se\u00f1or. Da gracias al Se\u00f1or, porque es bueno; su amor perdura para siempre\u00bb. El salmista no solo nos recuerda que Dios es el objeto correcto de nuestros agradecimientos sino que las gracias y la alabanza van de la mano. Damos alabanza a Dios y damos gracias a Dios. Son dos aspectos de nuestra gratitud a Dios, que es, la adoraci\u00f3n. Verdaderamente, las vacaciones de Acci\u00f3n de Gracias son solo unas vacaciones cristianas como la Navidad y la Pascua. <\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:14px;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">Una b\u00fasqueda simple de la palabra \u00abgracias\u00bb en la Biblia de NIV resulta en 100 \u00abgolpes\u00bb con un equilibrio sorprendentemente cercano entre el Antiguo Testamento (45) y el Nuevo Testamento (55). Como un pueblo con la misi\u00f3n de ser y hacer disc\u00edpulos como Cristo, debemos cultivar la virtud de la acci\u00f3n de gracias. Para nosotros, es m\u00e1s que unas vacaciones para celebrarse una vez al a\u00f1o; es un atributo estar tejido en el mismo tejido de nuestro ser. <\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom:11px\"><span style=\"font-family:'Open Sans','Arial',sans-serif;\"><span style=\"font-size:14px;\"><span style=\"line-height:107%\"><span style=\"line-height:107%\">Considere con qu\u00e9 frecuencia Jes\u00fas dio gracias al Padre durante su ministerio terrenal. Ciertamente ten\u00eda el objeto correcto de su acci\u00f3n de gracias. Como deber\u00edamos. As\u00ed que este a\u00f1o mi oraci\u00f3n por nosotros es que nuestras celebraciones de Acci\u00f3n de Gracias sean sobre mucho m\u00e1s que una buena comida. Que nos preocupemos de nombrar correctamente a Dios como el objeto de nuestros agradecimientos. Y que nuestras celebraciones de Acci\u00f3n de Gracias sean realmente una temporada de alabanza a \u00e9l por su bondad y su amor duradero. Para siempre.<\/span><\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":22597,"menu_order":0,"template":"","ndi-journey-tags":[1234],"class_list":["post-41358","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-gratitud-de-accion-de-gracias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tradiciones \u00fanicas de Acci\u00f3n de Gracias - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tradiciones \u00fanicas de Acci\u00f3n de Gracias\" \/>\n<meta property=\"og:description\" content=\"Si bien todos tenemos nuestras propias tradiciones \u00fanicas de Acci\u00f3n de Gracias, creo que la mayor\u00eda de nuestras celebraciones tienen mucho en com\u00fan. Reunir a la familia y los amigos, participando en una gran comida, compartiendo lo que estamos agradecidos, y tal vez incluso un poco de f\u00fatbol. En mi hogar, despu\u00e9s de que hemos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/tradiciones-unicas-de-accion-de-gracias\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/tradiciones-unicas-de-accion-de-gracias\\\/\",\"name\":\"Tradiciones \u00fanicas de Acci\u00f3n de Gracias - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/tradiciones-unicas-de-accion-de-gracias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/tradiciones-unicas-de-accion-de-gracias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/95-year-old-father-giving-all-his-thanks-when-it-s-2023-11-27-05-13-10-utc-scaled.jpg\",\"datePublished\":\"2024-11-15T15:22:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/tradiciones-unicas-de-accion-de-gracias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/tradiciones-unicas-de-accion-de-gracias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/tradiciones-unicas-de-accion-de-gracias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/95-year-old-father-giving-all-his-thanks-when-it-s-2023-11-27-05-13-10-utc-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/95-year-old-father-giving-all-his-thanks-when-it-s-2023-11-27-05-13-10-utc-scaled.jpg\",\"width\":2560,\"height\":1460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/tradiciones-unicas-de-accion-de-gracias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tradiciones \u00fanicas de Acci\u00f3n de Gracias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tradiciones \u00fanicas de Acci\u00f3n de Gracias - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/","og_locale":"es_ES","og_type":"article","og_title":"Tradiciones \u00fanicas de Acci\u00f3n de Gracias","og_description":"Si bien todos tenemos nuestras propias tradiciones \u00fanicas de Acci\u00f3n de Gracias, creo que la mayor\u00eda de nuestras celebraciones tienen mucho en com\u00fan. Reunir a la familia y los amigos, participando en una gran comida, compartiendo lo que estamos agradecidos, y tal vez incluso un poco de f\u00fatbol. En mi hogar, despu\u00e9s de que hemos [&hellip;]","og_url":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/","url":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/","name":"Tradiciones \u00fanicas de Acci\u00f3n de Gracias - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/11\/95-year-old-father-giving-all-his-thanks-when-it-s-2023-11-27-05-13-10-utc-scaled.jpg","datePublished":"2024-11-15T15:22:10+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/11\/95-year-old-father-giving-all-his-thanks-when-it-s-2023-11-27-05-13-10-utc-scaled.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/11\/95-year-old-father-giving-all-his-thanks-when-it-s-2023-11-27-05-13-10-utc-scaled.jpg","width":2560,"height":1460},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/tradiciones-unicas-de-accion-de-gracias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/es\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"Tradiciones \u00fanicas de Acci\u00f3n de Gracias"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/41358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/41358\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/22597"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=41358"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey-tags?post=41358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}