{"id":40931,"date":"2022-05-17T09:45:54","date_gmt":"2022-05-17T14:45:54","guid":{"rendered":"https:\/\/nazarene.org\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/"},"modified":"2022-05-17T09:45:54","modified_gmt":"2022-05-17T14:45:54","slug":"pascua-avanzar-en-nuestro-viaje-con-dios","status":"publish","type":"ndi-journey","link":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/","title":{"rendered":"Pascua &#8211; Avanzar en nuestro viaje con Dios"},"content":{"rendered":"<p>Este a\u00f1o, el mi\u00e9rcoles de Ash fue el 2 de marzo, marcando el comienzo de la Cuaresma en el calendario cristiano. Su origen es de una pr\u00e1ctica del octavo siglo de marcar las frentes de los cristianos con cenizas. A veces las cenizas se obtuvieron quemando las ramas de palma del Domingo de Palmas anterior. Esta pr\u00e1ctica tambi\u00e9n est\u00e1 enraizada en la pr\u00e1ctica del Antiguo Testamento de usar ceniza como un signo de penitencia y luto.<\/p>\n<p>\nMientras reflexionamos en los eventos que llevaron al primer Viernes Santo, reflexionemos tambi\u00e9n en la invitaci\u00f3n de Jes\u00fas a \u00abVen\u00bb (Juan 1:39). La vida cristiana es una invitaci\u00f3n a viajar con Jes\u00fas, que es \u00abel camino y la verdad y la vida\u00bb (Juan 14:6). Mientras viajamos con Jes\u00fas, experimentamos la incre\u00edble gracia de Dios. Cuando caminamos con Jes\u00fas, viene a nuestras vidas. Nos afecta. Nos cambia. Nos empodera a vivir vidas como Cristo.<\/p>\n<p>\n<strong>Jes\u00fas es el Camino.&nbsp;<\/strong><br \/>\nMientras esperamos el Viernes Santo y la Pascua, dejemos que consideremos nuestros pecados personales y los de nuestra sociedad. &nbsp;Recordemos la misi\u00f3n de Jes\u00fas. Vino a buscar y salvar a los perdidos\u00bb (Lucas 19:10). Una vez que est\u00e1bamos perdidos, y vivimos en un mundo lleno de personas perdidas. Sin embargo, como destinatarios de la gracia salvadora de Dios, no solo estemos agradecidos por la salvaci\u00f3n que Jes\u00fas nos trajo, sino que tambi\u00e9n encontremos formas de compartir las buenas noticias con otros cuyo viaje de la gracia se intersecta con el nuestro. Quiz\u00e1s podamos ayudar a traer a otros a Jes\u00fas como algunos amigos lo hicieron al paral\u00edtico en Lucas 5:17-26.<\/p>\n<p>\n<strong>Jes\u00fas es la Verdad.&nbsp;<\/strong><br \/>\nReflexionemos tambi\u00e9n en la gracia salvadora de Dios. La Biblia se\u00f1ala que \u00ablos salarios del pecado es la muerte\u00bb, pero \u00abDios no quiere que nadie perezca\u00bb. Entonces, leemos \u00abel regalo gratuito de Dios es la vida eterna en Cristo Jes\u00fas nuestro Se\u00f1or\u00bb (Romanos 6:23). Cuando nos arrepentimos de nuestros pecados y ponemos nuestra fe en Jes\u00fas como nuestro Salvador, nos convertimos en libres de los brazos del pecado porque Jes\u00fas es la verdad que nos libera del pecado (Juan 8:32). Durante la Cuaresma, muchos cristianos participan en algunas formas de autodenegaci\u00f3n para recordarse el \u00faltimo sacrificio de Jes\u00fas. Algunas personas se niegan comida durante ciertos per\u00edodos mientras que se comprometen m\u00e1s tiempo orando por su propio desarrollo espiritual y por la salvaci\u00f3n de otros. \u00bfQu\u00e9 estar\u00eda dispuesto a negarse a s\u00ed mismo a continuar su caminata con Jes\u00fas? \u00bfEst\u00e1 dispuesto a ofrecer parte de su tiempo y recursos para ayudar a otros en su viaje con Jes\u00fas?<\/p>\n<p>\n<strong>Jes\u00fas es la Vida.<\/strong><br \/>\nDios quiere que experimentemos Su gracia santificante mediante la cual el Esp\u00edritu Santo nos empodera a vivir una vida completamente consagrada a Dios. Paul or\u00f3 por los creyentes tesalonicenses: \u00abQue el Dios de la paz lo santifique por completo; y que su esp\u00edritu y alma y cuerpo se mantengan sanos e irreprochables en la venida de nuestro Se\u00f1or Jesucristo. El que lo llama es fiel, y har\u00e1 esto\u00bb (1 Tesalonicenses 5:23-24). Oremos para que otros experimenten la santificaci\u00f3n de Dios, que libera a los cristianos del pecado original y los trae a un estado de toda la devoci\u00f3n a Dios. Es en esta experiencia que los cristianos encuentran su mayor alegr\u00eda del viaje.<\/p>\n<p>\n<strong>Dios proporciona la gracia sostenida.<\/strong><br \/>\nAhora a Aquel que es capaz de mantenerte de caer, y hacerte pararte sin mancha en la presencia de Su gloria con regocijarse, al \u00fanico Dios nuestro Salvador, a trav\u00e9s de Jesucristo nuestro Se\u00f1or, sea gloria &#8230;\u00bb (Jude 1:24-25). Mantener la gracia requiere nuestra participaci\u00f3n. Debemos cooperar con el reordenamiento de Dios de nuestras vidas alrededor de las actividades, disciplinas y pr\u00e1cticas que Jes\u00fas model\u00f3. El viaje de la gracia implica la transformaci\u00f3n de toda la persona. A trav\u00e9s de sostener la gracia, el Esp\u00edritu Santo coopera con nosotros para permitir una vida fiel y disciplinada dada en el servicio a Dios. Busquemos la gracia de Dios tanto para el perd\u00f3n de nuestros pecados como el poder de vivir vidas que honran a Dios.<\/p>\n<p>\n<strong>La gracia de Dios es suficiente.<\/strong><br \/>\nReflexionemos tambi\u00e9n en la gracia suficiente de Dios, a trav\u00e9s de la cual el poder de Dios se hace perfecto en nuestra debilidad. Cuando Paul estaba luchando, Dios le record\u00f3, \u00abMi gracia es suficiente para ti, porque mi poder se hace perfecto en la debilidad\u00bb (2 Corintios 12:9). A veces en nuestro viaje con Jes\u00fas, venimos al \u00abfinal\u00bb de nuestros recursos humanos. Eso es cuando Dios dice: \u00abTe estoy ofreciendo fuerza sobrenatural. Cuando tu energ\u00eda se agote, mi energ\u00eda se har\u00e1 viva en ti. Cuando no puedes ir m\u00e1s lejos, te recoger\u00e9 y te llevar\u00e9. Descansar en mis brazos durante un tiempo (David Busic, Way, Verdad, Life, 2021). Confiemos en la gracia sostenedora de Dios.<\/p>\n<p>\n<strong>Jes\u00fas es triunfante.<\/strong><br \/>\nEl domingo de Palmas, celebraremos la entrada triunfal de Jes\u00fas en Jerusal\u00e9n. Mientras montaba un burro a Jerusal\u00e9n, fue recibido por muchas personas que estaban llenas de alegr\u00eda y felicidad. Hubo una gran celebraci\u00f3n en las calles de Jerusal\u00e9n. Las personas adornaron el camino con sus mantos y ramas de palma para el Rey Jes\u00fas mientras cabalgaba en el burro. Lucas 19:37 nos da la raz\u00f3n de esta reacci\u00f3n: alabar a Dios con voces fuertes \u00abpor todas las maravillas que hab\u00edan visto\u00bb. Hab\u00eda personas que hab\u00edan conocido a Jes\u00fas y caminaron con \u00c9l. Las personas hab\u00edan visto Sus milagros como la multiplicaci\u00f3n del pescado y el pan, sanar a los enfermos, expulsar demonios y el perd\u00f3n de los pecados. Las personas hab\u00edan visto y experimentado c\u00f3mo Jes\u00fas cambi\u00f3 vidas. Todav\u00eda est\u00e1 triunfando y cambiando vidas hoy. \u00a1Aseg\u00farese de compartir estas buenas noticias con otros!<\/p>\n<p>\n<strong>Jes\u00fas era el Siervo que sufr\u00eda.<\/strong><br \/>\nCada uno de los cuatro Evangelios relacionan algunos eventos que llevan al Viernes Santo (Mateo 26:17-30; Marcos 14:17-21; Lucas 22:14-23 y Juan 13:1-11). Gran parte del jueves fue en la preparaci\u00f3n de la comida de Pascua de la noche con Jes\u00fas y Sus disc\u00edpulos. Durante la comida, Jes\u00fas revel\u00f3 que Judas Iscariot lo traicionar\u00eda y que los otros disc\u00edpulos estar\u00edan dispersos. Jes\u00fas tambi\u00e9n dio un nuevo significado al pan y la vid, representando Su cuerpo roto y sangre derramada. Esta se llama la \u00daltima Cena o la Cena del Se\u00f1or, que se ha convertido en una forma duradera de recordar cu\u00e1nto Jes\u00fas sufri\u00f3 por nuestra salvaci\u00f3n. En alg\u00fan momento durante esta comida, Jes\u00fas tambi\u00e9n sirvi\u00f3 a Sus disc\u00edpulos lavando sus pies. Despu\u00e9s de la comida, Judas fue a los l\u00edderes jud\u00edos y traicion\u00f3 a Jes\u00fas. Jes\u00fas y los otros disc\u00edpulos fueron al jard\u00edn de Gethsemane a orar. Fue all\u00ed que Judas lider\u00f3 a un grupo armado a arrestar a Jes\u00fas. Lo llevaron a ser condenado a la muerte por romanos y l\u00edderes jud\u00edos. No olvidemos c\u00f3mo Jes\u00fas se convirti\u00f3 en nuestro Siervo de Sufrimiento.<\/p>\n<p>\n<strong>Viernes Santo<\/strong><br \/>\nViernes Santo es un d\u00eda de devoci\u00f3n y oraci\u00f3n entre muchos cristianos. Viernes Santo tambi\u00e9n es un d\u00eda festivo en algunos pa\u00edses. Conmemora la crucifixi\u00f3n y la muerte de Jesucristo mientras recordamos los sacrificios y el sufrimiento en la vida de Jes\u00fas. Muchos cristianos asisten a servicios especiales de adoraci\u00f3n del Viernes Santo. Algunos servicios tienen lugar aproximadamente las 3:00 p.m. ya que esto simboliza el tiempo que Jesucristo muri\u00f3 en la cruz. Juan 19:25-27 registra que \u00abEstar cerca de la cruz de Jes\u00fas fueron su madre, la hermana de su madre, Mar\u00eda la esposa de Clopas y Mar\u00eda Magdalena. Jes\u00fas vio a su madre y el disc\u00edpulo que amaba de pie all\u00ed; por lo que dijo a su madre, &#8216;Es tu hijo&#8217;. Luego dijo al disc\u00edpulo, &#8216;Es tu madre&#8217;. De ese tiempo el disc\u00edpulo la llev\u00f3 a vivir en su hogar. Encontremos formas de pasar a otros la bondad que Cristo ha tra\u00eddo a nuestras vidas.<\/p>\n<p>\n<strong>Jesucristo est\u00e1 vivo.<\/strong><br \/>\nEl domingo de Pascua, celebraremos la resurrecci\u00f3n de Jesucristo. El domingo de Pascua es un tiempo de regocijarse porque Jes\u00fas se levant\u00f3 de la tumba. Jes\u00fas es \u00abla resurrecci\u00f3n y la vida\u00bb (Juan 11:25). Su resurrecci\u00f3n es la fuente de esperanza para los cristianos para nuestra propia resurrecci\u00f3n en la Segunda Venida. Esto es cuando todos los creyentes son levantados a una nueva vida para vivir en la presencia eterna de Dios. Leemos en Juan 20:1-2 que \u00abTemprano el domingo por la ma\u00f1ana, mientras todav\u00eda estaba oscuro, Mar\u00eda Magdalena fue a la tumba y vio que la piedra hab\u00eda sido llevada de la entrada. Fue corriendo a Sim\u00f3n Pedro y el otro disc\u00edpulo, a quien Jes\u00fas amaba, y les dijo &#8230;\u00bb<\/p>\n<p>\n\u00bfCon qui\u00e9n puedes compartir las buenas noticias de Pascua este a\u00f1o?<\/p>\n","protected":false},"featured_media":23544,"menu_order":0,"template":"","ndi-journey-tags":[1004,1003],"class_list":["post-40931","ndi-journey","type-ndi-journey","status-publish","has-post-thumbnail","hentry","ndi-journey-tags-moverse-hacia-adelante","ndi-journey-tags-pascua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pascua - Avanzar en nuestro viaje con Dios - Church of the Nazarene<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pascua - Avanzar en nuestro viaje con Dios\" \/>\n<meta property=\"og:description\" content=\"Este a\u00f1o, el mi\u00e9rcoles de Ash fue el 2 de marzo, marcando el comienzo de la Cuaresma en el calendario cristiano. Su origen es de una pr\u00e1ctica del octavo siglo de marcar las frentes de los cristianos con cenizas. A veces las cenizas se obtuvieron quemando las ramas de palma del Domingo de Palmas anterior. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/\" \/>\n<meta property=\"og:site_name\" content=\"Church of the Nazarene\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NazareneOfficial\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Nazarene\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/pascua-avanzar-en-nuestro-viaje-con-dios\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/pascua-avanzar-en-nuestro-viaje-con-dios\\\/\",\"name\":\"Pascua - Avanzar en nuestro viaje con Dios - Church of the Nazarene\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/pascua-avanzar-en-nuestro-viaje-con-dios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/pascua-avanzar-en-nuestro-viaje-con-dios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/18.jpg\",\"datePublished\":\"2022-05-17T14:45:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/pascua-avanzar-en-nuestro-viaje-con-dios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/pascua-avanzar-en-nuestro-viaje-con-dios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/pascua-avanzar-en-nuestro-viaje-con-dios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/18.jpg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/18.jpg\",\"width\":1320,\"height\":880},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/pascua-avanzar-en-nuestro-viaje-con-dios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NDI Journey\",\"item\":\"https:\\\/\\\/nazarene.org\\\/es\\\/ndi-journey\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pascua &#8211; Avanzar en nuestro viaje con Dios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"name\":\"Church of the Nazarene\",\"description\":\"Making Christlike Disciples in the Nations\",\"publisher\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nazarene.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#organization\",\"name\":\"Church of the Nazarene\",\"url\":\"https:\\\/\\\/nazarene.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"contentUrl\":\"https:\\\/\\\/nazarene.org\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Naz_Desktop_Black_Logo-1.svg\",\"width\":258,\"height\":36,\"caption\":\"Church of the Nazarene\"},\"image\":{\"@id\":\"https:\\\/\\\/nazarene.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/NazareneOfficial\\\/\",\"https:\\\/\\\/x.com\\\/Nazarene\",\"https:\\\/\\\/www.instagram.com\\\/nazareneofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pascua - Avanzar en nuestro viaje con Dios - Church of the Nazarene","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/","og_locale":"es_ES","og_type":"article","og_title":"Pascua - Avanzar en nuestro viaje con Dios","og_description":"Este a\u00f1o, el mi\u00e9rcoles de Ash fue el 2 de marzo, marcando el comienzo de la Cuaresma en el calendario cristiano. Su origen es de una pr\u00e1ctica del octavo siglo de marcar las frentes de los cristianos con cenizas. A veces las cenizas se obtuvieron quemando las ramas de palma del Domingo de Palmas anterior. [&hellip;]","og_url":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/","og_site_name":"Church of the Nazarene","article_publisher":"https:\/\/www.facebook.com\/NazareneOfficial\/","twitter_card":"summary_large_image","twitter_site":"@Nazarene","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/","url":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/","name":"Pascua - Avanzar en nuestro viaje con Dios - Church of the Nazarene","isPartOf":{"@id":"https:\/\/nazarene.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/#primaryimage"},"image":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/#primaryimage"},"thumbnailUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2022\/05\/18.jpg","datePublished":"2022-05-17T14:45:54+00:00","breadcrumb":{"@id":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/#primaryimage","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2022\/05\/18.jpg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2022\/05\/18.jpg","width":1320,"height":880},{"@type":"BreadcrumbList","@id":"https:\/\/nazarene.org\/es\/ndi-journey\/pascua-avanzar-en-nuestro-viaje-con-dios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nazarene.org\/es\/inicio\/"},{"@type":"ListItem","position":2,"name":"NDI Journey","item":"https:\/\/nazarene.org\/es\/ndi-journey\/"},{"@type":"ListItem","position":3,"name":"Pascua &#8211; Avanzar en nuestro viaje con Dios"}]},{"@type":"WebSite","@id":"https:\/\/nazarene.org\/es\/#website","url":"https:\/\/nazarene.org\/es\/","name":"Church of the Nazarene","description":"Making Christlike Disciples in the Nations","publisher":{"@id":"https:\/\/nazarene.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nazarene.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/nazarene.org\/es\/#organization","name":"Church of the Nazarene","url":"https:\/\/nazarene.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","contentUrl":"https:\/\/nazarene.org\/wp-content\/uploads\/2024\/06\/Naz_Desktop_Black_Logo-1.svg","width":258,"height":36,"caption":"Church of the Nazarene"},"image":{"@id":"https:\/\/nazarene.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/NazareneOfficial\/","https:\/\/x.com\/Nazarene","https:\/\/www.instagram.com\/nazareneofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/40931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey"}],"about":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/types\/ndi-journey"}],"version-history":[{"count":0,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey\/40931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media\/23544"}],"wp:attachment":[{"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/media?parent=40931"}],"wp:term":[{"taxonomy":"ndi-journey-tags","embeddable":true,"href":"https:\/\/nazarene.org\/es\/wp-json\/wp\/v2\/ndi-journey-tags?post=40931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}